{"id":2409,"date":"2022-03-29T10:41:07","date_gmt":"2022-03-29T10:41:07","guid":{"rendered":"https:\/\/blog.colmena.media\/home\/"},"modified":"2024-05-27T19:04:15","modified_gmt":"2024-05-27T19:04:15","slug":"home","status":"publish","type":"page","link":"https:\/\/blog.colmena.media\/ar\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2409\" class=\"elementor elementor-2409 elementor-11\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-dce-background-overlay-color=\"#4C517F\" data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/\/P1_3-3-2.svg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f8b3abb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8b3abb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fe784d\" data-id=\"3fe784d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e2c8b49 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2c8b49\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:25,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3629e1a\" data-id=\"3629e1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-067d673 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"067d673\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/LogoColmena_color.svg\" class=\"attachment-large size-large wp-image-284\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c754427\" data-id=\"c754427\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db4aa1 elementor-nav-menu__align-left elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"4db4aa1\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-4db4aa1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2059\"><a href=\"\/ar\/#about\" class=\"elementor-item elementor-item-anchor\">\u062d\u0648\u0644<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2060\"><a href=\"\/ar\/#features\" class=\"elementor-item elementor-item-anchor\">\u0627\u0644\u0645\u064a\u0632\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2062\"><a href=\"\/ar\/#publications\" class=\"elementor-item elementor-item-anchor\">\u0627\u0644\u0645\u0646\u0634\u0648\u0631\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5863\"><a href=\"\/ar\/#consortium\" class=\"elementor-item elementor-item-anchor\">\u0627\u0644\u062a\u062d\u0627\u0644\u0641<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5864\"><a href=\"https:\/\/docs.colmena.media\/\" class=\"elementor-item\">\u062a\u0648\u062b\u064a\u0642<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5865\"><a href=\"https:\/\/gitlab.com\/colmena-project\/\" class=\"elementor-item\">\u0634\u0641\u0631\u0629<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-4db4aa1\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2059\"><a href=\"\/ar\/#about\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u062d\u0648\u0644<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2060\"><a href=\"\/ar\/#features\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u0627\u0644\u0645\u064a\u0632\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2062\"><a href=\"\/ar\/#publications\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u0627\u0644\u0645\u0646\u0634\u0648\u0631\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5863\"><a href=\"\/ar\/#consortium\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u0627\u0644\u062a\u062d\u0627\u0644\u0641<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5864\"><a href=\"https:\/\/docs.colmena.media\/\" class=\"elementor-item\" tabindex=\"-1\">\u062a\u0648\u062b\u064a\u0642<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5865\"><a href=\"https:\/\/gitlab.com\/colmena-project\/\" class=\"elementor-item\" tabindex=\"-1\">\u0634\u0641\u0631\u0629<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d8e4e26\" data-id=\"d8e4e26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0fb72a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fb72a5\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-792f559\" data-id=\"792f559\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"dce-visibility-element-hidden dce-visibility-original-content elementor-element elementor-element-39022d0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"39022d0\" data-element_type=\"widget\" data-settings=\"{&quot;enabled_visibility&quot;:&quot;yes&quot;,&quot;dce_visibility_event&quot;:&quot;click&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/colmena.media\/login\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u062a\u0633\u062c\u064a\u0644 \u062f\u062e\u0648\u0644<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2667bca\" data-id=\"2667bca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e597a7f elementor-widget__width-initial elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"e597a7f\" data-element_type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpml-elementor-ls\">\n<div\n\t class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-rtl wpml-ls-legacy-dropdown js-wpml-ls-legacy-dropdown\">\n\t<ul>\n\n\t\t<li tabindex=\"0\" class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-ar wpml-ls-current-language wpml-ls-item-legacy-dropdown\">\n\t\t\t<a href=\"#\" class=\"js-wpml-ls-item-toggle wpml-ls-item-toggle\">\n                <span class=\"wpml-ls-native\">\u0627\u0644\u0639\u0631\u0628\u064a\u0629<\/span><\/a>\n\n\t\t\t<ul class=\"wpml-ls-sub-menu\">\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"en\">English<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/es\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"es\">Espa\u00f1ol<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-br\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/pt-br\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"pt-br\">Portugu\u00eas<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/fr\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"fr\">Fran\u00e7ais<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-kw wpml-ls-last-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/kw\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"kw\">Kiswahili<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/li>\n\n\t<\/ul>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dc000cb elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc000cb\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8f90f3b\" data-id=\"8f90f3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25b79b8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"25b79b8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/colmena.media\/login\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u062a\u0633\u062c\u064a\u0644 \u062f\u062e\u0648\u0644<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3bddf88\" data-id=\"3bddf88\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3c2a2c elementor-widget elementor-widget-wpml-language-switcher\" data-id=\"d3c2a2c\" data-element_type=\"widget\" data-widget_type=\"wpml-language-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"wpml-elementor-ls\">\n<div\n\t class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-rtl wpml-ls-legacy-dropdown js-wpml-ls-legacy-dropdown\">\n\t<ul>\n\n\t\t<li tabindex=\"0\" class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-ar wpml-ls-current-language wpml-ls-item-legacy-dropdown\">\n\t\t\t<a href=\"#\" class=\"js-wpml-ls-item-toggle wpml-ls-item-toggle\">\n                <span class=\"wpml-ls-native\">\u0627\u0644\u0639\u0631\u0628\u064a\u0629<\/span><\/a>\n\n\t\t\t<ul class=\"wpml-ls-sub-menu\">\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-first-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"en\">English<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/es\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"es\">Espa\u00f1ol<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-pt-br\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/pt-br\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"pt-br\">Portugu\u00eas<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-fr\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/fr\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"fr\">Fran\u00e7ais<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-kw wpml-ls-last-item\">\n\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/kw\/\" class=\"wpml-ls-link\">\n                            <span class=\"wpml-ls-native\" lang=\"kw\">Kiswahili<\/span><\/a>\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t<\/li>\n\n\t<\/ul>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-30267e0 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30267e0\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-69abd65\" data-id=\"69abd65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44b648e dce_masking-none elementor-widget elementor-widget-image\" data-id=\"44b648e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/ar\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/LogoColmena_color.svg\" class=\"attachment-large size-large wp-image-284\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2cf234b\" data-id=\"2cf234b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb33b8 elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"5eb33b8\" data-element_type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-5eb33b8\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2059\"><a href=\"\/ar\/#about\" class=\"elementor-item elementor-item-anchor\">\u062d\u0648\u0644<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2060\"><a href=\"\/ar\/#features\" class=\"elementor-item elementor-item-anchor\">\u0627\u0644\u0645\u064a\u0632\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2062\"><a href=\"\/ar\/#publications\" class=\"elementor-item elementor-item-anchor\">\u0627\u0644\u0645\u0646\u0634\u0648\u0631\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5863\"><a href=\"\/ar\/#consortium\" class=\"elementor-item elementor-item-anchor\">\u0627\u0644\u062a\u062d\u0627\u0644\u0641<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5864\"><a href=\"https:\/\/docs.colmena.media\/\" class=\"elementor-item\">\u062a\u0648\u062b\u064a\u0642<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5865\"><a href=\"https:\/\/gitlab.com\/colmena-project\/\" class=\"elementor-item\">\u0634\u0641\u0631\u0629<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5eb33b8\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2059\"><a href=\"\/ar\/#about\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u062d\u0648\u0644<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2060\"><a href=\"\/ar\/#features\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u0627\u0644\u0645\u064a\u0632\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2062\"><a href=\"\/ar\/#publications\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u0627\u0644\u0645\u0646\u0634\u0648\u0631\u0627\u062a<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5863\"><a href=\"\/ar\/#consortium\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">\u0627\u0644\u062a\u062d\u0627\u0644\u0641<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5864\"><a href=\"https:\/\/docs.colmena.media\/\" class=\"elementor-item\" tabindex=\"-1\">\u062a\u0648\u062b\u064a\u0642<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-5865\"><a href=\"https:\/\/gitlab.com\/colmena-project\/\" class=\"elementor-item\" tabindex=\"-1\">\u0634\u0641\u0631\u0629<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d69a6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d69a6d\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7c92d63\" data-id=\"7c92d63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85a3c82 elementor-widget elementor-widget-heading\" data-id=\"85a3c82\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0643\u0646 \u062c\u0632\u0621\u064b\u0627 \u0645\u0646 \u062e\u0644\u064a\u0629 \u0627\u0644\u0646\u062d\u0644<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee19922 elementor-widget elementor-widget-heading\" data-id=\"ee19922\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Colmena \u0647\u0648 \u0635\u0646\u062f\u0648\u0642 \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0644\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u064a \u0627\u0644\u0645\u062d\u0644\u064a \u0648\u0627\u0644\u0645\u062c\u062a\u0645\u0639\u064a. \u0625\u0646\u0647 \u062d\u0644 \u0645\u062c\u0627\u0646\u064a \u0648\u0622\u0645\u0646 \u0648\u0645\u0641\u062a\u0648\u062d \u0627\u0644\u0645\u0635\u062f\u0631 \u0628\u0646\u0633\u0628\u0629 100% \u0644\u0628\u064a\u0626\u0627\u062a \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\u0629 \u0648\u0633\u0637\u062d \u0627\u0644\u0645\u0643\u062a\u0628. \u062a\u062a\u0645 \u0635\u064a\u0627\u0646\u0629 \u0648\u062a\u0637\u0648\u064a\u0631 \u0643\u0648\u0644\u0645\u064a\u0646\u0627 \u0645\u0646 \u0642\u0628\u0644 \u0627\u062a\u062d\u0627\u062f \u063a\u064a\u0631 \u0631\u0628\u062d\u064a \u0645\u0646 \u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u0645\u062c\u062a\u0645\u0639 \u0627\u0644\u0645\u062f\u0646\u064a \u0627\u0644\u0645\u0643\u0631\u0633\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062a\u0639\u0628\u064a\u0631 \u0648\u0627\u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0631\u0642\u0645\u064a\u0629.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e116a3 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"4e116a3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"#join\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0627\u0644\u0627\u0646\u0636\u0645\u0627\u0645 \u0625\u0644\u0649 \u0627\u0644\u0645\u062c\u062a\u0645\u0639!<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-864940f\" data-id=\"864940f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-172a72c elementor-absolute elementor-widget-mobile__width-initial dce_masking-none elementor-invisible elementor-widget elementor-widget-image\" data-id=\"172a72c\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_tilt_effect&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_tilt_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"577\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-577x1024.png\" class=\"attachment-large size-large wp-image-4781\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-577x1024.png 577w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-768x1363.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-866x1536.png 866w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4.png 1082w\" sizes=\"(max-width: 577px) 100vw, 577px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05cf354 elementor-absolute animated-slow elementor-widget-mobile__width-initial dce_masking-none elementor-invisible elementor-widget elementor-widget-image\" data-id=\"05cf354\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.5,&quot;sizes&quot;:[]},&quot;motion_fx_tilt_effect&quot;:&quot;yes&quot;,&quot;motion_fx_tilt_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4.7,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-576x1024.png\" class=\"attachment-large size-large wp-image-4788\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-576x1024.png 576w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-768x1364.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-865x1536.png 865w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final.png 1082w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-overlay-color=\"#4C517F\" data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/\/P1_3-3-2.svg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e11096d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e11096d\" data-element_type=\"section\" id=\"about\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3162820\" data-id=\"3162820\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9bad43 dce_masking-none elementor-widget elementor-widget-video\" data-id=\"f9bad43\" data-element_type=\"widget\" data-settings=\"{&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Captura-de-pantalla-de-2022-04-02-15-13-51.png&quot;,&quot;id&quot;:522,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;hosted&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/archive.org\/download\/dla-21-gki-110-colmena-videographic-en-2022-04\/DLA21-GKI110-Colmena_Videographic_EN_2022-04.mp4\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Captura-de-pantalla-de-2022-04-02-15-13-51.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"\u062a\u0634\u063a\u064a\u0644 \u0627\u0644\u0641\u064a\u062f\u064a\u0648\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">\u062a\u0634\u063a\u064a\u0644 \u0627\u0644\u0641\u064a\u062f\u064a\u0648<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-237fd9a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"237fd9a\" data-element_type=\"section\" id=\"join\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac18fa6\" data-id=\"ac18fa6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfe9ce7 elementor-widget elementor-widget-template\" data-id=\"bfe9ce7\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3594\" class=\"elementor elementor-3594 elementor-1844\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Register_banner.png\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-63460c4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63460c4a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-14c7345f\" data-id=\"14c7345f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a350cc0 elementor-widget elementor-widget-heading\" data-id=\"1a350cc0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u062c\u0627\u0647\u0632 \u0644\u0644\u0627\u0646\u0636\u0645\u0627\u0645\u061f<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-53003b9b\" data-id=\"53003b9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dde650e elementor-widget elementor-widget-toggle\" data-id=\"dde650e\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h5 id=\"elementor-tab-title-2321\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2321\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns:inkscape=\"http:\/\/www.inkscape.org\/namespaces\/inkscape\" xmlns:sodipodi=\"http:\/\/sodipodi.sourceforge.net\/DTD\/sodipodi-0.dtd\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 97.630111 105\" id=\"svg32\" sodipodi:docname=\"IconColmena_marron.svg\" width=\"97.630112\" height=\"105\" inkscape:version=\"1.1.2 (1:1.1+202202050950+0a00cf5339)\"><defs id=\"defs13\"><style id=\"style2\">.cls-1{fill:url(#linear-gradient);}.cls-2{fill:#f29a1f;}<\/style><linearGradient id=\"linear-gradient\" x1=\"40.639999\" y1=\"3750.8601\" x2=\"106.37\" y2=\"3810.04\" gradientTransform=\"matrix(1,0,0,-1,-24.709943,3829.91)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#e05074\" id=\"stop4\"><\/stop><stop offset=\"0.3\" stop-color=\"#ef8342\" id=\"stop6\"><\/stop><stop offset=\"0.66\" stop-color=\"#f9ac1b\" id=\"stop8\"><\/stop><stop offset=\"1\" stop-color=\"#fbc665\" id=\"stop10\"><\/stop><\/linearGradient><\/defs><path class=\"cls-1\" d=\"m 61.690057,100.14 a 4.84,4.84 0 0 1 -4.84,4.86 h -5.16 a 4.84,4.84 0 0 1 0,-9.68 h 5.16 a 4.85,4.85 0 0 1 4.84,4.82 z m -40.07,-47.67 a 4.84,4.84 0 0 0 -4.83,-4.84 H 4.6200568 a 4.84,4.84 0 0 0 0,9.67 H 16.790057 a 4.83,4.83 0 0 0 4.84,-4.82 v 0 z m 71.39,-4.84 h -9.64 v 0 h -9.43 a 3.12,3.12 0 0 1 0,-6.23 h 9.46 v 0 h 2.89 a 4.84,4.84 0 1 0 0.32,-9.67 h -45.32 a 3.1103255,3.1103255 0 0 1 0.09,-6.22 h 32.83 a 4.84,4.84 0 0 0 0,-9.68 h -21.69 a 3.11,3.11 0 0 1 -2.23,-5.25 3,3 0 0 1 2,-0.9 h 9.24 a 4.84,4.84 0 0 0 0,-9.68 h -27.52 a 4.84,4.84 0 1 0 0,9.68 h 2.81 a 3.11,3.11 0 0 1 -0.2,6.21 h -15.13 a 4.8426439,4.8426439 0 0 0 -0.32,9.68 h 4.28 a 3.11,3.11 0 0 1 2.2,5.31 3.15,3.15 0 0 1 -2.12,0.91 h -13.19 a 4.84,4.84 0 0 0 -0.31,9.67 h 46.09 a 3.11,3.11 0 0 1 0,6.22 h -27.36 a 4.84,4.84 0 0 0 -0.31,9.67 h 16.43 a 3.1121255,3.1121255 0 0 1 0.23,6.22 h -31.95 a 4.84,4.84 0 0 0 0,9.67 h 16.38 a 3.1105787,3.1105787 0 0 1 0.12,6.22 h -4.5 a 4.84,4.84 0 0 0 0,9.67 h 41.87 a 4.84,4.84 0 0 0 0,-9.67 h -21.74 a 3.1105787,3.1105787 0 0 1 0.12,-6.22 h 31.11 a 4.84,4.84 0 0 0 0.31,-9.67 h -16.29 a 3.1121255,3.1121255 0 0 1 0.23,-6.22 h 30.24 a 4.84,4.84 0 0 0 0,-9.67 z\" id=\"path15\" style=\"fill:#c27b0b;fill-opacity:1\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns:inkscape=\"http:\/\/www.inkscape.org\/namespaces\/inkscape\" xmlns:sodipodi=\"http:\/\/sodipodi.sourceforge.net\/DTD\/sodipodi-0.dtd\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 97.630111 105\" id=\"svg32\" sodipodi:docname=\"IconColmena_blanco.svg\" width=\"97.630112\" height=\"105\" inkscape:version=\"1.1.2 (1:1.1+202202050950+0a00cf5339)\"><defs id=\"defs13\"><style id=\"style2\">.cls-1{fill:url(#linear-gradient);}.cls-2{fill:#f29a1f;}<\/style><linearGradient id=\"linear-gradient\" x1=\"40.639999\" y1=\"3750.8601\" x2=\"106.37\" y2=\"3810.04\" gradientTransform=\"matrix(1,0,0,-1,-24.709943,3829.91)\" gradientUnits=\"userSpaceOnUse\"><stop offset=\"0\" stop-color=\"#e05074\" id=\"stop4\"><\/stop><stop offset=\"0.3\" stop-color=\"#ef8342\" id=\"stop6\"><\/stop><stop offset=\"0.66\" stop-color=\"#f9ac1b\" id=\"stop8\"><\/stop><stop offset=\"1\" stop-color=\"#fbc665\" id=\"stop10\"><\/stop><\/linearGradient><\/defs><path class=\"cls-1\" d=\"m 61.690057,100.14 a 4.84,4.84 0 0 1 -4.84,4.86 h -5.16 a 4.84,4.84 0 0 1 0,-9.68 h 5.16 a 4.85,4.85 0 0 1 4.84,4.82 z m -40.07,-47.67 a 4.84,4.84 0 0 0 -4.83,-4.84 H 4.6200568 a 4.84,4.84 0 0 0 0,9.67 H 16.790057 a 4.83,4.83 0 0 0 4.84,-4.82 v 0 z m 71.39,-4.84 h -9.64 v 0 h -9.43 a 3.12,3.12 0 0 1 0,-6.23 h 9.46 v 0 h 2.89 a 4.84,4.84 0 1 0 0.32,-9.67 h -45.32 a 3.1103255,3.1103255 0 0 1 0.09,-6.22 h 32.83 a 4.84,4.84 0 0 0 0,-9.68 h -21.69 a 3.11,3.11 0 0 1 -2.23,-5.25 3,3 0 0 1 2,-0.9 h 9.24 a 4.84,4.84 0 0 0 0,-9.68 h -27.52 a 4.84,4.84 0 1 0 0,9.68 h 2.81 a 3.11,3.11 0 0 1 -0.2,6.21 h -15.13 a 4.8426439,4.8426439 0 0 0 -0.32,9.68 h 4.28 a 3.11,3.11 0 0 1 2.2,5.31 3.15,3.15 0 0 1 -2.12,0.91 h -13.19 a 4.84,4.84 0 0 0 -0.31,9.67 h 46.09 a 3.11,3.11 0 0 1 0,6.22 h -27.36 a 4.84,4.84 0 0 0 -0.31,9.67 h 16.43 a 3.1121255,3.1121255 0 0 1 0.23,6.22 h -31.95 a 4.84,4.84 0 0 0 0,9.67 h 16.38 a 3.1105787,3.1105787 0 0 1 0.12,6.22 h -4.5 a 4.84,4.84 0 0 0 0,9.67 h 41.87 a 4.84,4.84 0 0 0 0,-9.67 h -21.74 a 3.1105787,3.1105787 0 0 1 0.12,-6.22 h 31.11 a 4.84,4.84 0 0 0 0.31,-9.67 h -16.29 a 3.1121255,3.1121255 0 0 1 0.23,-6.22 h 30.24 a 4.84,4.84 0 0 0 0,-9.67 z\" id=\"path15\" style=\"fill:#ffffff;fill-opacity:1\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u062a\u0642\u062f\u0645 \u0628\u0637\u0644\u0628 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u062d\u0633\u0627\u0628 Colmena \u0645\u0628\u0627\u0634\u0631\u0629<\/a>\n\t\t\t\t\t<\/h5>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2321\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2321\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"3821\" data-post-id=\"2409\" data-obj-id=\"2409\" class=\"elementor elementor-3821 dce-elementor-post-2409 elementor-3740\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f0c239 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f0c239\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b38ff8\" data-id=\"9b38ff8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0c90f7 elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"f0c90f7\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;dce_confirm_dialog_enabled&quot;:&quot;no&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;label_icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;field_icon_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"\u062a\u0642\u062f\u0645 \u0644\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u062d\u0633\u0627\u0628\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"3821\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"f0c90f7\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u0627\u0633\u0645 \u0627\u0644\u0648\u0633\u0627\u0626\u0637\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_114863f elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_114863f\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u0627\u0633\u0645\u0643\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_114863f]\" id=\"form-field-field_114863f\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u0628\u0631\u064a\u062f \u0627\u0644\u0627\u0644\u0643\u062a\u0631\u0648\u0646\u064a\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_057c174 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_057c174\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u0627\u0644\u0645\u062f\u064a\u0646\u0629 \u0623\u0648 \u0627\u0644\u0645\u062c\u062a\u0645\u0639\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_057c174]\" id=\"form-field-field_057c174\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_b4d4766 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_b4d4766\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u062f\u0648\u0644\u0629\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_b4d4766]\" id=\"form-field-field_b4d4766\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u0623\u062e\u0628\u0631\u0646\u0627 \u0639\u0646 \u0627\u0644\u0648\u0633\u0627\u0626\u0637 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 (\u0646\u0648\u0639 \u0627\u0644\u0648\u0633\u0627\u0626\u0637 \u060c \u0645\u0639 \u0645\u0646 \u064a\u0639\u0645\u0644\u0648\u0646 \u060c \u0645\u0627 \u0647\u064a \u0627\u0644\u0645\u0648\u0636\u0648\u0639\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u063a\u0637\u064a\u0647\u0627 &#8230;).\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-md\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" required=\"required\" aria-required=\"true\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_f864688 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f864688\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u0645\u0627 \u0627\u0644\u0630\u064a \u062a\u0631\u063a\u0628 \u0641\u064a \u0627\u0633\u062a\u062e\u062f\u0627\u0645 Colmena \u0644\u0623\u062c\u0644\u0647\u061f\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-md\" name=\"form_fields[field_f864688]\" id=\"form-field-field_f864688\" rows=\"4\" required=\"required\" aria-required=\"true\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u064a\u0631\u0633\u0644<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<!-- dce invisible element f129ff5 -->\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79b5374 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79b5374\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61e491e features\" data-id=\"61e491e\" data-element_type=\"column\" id=\"features\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77065e1 elementor-widget elementor-widget-heading\" data-id=\"77065e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0645\u0627 \u0643\u0644 \u0647\u0630\u0627 \u0627\u0644\u0639\u0646\u0627\u0621\u061f<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ea04ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ea04ad\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e2cc2cb\" data-id=\"e2cc2cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5be4f10 elementor-widget elementor-widget-text-editor\" data-id=\"5be4f10\" data-element_type=\"widget\" id=\"cuerpo3\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u062a\u062c\u0645\u0639 Colmena \u062c\u0645\u064a\u0639 \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0644\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u064a \u0627\u0644\u0645\u062d\u0644\u064a \u0648\u0627\u0644\u0645\u062c\u062a\u0645\u0639\u064a \u0627\u0644\u0645\u0631\u0646 \u0641\u064a \u062a\u0637\u0628\u064a\u0642 \u0648\u0627\u062d\u062f \u0641\u0642\u0637. \u0628\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0628\u0631\u0646\u0627\u0645\u062c\u0646\u0627 \u0627\u0644\u0645\u062c\u0627\u0646\u064a \u0645\u0641\u062a\u0648\u062d \u0627\u0644\u0645\u0635\u062f\u0631\u060c \u064a\u0645\u0643\u0646\u0643: \u0627\u0644\u062a\u0633\u062c\u064a\u0644 \u0648\u0627\u0644\u062a\u062d\u0631\u064a\u0631 \u0648\u0625\u062c\u0631\u0627\u0621 \u0627\u0644\u0645\u0642\u0627\u0628\u0644\u0627\u062a \u0639\u0646 \u0628\u0639\u062f \u0648\u0627\u0644\u0628\u062b \u0627\u0644\u0645\u0628\u0627\u0634\u0631 \u0648\u0627\u0644\u0627\u0644\u062a\u0642\u0627\u0621 \u0628\u0641\u0631\u064a\u0642\u0643 \u0648\u0627\u0644\u062a\u062e\u0637\u064a\u0637 \u0644\u0647 \u0648\u0645\u0634\u0627\u0631\u0643\u0629 \u0627\u0644\u0645\u0644\u0641\u0627\u062a \u0648\u0627\u0644\u0646\u0634\u0631 \u0645\u0646 \u0623\u064a \u062c\u0647\u0627\u0632 \u0631\u0642\u0645\u064a \u062a\u0642\u0631\u064a\u0628\u064b\u0627.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64ff6c9 elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"64ff6c9\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"279\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionAbeja.png\" class=\"attachment-large size-large wp-image-62\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b99704 elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"4b99704\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.5,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"279\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionAbeja.png\" class=\"attachment-large size-large wp-image-62\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-208ef07 elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"208ef07\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.5,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"279\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionAbeja.png\" class=\"attachment-large size-large wp-image-62\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0794fe6\" data-id=\"0794fe6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f754bbf dce_masking-none elementor-widget elementor-widget-image\" data-id=\"f754bbf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_ElementoPatronLila.svg\" class=\"attachment-large size-large wp-image-56\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d4e94 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"44d4e94\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_ElementoPatronLila.svg\" class=\"attachment-large size-large wp-image-56\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4855676 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"4855676\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_ElementoPatronLila.svg\" class=\"attachment-large size-large wp-image-56\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d216b39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d216b39\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4598e61\" data-id=\"4598e61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd15560 elementor-widget__width-initial dce_masking-none elementor-widget elementor-widget-image\" data-id=\"bd15560\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"951\" height=\"870\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionColmena.png\" class=\"attachment-large size-large wp-image-74\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionColmena.png 951w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionColmena-300x274.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionColmena-768x703.png 768w\" sizes=\"(max-width: 951px) 100vw, 951px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6272e0d\" data-id=\"6272e0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b40692a elementor-widget elementor-widget-heading\" data-id=\"b40692a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/docs.colmena.media\" target=\"_blank\">> \u0627\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u0643\u0648\u0644\u0645\u064a\u0646<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<!-- dce invisible element 24b578f --><!-- dce invisible element bda43ff --><!-- dce invisible element 7100e7b -->\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-584cbb7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"584cbb7\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-922ef6e\" data-id=\"922ef6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c3c46e elementor-widget elementor-widget-template\" data-id=\"3c3c46e\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4127\" class=\"elementor elementor-4127 elementor-3899\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section data-dce-background-overlay-color=\"#4C517F73\" data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/P1_3-3-9.svg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-428d2bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"428d2bf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08d8dc4\" data-id=\"08d8dc4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c621df8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c621df8\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8f56616\" data-id=\"8f56616\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0511ca2\" data-id=\"0511ca2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4e15a7 elementor-widget elementor-widget-heading\" data-id=\"e4e15a7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0623\u062f\u0648\u0627\u062a\u0643 \u0627\u0644\u0645\u0641\u0636\u0644\u0629 \u0641\u064a \u0645\u0643\u0627\u0646 \u0648\u0627\u062d\u062f<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ed0bdac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed0bdac\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a26d70\" data-id=\"4a26d70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09e7e9d premium-tabs-icon-column premium-tabs-icon-row elementor-widget elementor-widget-premium-addon-tabs\" data-id=\"09e7e9d\" data-element_type=\"widget\" data-settings=\"{&quot;premium_tabs_repeater&quot;:[{&quot;premium_tabs_title&quot;:&quot;&quot;,&quot;_id&quot;:&quot;46b1eaf&quot;,&quot;premium_tabs_icon_switcher&quot;:&quot;yes&quot;,&quot;premium_tabs_icon_updated&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/01digital-newsrooms_SW-copy.svg&quot;,&quot;id&quot;:4138},&quot;library&quot;:&quot;svg&quot;},&quot;premium_tabs_content&quot;:&quot;elementor_templates&quot;,&quot;premium_tabs_content_temp&quot;:&quot;Digital newsrooms AR&quot;,&quot;icon_type&quot;:&quot;icon&quot;,&quot;image_upload&quot;:null,&quot;custom_svg&quot;:null,&quot;lottie_url&quot;:null,&quot;draw_svg&quot;:null,&quot;lottie_loop&quot;:null,&quot;lottie_reverse&quot;:null,&quot;premium_tabs_content_text&quot;:null,&quot;live_temp_content&quot;:&quot;&quot;,&quot;custom_tab_navigation&quot;:&quot;&quot;},{&quot;premium_tabs_title&quot;:&quot;&quot;,&quot;_id&quot;:&quot;d6c3c42&quot;,&quot;premium_tabs_icon_switcher&quot;:&quot;yes&quot;,&quot;premium_tabs_icon_updated&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/02mobile-recording_AR_white-1.svg&quot;,&quot;id&quot;:4132},&quot;library&quot;:&quot;svg&quot;},&quot;premium_tabs_content&quot;:&quot;elementor_templates&quot;,&quot;premium_tabs_content_temp&quot;:&quot;Mobile recording AR&quot;,&quot;icon_type&quot;:&quot;icon&quot;,&quot;image_upload&quot;:null,&quot;custom_svg&quot;:null,&quot;lottie_url&quot;:null,&quot;draw_svg&quot;:null,&quot;lottie_loop&quot;:null,&quot;lottie_reverse&quot;:null,&quot;premium_tabs_content_text&quot;:null,&quot;live_temp_content&quot;:&quot;&quot;,&quot;custom_tab_navigation&quot;:&quot;&quot;},{&quot;premium_tabs_title&quot;:&quot;&quot;,&quot;_id&quot;:&quot;1910df0&quot;,&quot;premium_tabs_icon_switcher&quot;:&quot;yes&quot;,&quot;premium_tabs_icon_updated&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/03virtual-studio_AR.svg&quot;,&quot;id&quot;:4133},&quot;library&quot;:&quot;svg&quot;},&quot;premium_tabs_content&quot;:&quot;elementor_templates&quot;,&quot;premium_tabs_content_temp&quot;:&quot;Virtual Studio AR&quot;,&quot;icon_type&quot;:&quot;icon&quot;,&quot;image_upload&quot;:null,&quot;custom_svg&quot;:null,&quot;lottie_url&quot;:null,&quot;draw_svg&quot;:null,&quot;lottie_loop&quot;:null,&quot;lottie_reverse&quot;:null,&quot;premium_tabs_content_text&quot;:null,&quot;live_temp_content&quot;:&quot;&quot;,&quot;custom_tab_navigation&quot;:&quot;&quot;},{&quot;premium_tabs_title&quot;:&quot;&quot;,&quot;premium_tabs_icon_switcher&quot;:&quot;yes&quot;,&quot;premium_tabs_icon_updated&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/04mobile-editing_AR.svg&quot;,&quot;id&quot;:4134},&quot;library&quot;:&quot;svg&quot;},&quot;premium_tabs_content&quot;:&quot;elementor_templates&quot;,&quot;premium_tabs_content_temp&quot;:&quot;Mobile editing AR&quot;,&quot;_id&quot;:&quot;2d93fea&quot;,&quot;icon_type&quot;:&quot;icon&quot;,&quot;image_upload&quot;:null,&quot;custom_svg&quot;:null,&quot;lottie_url&quot;:null,&quot;draw_svg&quot;:null,&quot;lottie_loop&quot;:null,&quot;lottie_reverse&quot;:null,&quot;premium_tabs_content_text&quot;:null,&quot;live_temp_content&quot;:&quot;&quot;,&quot;custom_tab_navigation&quot;:&quot;&quot;},{&quot;premium_tabs_title&quot;:&quot;&quot;,&quot;premium_tabs_icon_switcher&quot;:&quot;yes&quot;,&quot;premium_tabs_icon_updated&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/05collaborative-text_AR.svg&quot;,&quot;id&quot;:4135},&quot;library&quot;:&quot;svg&quot;},&quot;premium_tabs_content&quot;:&quot;elementor_templates&quot;,&quot;premium_tabs_content_temp&quot;:&quot;Collaborative text AR&quot;,&quot;_id&quot;:&quot;67af4d9&quot;,&quot;icon_type&quot;:&quot;icon&quot;,&quot;image_upload&quot;:null,&quot;custom_svg&quot;:null,&quot;lottie_url&quot;:null,&quot;draw_svg&quot;:null,&quot;lottie_loop&quot;:null,&quot;lottie_reverse&quot;:null,&quot;premium_tabs_content_text&quot;:null,&quot;live_temp_content&quot;:&quot;&quot;,&quot;custom_tab_navigation&quot;:&quot;&quot;},{&quot;premium_tabs_title&quot;:&quot;&quot;,&quot;premium_tabs_icon_switcher&quot;:&quot;yes&quot;,&quot;premium_tabs_icon_updated&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/06collabs_AR.svg&quot;,&quot;id&quot;:4136},&quot;library&quot;:&quot;svg&quot;},&quot;premium_tabs_content&quot;:&quot;elementor_templates&quot;,&quot;premium_tabs_content_temp&quot;:&quot;Collabs AR&quot;,&quot;_id&quot;:&quot;447aea6&quot;,&quot;icon_type&quot;:&quot;icon&quot;,&quot;image_upload&quot;:null,&quot;custom_svg&quot;:null,&quot;lottie_url&quot;:null,&quot;draw_svg&quot;:null,&quot;lottie_loop&quot;:null,&quot;lottie_reverse&quot;:null,&quot;premium_tabs_content_text&quot;:null,&quot;live_temp_content&quot;:&quot;&quot;,&quot;custom_tab_navigation&quot;:&quot;&quot;},{&quot;premium_tabs_title&quot;:&quot;&quot;,&quot;premium_tabs_icon_switcher&quot;:&quot;yes&quot;,&quot;premium_tabs_icon_updated&quot;:{&quot;value&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/blog.colmena.media\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/07personalized-outplay_AR.svg&quot;,&quot;id&quot;:4137},&quot;library&quot;:&quot;svg&quot;},&quot;premium_tabs_content&quot;:&quot;elementor_templates&quot;,&quot;premium_tabs_content_temp&quot;:&quot;Personalized outplay AR&quot;,&quot;_id&quot;:&quot;b98275d&quot;,&quot;icon_type&quot;:&quot;icon&quot;,&quot;image_upload&quot;:null,&quot;custom_svg&quot;:null,&quot;lottie_url&quot;:null,&quot;draw_svg&quot;:null,&quot;lottie_loop&quot;:null,&quot;lottie_reverse&quot;:null,&quot;premium_tabs_content_text&quot;:null,&quot;live_temp_content&quot;:&quot;&quot;,&quot;custom_tab_navigation&quot;:&quot;&quot;}],&quot;autochange&quot;:&quot;true&quot;,&quot;premium_tab_type&quot;:&quot;vertical&quot;,&quot;accordion_tabs&quot;:&quot;true&quot;,&quot;premium_tab_active_background_color&quot;:&quot;#F39B10&quot;,&quot;default_tab_index&quot;:0,&quot;autochange_delay&quot;:2,&quot;premium_tab_style_selected&quot;:&quot;style1&quot;,&quot;accordion_tabs_devices&quot;:[&quot;tablet&quot;,&quot;mobile&quot;],&quot;accordion_tabs_anim_duration&quot;:&quot;fast&quot;}\" data-widget_type=\"premium-addon-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t\t<div data-navigation=\"[&quot;&quot;,&quot;&quot;,&quot;&quot;,&quot;&quot;,&quot;&quot;,&quot;&quot;,&quot;&quot;]\" id=\"premium-tabs-09e7e9d\" class=\"premium-tabs premium-tabs-style-iconbox premium-tabs-vertical\">\r\n\t\t\t\t<div class=\"premium-tabs-nav vertical\">\r\n\t\t\t\t\t<ul class=\"premium-tabs-nav-list premium-tabs-vertical\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-tabs-nav-list-item elementor-repeater-item-46b1eaf\" data-list-index=\"0\" data-content-id=\"#premium-accordion-content-0\">\r\n\t\t\t\t\t\t\t\t<a class=\"premium-tab-link\" aria-label=\"#section-0-09e7e9d\" href=\"#section-iconbox-0-09e7e9d\">\r\n\r\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 521 153\"><defs><style>.cls-1{fill:#fff;}.cls-2{fill:none;}<\/style><\/defs><path class=\"cls-1\" d=\"M155.53,82.68a15.93,15.93,0,0,1-4,.44,10.68,10.68,0,0,1-3.69-.74,6.1,6.1,0,0,1-2.66-2,5.55,5.55,0,0,1-1-3.4,7.23,7.23,0,0,1,.78-3.36,8.94,8.94,0,0,1,2.19-2.67,13.25,13.25,0,0,1,3.27-2,21.09,21.09,0,0,1,4-1.26l.46,4.79a9.47,9.47,0,0,0-2.4.44,8,8,0,0,0-1.93.91,4.4,4.4,0,0,0-1.27,1.23,2.56,2.56,0,0,0-.46,1.48,1.47,1.47,0,0,0,.42,1.09,2.91,2.91,0,0,0,1.1.66,5.2,5.2,0,0,0,1.55.3,7.79,7.79,0,0,0,1.73-.09,7.2,7.2,0,0,0,1.64-.45Zm-5.7-21.25a2.24,2.24,0,0,1-1.65-.66,2.21,2.21,0,0,1-.66-1.61,2.36,2.36,0,0,1,.66-1.66,2.19,2.19,0,0,1,1.68-.72,2.09,2.09,0,0,1,1.58.72,2.32,2.32,0,0,1,.66,1.62,2.25,2.25,0,0,1-.66,1.65A2.21,2.21,0,0,1,149.83,61.43Zm11.23,24.68a10,10,0,0,1-3.69-.63,5.24,5.24,0,0,1-2.52-2.08,7.82,7.82,0,0,1-1-3.91l-.67-14.24h4.69l.6,12.63a7.8,7.8,0,0,0,.36,2.26,1.86,1.86,0,0,0,.93,1.09,4,4,0,0,0,1.65.29,2.17,2.17,0,0,1,1.73.63,2.35,2.35,0,0,1,.54,1.58,2.31,2.31,0,0,1-.66,1.73A2.68,2.68,0,0,1,161.06,86.11Zm-5.42-24.68a2.25,2.25,0,0,1-1.65-.66,2.18,2.18,0,0,1-.66-1.58,2.37,2.37,0,0,1,.66-1.68,2.26,2.26,0,0,1,1.68-.7,2.1,2.1,0,0,1,1.59.7,2.33,2.33,0,0,1,.65,1.65,2.25,2.25,0,0,1-2.27,2.27Z\"><\/path><path class=\"cls-1\" d=\"M161.06,86.11l.35-4.59a6.17,6.17,0,0,0,2-.26,2.65,2.65,0,0,0,1.33-1,7,7,0,0,0,.91-2.28c.25-1,.48-2.34.72-4l4.41.73c0,.38-.11.79-.19,1.25s-.16.92-.21,1.39a11.29,11.29,0,0,0-.09,1.39,2.84,2.84,0,0,0,.23,1.19,2,2,0,0,0,.73.87,4.08,4.08,0,0,0,1.4.56,9.67,9.67,0,0,0,2.19.21,2.1,2.1,0,0,1,1.69.63,2.31,2.31,0,0,1,.55,1.58,2.28,2.28,0,0,1-.67,1.73,2.64,2.64,0,0,1-1.92.65,14.75,14.75,0,0,1-3-.28,5.75,5.75,0,0,1-2.14-.88A4.09,4.09,0,0,1,168,83.41a6.72,6.72,0,0,1-.61-2.31l1.57,0a8,8,0,0,1-1.47,2.68,5.62,5.62,0,0,1-2,1.48,8.06,8.06,0,0,1-2.22.65A17.29,17.29,0,0,1,161.06,86.11Zm3.36,7.8a2.31,2.31,0,0,1-2.31-2.27,2.31,2.31,0,0,1,.67-1.68,2.16,2.16,0,0,1,1.64-.7A2.12,2.12,0,0,1,166,90a2.31,2.31,0,0,1,.67,1.68,2.19,2.19,0,0,1-.67,1.59A2.14,2.14,0,0,1,164.42,93.91Zm5.85,0a2.22,2.22,0,0,1-1.68-.68,2.19,2.19,0,0,1-.67-1.59,2.31,2.31,0,0,1,.67-1.68,2.2,2.2,0,0,1,1.68-.7,2.08,2.08,0,0,1,1.57.7,2.31,2.31,0,0,1,.67,1.68,2.19,2.19,0,0,1-.67,1.59A2.1,2.1,0,0,1,170.27,93.91Z\"><\/path><path class=\"cls-1\" d=\"M174.43,86.11l.32-4.59a2,2,0,0,0,1.22-.38A5,5,0,0,0,177,79.75c.38-.66.88-1.6,1.49-2.81a18.33,18.33,0,0,1,1.57-2.66,8.87,8.87,0,0,1,1.66-1.8,6.13,6.13,0,0,1,1.75-1,5.62,5.62,0,0,1,1.88-.32,4.15,4.15,0,0,1,2.34.65,6.28,6.28,0,0,1,1.79,1.94A20.79,20.79,0,0,1,191.09,77a20.78,20.78,0,0,0,1.07,2.22,5.91,5.91,0,0,0,1.31,1.66,2.51,2.51,0,0,0,1.68.63,2.13,2.13,0,0,1,1.7.63,2.53,2.53,0,0,1-.12,3.27,2.52,2.52,0,0,1-1.89.69,6.45,6.45,0,0,1-2.72-.56A5.77,5.77,0,0,1,190,83.87l1-.53a6,6,0,0,1-.84,1.6,4.07,4.07,0,0,1-1.42,1.18,4.44,4.44,0,0,1-2.08.44,6.77,6.77,0,0,1-1.91-.33,8.33,8.33,0,0,1-2.29-1.15,9.69,9.69,0,0,1-2.31-2.37,8.06,8.06,0,0,1-1.72,2.16,4.93,4.93,0,0,1-1.85,1A8.09,8.09,0,0,1,174.43,86.11Zm7.81-7.21a10.71,10.71,0,0,0,.82,1.14,6.54,6.54,0,0,0,1.07,1,6.12,6.12,0,0,0,1.2.73,3,3,0,0,0,1.25.28,1,1,0,0,0,1-.58,2.47,2.47,0,0,0,0-1.62c-.3-.75-.56-1.38-.79-1.91s-.42-1-.61-1.33a2.49,2.49,0,0,0-.59-.79,1,1,0,0,0-.63-.24,1.39,1.39,0,0,0-1,.47,5.75,5.75,0,0,0-.93,1.21A13.43,13.43,0,0,0,182.24,78.9Z\"><\/path><path class=\"cls-1\" d=\"M194.8,86.11l.32-4.59c1,0,1.95,0,2.78,0s1.56-.06,2.2-.11a13.5,13.5,0,0,0,1.74-.22,5.25,5.25,0,0,0,1.29-.44,3.14,3.14,0,0,0,1.05-1,4,4,0,0,0,.61-1.59,12.3,12.3,0,0,0,.2-2.38,15.31,15.31,0,0,0-.25-3A4.35,4.35,0,0,0,204,71a1.48,1.48,0,0,0-1.17-.65,1.35,1.35,0,0,0-.93.41,2.92,2.92,0,0,0-.72,1.1,4.3,4.3,0,0,0-.28,1.64,1.83,1.83,0,0,0,.28,1,1.6,1.6,0,0,0,.75.61,2.93,2.93,0,0,0,1.11.2,5.5,5.5,0,0,0,1.34-.18,6.58,6.58,0,0,0,1.42-.52l.14,3.5a5.29,5.29,0,0,1-1.17.71,5.71,5.71,0,0,1-1.38.44,7.58,7.58,0,0,1-1.51.14,6.35,6.35,0,0,1-2.85-.61A4.37,4.37,0,0,1,197.11,77a5.69,5.69,0,0,1-.66-2.87,9.8,9.8,0,0,1,.45-2.94,8.21,8.21,0,0,1,1.35-2.59,6.94,6.94,0,0,1,2.1-1.84,5.45,5.45,0,0,1,2.71-.68,5.09,5.09,0,0,1,3.5,1.28,7.81,7.81,0,0,1,2.17,3.52,16.6,16.6,0,0,1,.74,5.18,12.88,12.88,0,0,1-.81,4.79A6.54,6.54,0,0,1,206.18,84a7.8,7.8,0,0,1-2.07,1.07,14,14,0,0,1-2.55.61c-.94.14-2,.24-3.08.3S196.13,86.11,194.8,86.11Zm5.29-23.42a2.24,2.24,0,0,1-1.65-.66,2.21,2.21,0,0,1-.66-1.61,2.4,2.4,0,0,1,.66-1.67,2.2,2.2,0,0,1,1.68-.71,2.12,2.12,0,0,1,1.58.71,2.36,2.36,0,0,1,.66,1.63A2.25,2.25,0,0,1,201.7,62,2.21,2.21,0,0,1,200.09,62.69Zm5.81,0a2.24,2.24,0,0,1-1.65-.66,2.18,2.18,0,0,1-.66-1.58,2.37,2.37,0,0,1,.66-1.68,2.23,2.23,0,0,1,1.68-.7,2.1,2.1,0,0,1,1.59.7,2.33,2.33,0,0,1,.65,1.65,2.25,2.25,0,0,1-2.27,2.27Z\"><\/path><path class=\"cls-1\" d=\"M210.76,94l-2.41-4.41a20.13,20.13,0,0,0,2.9-1.66,12,12,0,0,0,2.12-1.88,6.78,6.78,0,0,0,1.28-2.1,6.7,6.7,0,0,0,.42-2.38,9.25,9.25,0,0,0-.65-3.25,37.38,37.38,0,0,0-1.59-3.61l4.41-2.2a20.29,20.29,0,0,1,1,2.17c.3.74.56,1.44.79,2.1s.41,1.2.53,1.64a4.27,4.27,0,0,0,1.4,2.42,4,4,0,0,0,2.38.66,2.1,2.1,0,0,1,1.69.63,2.59,2.59,0,0,1-.1,3.31,2.64,2.64,0,0,1-1.94.65,5.39,5.39,0,0,1-2.19-.44,3.7,3.7,0,0,1-1.59-1.26,5.06,5.06,0,0,1-.84-1.84l1.36-.63a11.19,11.19,0,0,1-.65,3.61,12.38,12.38,0,0,1-1.73,3.24,15.32,15.32,0,0,1-2.76,2.83A21.69,21.69,0,0,1,210.76,94Z\"><\/path><path class=\"cls-1\" d=\"M223,86.11l.31-4.59a3.65,3.65,0,0,0,1.89-.36,2,2,0,0,0,.72-1.39,17.36,17.36,0,0,0,.09-2.9l-.67-16.7h4.76l.7,17.08a19.5,19.5,0,0,1-.12,3.66,6.34,6.34,0,0,1-1,2.78,5.15,5.15,0,0,1-2.4,1.79A11.79,11.79,0,0,1,223,86.11Z\"><\/path><path class=\"cls-1\" d=\"M235.58,85.93l-.74-25.76h4.76l.74,25.76Z\"><\/path><path class=\"cls-1\" d=\"M252.45,94,250,89.61A19.73,19.73,0,0,0,252.94,88a11.88,11.88,0,0,0,2.11-1.88,6.78,6.78,0,0,0,1.28-2.1,6.7,6.7,0,0,0,.42-2.38,9.25,9.25,0,0,0-.65-3.25,37.38,37.38,0,0,0-1.59-3.61l4.41-2.2a20.35,20.35,0,0,1,1,2.17c.29.74.55,1.44.79,2.1s.4,1.2.52,1.64a4.33,4.33,0,0,0,1.4,2.42,4,4,0,0,0,2.38.66,2.13,2.13,0,0,1,1.7.63,2.61,2.61,0,0,1-.11,3.31,2.64,2.64,0,0,1-1.94.65,5.46,5.46,0,0,1-2.19-.44,3.82,3.82,0,0,1-1.59-1.26,5.06,5.06,0,0,1-.84-1.84l1.37-.63a11.47,11.47,0,0,1-.65,3.61A13,13,0,0,1,259,88.79a15.07,15.07,0,0,1-2.77,2.83A22,22,0,0,1,252.45,94Z\"><\/path><path class=\"cls-1\" d=\"M264.66,86.11l.35-4.59a15.45,15.45,0,0,0,3.1-.24,2.5,2.5,0,0,0,1.54-.86,3,3,0,0,0,.43-1.73,13.35,13.35,0,0,0-.26-2.5c-.17-1-.39-1.91-.66-2.89s-.54-1.88-.83-2.7l4.45-1.29a28.44,28.44,0,0,1,.88,2.76c.28,1.05.51,2.14.71,3.26a18.45,18.45,0,0,1,.3,3.25,8.6,8.6,0,0,1-.75,3.87,5.38,5.38,0,0,1-2.12,2.28,9.49,9.49,0,0,1-3.17,1.08A24.2,24.2,0,0,1,264.66,86.11Zm2.49,7.8a2.18,2.18,0,0,1-1.65-.68,2.23,2.23,0,0,1-.67-1.59A2.35,2.35,0,0,1,265.5,90a2.2,2.2,0,0,1,1.68-.7,2.07,2.07,0,0,1,1.57.7,2.27,2.27,0,0,1,.67,1.64,2.24,2.24,0,0,1-.68,1.63A2.17,2.17,0,0,1,267.15,93.91Zm5.81,0a2.18,2.18,0,0,1-1.65-.68,2.22,2.22,0,0,1-.66-1.59,2.34,2.34,0,0,1,.66-1.68,2.2,2.2,0,0,1,1.68-.7,2.11,2.11,0,0,1,1.58.7,2.3,2.3,0,0,1,.66,1.64,2.26,2.26,0,0,1-.66,1.63A2.17,2.17,0,0,1,273,93.91Z\"><\/path><path class=\"cls-1\" d=\"M277.68,94l-2.42-4.41A19.73,19.73,0,0,0,278.17,88a12,12,0,0,0,2.12-1.88,6.56,6.56,0,0,0,1.27-2.1,6.7,6.7,0,0,0,.43-2.38,9.25,9.25,0,0,0-.65-3.25,37.38,37.38,0,0,0-1.59-3.61l4.41-2.2a20.29,20.29,0,0,1,1,2.17c.29.74.56,1.44.79,2.1s.41,1.2.52,1.64a4.33,4.33,0,0,0,1.41,2.42,3.93,3.93,0,0,0,2.38.66,2.12,2.12,0,0,1,1.69.63,2.59,2.59,0,0,1-.1,3.31,2.65,2.65,0,0,1-1.95.65,5.37,5.37,0,0,1-2.18-.44,3.7,3.7,0,0,1-1.59-1.26,5.25,5.25,0,0,1-.85-1.84l1.37-.63a11.19,11.19,0,0,1-.65,3.61,12.68,12.68,0,0,1-1.73,3.24,15.32,15.32,0,0,1-2.76,2.83A21.69,21.69,0,0,1,277.68,94Z\"><\/path><path class=\"cls-1\" d=\"M289.89,86.11l.32-4.59a19.1,19.1,0,0,0,3.2-.26,27.38,27.38,0,0,0,3.17-.73,21.84,21.84,0,0,0,3.1-1.21,22.36,22.36,0,0,0,3-1.75,16.21,16.21,0,0,0-2.31-1.11,14.39,14.39,0,0,0-2.29-.66,12,12,0,0,0-2.33-.23c-.37,0-.74,0-1.09,0s-.7.06-1.06.1-.73.12-1.11.21l-.8-4.62a12.72,12.72,0,0,1,1.91-.4,15.27,15.27,0,0,1,1.9-.12,12.66,12.66,0,0,1,3.4.42,15.35,15.35,0,0,1,2.73,1q1.23.61,2.22,1.23a20.33,20.33,0,0,0,1.91,1,4.31,4.31,0,0,0,1.82.42h.91l.56,4.27a6.2,6.2,0,0,0-2.28.65,18.75,18.75,0,0,0-2.24,1.33c-.77.52-1.6,1.06-2.5,1.62A25.53,25.53,0,0,1,299,84.39,18.82,18.82,0,0,1,295,85.63,24.45,24.45,0,0,1,289.89,86.11Zm19.92,0a9.36,9.36,0,0,1-2.21-.25,6,6,0,0,1-2-.87,6.33,6.33,0,0,1-1.7-1.72,9.74,9.74,0,0,1-1.24-2.69l2.69-2a4.78,4.78,0,0,0,1.21,1.82,4.11,4.11,0,0,0,1.63.88,7.68,7.68,0,0,0,2,.24,2.13,2.13,0,0,1,1.7.63,2.61,2.61,0,0,1-.11,3.31A2.64,2.64,0,0,1,309.81,86.11Z\"><\/path><path class=\"cls-1\" d=\"M309.81,86.11l.35-4.59a6.25,6.25,0,0,0,2-.26,2.69,2.69,0,0,0,1.33-1,7,7,0,0,0,.91-2.28c.24-1,.48-2.34.71-4l4.41.73c0,.38-.11.79-.19,1.25s-.15.92-.21,1.39a11.29,11.29,0,0,0-.09,1.39,3,3,0,0,0,.23,1.19,2,2,0,0,0,.74.87,4,4,0,0,0,1.4.56,9.63,9.63,0,0,0,2.18.21,2.13,2.13,0,0,1,1.7.63,2.3,2.3,0,0,1,.54,1.54,2.36,2.36,0,0,1-.66,1.77,2.66,2.66,0,0,1-1.93.65,14.9,14.9,0,0,1-3-.28,5.77,5.77,0,0,1-2.13-.88,4,4,0,0,1-1.31-1.54,6.71,6.71,0,0,1-.62-2.31l1.58,0a8.35,8.35,0,0,1-1.47,2.68,5.71,5.71,0,0,1-2,1.48,8.06,8.06,0,0,1-2.22.65A17.29,17.29,0,0,1,309.81,86.11ZM314.15,70a2.29,2.29,0,0,1-1.66-.66,2.16,2.16,0,0,1-.69-1.61,2.37,2.37,0,0,1,.67-1.66,2.18,2.18,0,0,1,1.68-.72,2.11,2.11,0,0,1,1.61.72,2.32,2.32,0,0,1,.66,1.62,2.25,2.25,0,0,1-.66,1.65A2.2,2.2,0,0,1,314.15,70Zm5.81,0a2.29,2.29,0,0,1-2.31-2.28,2.37,2.37,0,0,1,.66-1.68,2.26,2.26,0,0,1,1.68-.7,2.13,2.13,0,0,1,1.58.7,2.34,2.34,0,0,1,.66,1.65,2.21,2.21,0,0,1-.68,1.63A2.18,2.18,0,0,1,320,70.08Z\"><\/path><path class=\"cls-1\" d=\"M323.18,86.11l.31-4.59a3.65,3.65,0,0,0,1.89-.36,1.89,1.89,0,0,0,.72-1.39,15.42,15.42,0,0,0,.09-2.9l-.67-16.7h4.76l.7,17.08a19.5,19.5,0,0,1-.12,3.66,6.22,6.22,0,0,1-1,2.78,5.15,5.15,0,0,1-2.4,1.79A11.79,11.79,0,0,1,323.18,86.11Z\"><\/path><path class=\"cls-1\" d=\"M335.78,85.93,335,60.17h4.76l.74,25.76Z\"><\/path><path class=\"cls-1\" d=\"M364.79,86.67a23.83,23.83,0,0,1-5.56-.56,11,11,0,0,1-3.73-1.6A6,6,0,0,1,353.4,82a7.91,7.91,0,0,1-.65-3.24,12.72,12.72,0,0,1,.21-2.2c.14-.8.31-1.56.51-2.3s.39-1.39.58-2l4.09,1.05c-.11.42-.24.87-.36,1.36s-.24,1-.34,1.47a8.13,8.13,0,0,0-.14,1.47,3.89,3.89,0,0,0,.7,2.24,4.63,4.63,0,0,0,2.52,1.59,17.68,17.68,0,0,0,5.15.58l.7,3.5Zm0,0,.88-4.59c1.77,0,3.32,0,4.65-.08s2.46-.14,3.38-.25a9.93,9.93,0,0,0,2.22-.46,3.51,3.51,0,0,0,1.26-.68A3.58,3.58,0,0,0,378,79a14.22,14.22,0,0,0,.28-3.34,15.37,15.37,0,0,0-.14-2.24,8.6,8.6,0,0,0-.4-1.77,2.93,2.93,0,0,0-.65-1.14,1.25,1.25,0,0,0-.91-.38,1.33,1.33,0,0,0-1,.43,3,3,0,0,0-.68,1.16,5,5,0,0,0-.25,1.59,2.2,2.2,0,0,0,.25,1.07,1.5,1.5,0,0,0,.73.65,2.83,2.83,0,0,0,1.12.21,6.42,6.42,0,0,0,1.47-.18,4.85,4.85,0,0,0,1.44-.56l.14,3.54a4.53,4.53,0,0,1-1.23.72,8,8,0,0,1-1.5.43,7.28,7.28,0,0,1-1.4.14,6.7,6.7,0,0,1-2.8-.56,4.34,4.34,0,0,1-2-1.71,5.47,5.47,0,0,1-.72-2.94,9.35,9.35,0,0,1,.48-3,8.66,8.66,0,0,1,1.36-2.59,6.84,6.84,0,0,1,2.12-1.83,5.33,5.33,0,0,1,2.66-.69,5.06,5.06,0,0,1,3.52,1.32,8.19,8.19,0,0,1,2.2,3.51,15.52,15.52,0,0,1,.75,5,17.27,17.27,0,0,1-.26,3.16,11.79,11.79,0,0,1-.73,2.56,8,8,0,0,1-1.11,1.87,6.67,6.67,0,0,1-2.1,1.51,13.22,13.22,0,0,1-3.16,1,34.7,34.7,0,0,1-4.54.52Q368.3,86.68,364.79,86.67Zm11.9-24.05a2.32,2.32,0,0,1-2.34-2.31A2.37,2.37,0,0,1,375,58.6a2.27,2.27,0,0,1,1.7-.7,2.2,2.2,0,0,1,1.63.7,2.32,2.32,0,0,1,.68,1.68,2.32,2.32,0,0,1-2.35,2.34Z\"><\/path><path class=\"cls-1\" d=\"M384.11,94l-2.41-4.41A19.6,19.6,0,0,0,384.6,88a12,12,0,0,0,2.12-1.88A6.78,6.78,0,0,0,388,84a6.7,6.7,0,0,0,.42-2.38,9.25,9.25,0,0,0-.65-3.25,37.38,37.38,0,0,0-1.59-3.61l4.41-2.2a22.54,22.54,0,0,1,1,2.17q.44,1.11.78,2.1c.24.65.41,1.2.53,1.64a4.27,4.27,0,0,0,1.4,2.42,4,4,0,0,0,2.38.66,2.14,2.14,0,0,1,1.7.63,2.61,2.61,0,0,1-.11,3.31,2.64,2.64,0,0,1-1.94.65,5.46,5.46,0,0,1-2.19-.44,3.82,3.82,0,0,1-1.59-1.26,5.06,5.06,0,0,1-.84-1.84l1.36-.63a11.46,11.46,0,0,1-.64,3.61,12.72,12.72,0,0,1-1.74,3.24,14.71,14.71,0,0,1-2.76,2.83A21.69,21.69,0,0,1,384.11,94Z\"><\/path><path class=\"cls-1\" d=\"M396.33,86.11l.35-4.59q1.15,0,1.89,0c.49,0,.93-.07,1.33-.12l1.26-.2a6.89,6.89,0,0,1-1.1-1.12A6.74,6.74,0,0,1,399,78.16a7.29,7.29,0,0,1-.46-2.73,6.45,6.45,0,0,1,3.7-6.05,8.34,8.34,0,0,1,3.76-.84,11.87,11.87,0,0,1,1.68.12,12.45,12.45,0,0,1,1.75.4l-.7,4.27a10,10,0,0,0-1.19-.24,8,8,0,0,0-1.12-.07,3.44,3.44,0,0,0-1.61.35,2.51,2.51,0,0,0-1.09,1,3,3,0,0,0-.38,1.55,3.6,3.6,0,0,0,.24,1.32,5.16,5.16,0,0,0,.63,1.1,5.63,5.63,0,0,0,1.72,1.47,2.4,2.4,0,0,0,.8.28l.84-.25.77-.22c.28-.09.62-.21,1-.37l1.56-.67,1.43,4A33,33,0,0,1,407,84.69a32.42,32.42,0,0,1-5.24,1.1A44.76,44.76,0,0,1,396.33,86.11Zm8.4-21a2.34,2.34,0,0,1-2.35-2.31,2.34,2.34,0,0,1,.69-1.71,2.25,2.25,0,0,1,1.69-.7,2.18,2.18,0,0,1,1.63.7,2.28,2.28,0,0,1,.68,1.68,2.32,2.32,0,0,1-2.34,2.34Z\"><\/path><path class=\"cls-1\" d=\"M31.35,96.1A3,3,0,0,1,28.47,94,3.12,3.12,0,0,1,30,90.35c1.55-.85,4.62-6.16,5.36-8.21a1.76,1.76,0,0,0,.08-.68L29.31,70.91a9.78,9.78,0,0,1,0-9.76l8.65-15a9.79,9.79,0,0,1,8.45-4.88H63.72a9.79,9.79,0,0,1,8.45,4.88l8.65,15h0a9.78,9.78,0,0,1,0,9.76l-8.65,15a9.79,9.79,0,0,1-8.45,4.88H46.46c-.38.15-1.15.54-1.79.86-3,1.5-8,4-13.06,4.44ZM46.41,46.45a4.62,4.62,0,0,0-4,2.3l-8.65,15a4.61,4.61,0,0,0,0,4.6L40,79a6.16,6.16,0,0,1,.22,4.85,38.08,38.08,0,0,1-2.78,5.43c1.91-.76,3.65-1.63,5-2.29,1.93-1,2.81-1.41,3.78-1.41H63.72a4.63,4.63,0,0,0,4-2.29l8.65-15a4.61,4.61,0,0,0,0-4.6h0l-8.65-15a4.62,4.62,0,0,0-4-2.3Z\"><\/path><path class=\"cls-1\" d=\"M125,117.76c-1.56-.85-4.63-6.17-5.36-8.21a1.82,1.82,0,0,1-.08-.69l6.09-10.54a9.83,9.83,0,0,0,0-9.76l-8.66-15a9.76,9.76,0,0,0-8.44-4.87H91.28a9.78,9.78,0,0,0-8.45,4.87l-8.65,15a9.78,9.78,0,0,0,0,9.76l8.65,15a9.79,9.79,0,0,0,8.45,4.88h17.26c.38.15,1.15.55,1.79.86,3,1.51,8,4,13.06,4.45h.26a3,3,0,0,0,2.88-2.14A3.11,3.11,0,0,0,125,117.76Zm-12.4-3.34c-1.93-1-2.81-1.4-3.78-1.4H91.28a4.6,4.6,0,0,1-4-2.3l-8.65-15a4.56,4.56,0,0,1,0-4.59l8.65-15a4.61,4.61,0,0,1,4-2.29h17.31a4.63,4.63,0,0,1,4,2.29l8.65,15a4.59,4.59,0,0,1,0,4.59L115,106.44a6.16,6.16,0,0,0-.22,4.85,38.74,38.74,0,0,0,2.78,5.42C115.69,116,114,115.08,112.64,114.42Z\"><\/path><circle class=\"cls-1\" cx=\"47.12\" cy=\"66.19\" r=\"2.53\"><\/circle><circle class=\"cls-1\" cx=\"55.89\" cy=\"66.19\" r=\"2.53\"><\/circle><circle class=\"cls-1\" cx=\"64.67\" cy=\"66.19\" r=\"2.53\"><\/circle><circle class=\"cls-1\" cx=\"91.16\" cy=\"93.32\" r=\"2.53\"><\/circle><circle class=\"cls-1\" cx=\"99.93\" cy=\"93.32\" r=\"2.53\"><\/circle><circle class=\"cls-1\" cx=\"108.71\" cy=\"93.32\" r=\"2.53\"><\/circle><rect class=\"cls-2\" x=\"0.5\" y=\"0.5\" width=\"520\" height=\"152\"><\/rect><\/svg>\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-border\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-accordion-tab-content\" id=\"premium-accordion-content-0\">\r\n\t\t\t\t\t\t\t\t\t\t<section id=\"section-iconbox-0-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3532\" class=\"elementor elementor-3532 elementor-1167\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-769878e elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"769878e\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d803fb\" data-id=\"6d803fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3064fa6 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"3064fa6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1082\" height=\"1920\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4.png\" class=\"attachment-full size-full wp-image-4781\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4.png 1082w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-577x1024.png 577w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-768x1363.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-866x1536.png 866w\" sizes=\"(max-width: 1082px) 100vw, 1082px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11ae159\" data-id=\"11ae159\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f334a27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f334a27\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1c28618\" data-id=\"1c28618\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5318d7 elementor-widget elementor-widget-text-editor\" data-id=\"e5318d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u0646\u0633\u0645\u064a\u0647\u0627 \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0639\u0633\u0644 \u0648\u0647\u064a \u062a\u0623\u062a\u064a \u0645\u0639 \u0628\u0631\u0648\u062a\u0648\u0643\u0648\u0644 \u062f\u0631\u062f\u0634\u0629 \u0648\u0645\u0634\u0641\u0631\u0629 \u0648\u0645\u0624\u062a\u0645\u0631\u0627\u062a \u0635\u0648\u062a\u064a\u0629 \u0648\u0647\u064a\u0643\u0644 \u0645\u062c\u0644\u062f \u0645\u0637\u0627\u0628\u0642 \u0644\u0625\u062f\u0627\u0631\u0629 \u062c\u0645\u064a\u0639 \u0645\u0633\u062a\u0646\u062f\u0627\u062a\u0643 \u0628\u0634\u0643\u0644 \u062c\u0645\u0627\u0639\u064a.\r\n\r\n\u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0639\u0633\u0644 \u0645\u0646 \u0642\u0628\u0644 \u0627\u0644\u0632\u0645\u0644\u0627\u0621 \u0645\u0646 \u0625\u062d\u062f\u0649 \u0627\u0644\u0648\u0633\u0627\u0626\u0637 \u0623\u0648 \u0625\u0639\u062f\u0627\u062f\u0647\u0627 \u0644\u0644\u062a\u0639\u0627\u0648\u0646 \u0627\u0644\u0634\u0628\u0643\u064a \u0628\u064a\u0646 \u0645\u062e\u062a\u0644\u0641 \u0627\u0644\u0634\u0631\u0643\u0627\u0621.\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/section>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-tabs-nav-list-item elementor-repeater-item-d6c3c42\" data-list-index=\"1\" data-content-id=\"#premium-accordion-content-1\">\r\n\t\t\t\t\t\t\t\t<a class=\"premium-tab-link\" aria-label=\"#section-1-09e7e9d\" href=\"#section-iconbox-1-09e7e9d\">\r\n\r\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 521 153\"><defs><style>.cls-1{fill:#fff;}.cls-2{fill:none;}<\/style><\/defs><path class=\"cls-1\" d=\"M144.37,85.23a16.8,16.8,0,0,1,.12-1.89,16.22,16.22,0,0,1,.52-2.45,26.45,26.45,0,0,1,1.21-3.22l4.13,1.54c-.3.79-.55,1.49-.73,2.1a12.74,12.74,0,0,0-.41,1.68,10.62,10.62,0,0,0-.12,1.64,5.21,5.21,0,0,0,.63,2.66,4,4,0,0,0,1.79,1.63,6.27,6.27,0,0,0,2.69.54,6.13,6.13,0,0,0,3-.66A4.33,4.33,0,0,0,159,86.87a9.34,9.34,0,0,0,.81-3.13,32.58,32.58,0,0,0,.12-4.32l-.7-19.25h4.83l.6,19a32.88,32.88,0,0,1-.2,4.74,17.93,17.93,0,0,1-.94,4.08,9.6,9.6,0,0,1-1.91,3.2,8.19,8.19,0,0,1-3.1,2.1A12,12,0,0,1,154,94a12.51,12.51,0,0,1-3.61-.52,9.37,9.37,0,0,1-3.11-1.6,7.51,7.51,0,0,1-2.16-2.71A9.15,9.15,0,0,1,144.37,85.23Z\"><\/path><path class=\"cls-1\" d=\"M168.52,94l-1-4.45a32,32,0,0,0,4-.79,10,10,0,0,0,2.95-1.27,5.17,5.17,0,0,0,1.84-2.14,7.47,7.47,0,0,0,.6-3.32,11.1,11.1,0,0,0-.53-4c-.37-1-.91-1.47-1.61-1.47a1.27,1.27,0,0,0-1,.49,3.25,3.25,0,0,0-.63,1.23,5.33,5.33,0,0,0-.21,1.47,2.68,2.68,0,0,0,.17,1,1.31,1.31,0,0,0,.72.66,4.48,4.48,0,0,0,1.63.28,21.13,21.13,0,0,0,2.9-.17h5.39a2.2,2.2,0,0,1,1.7.63,2.25,2.25,0,0,1,.58,1.57,2.3,2.3,0,0,1-.67,1.75,2.68,2.68,0,0,1-1.92.63h-7.56a11.48,11.48,0,0,1-4.05-.63,4.86,4.86,0,0,1-3.37-4.9,9.79,9.79,0,0,1,.49-3,11.2,11.2,0,0,1,1.36-2.83,7,7,0,0,1,2.08-2.08,4.84,4.84,0,0,1,2.68-.77,5,5,0,0,1,3.43,1.27,8.23,8.23,0,0,1,2.21,3.5,15.86,15.86,0,0,1,.8,5,12.19,12.19,0,0,1-1.68,6.53,10.85,10.85,0,0,1-4.55,4A19.8,19.8,0,0,1,168.52,94Z\"><\/path><path class=\"cls-1\" d=\"M183.43,86.1l.31-4.58a1.93,1.93,0,0,0,1.23-.39A5.07,5.07,0,0,0,186,79.75c.39-.67.89-1.61,1.49-2.82a19.89,19.89,0,0,1,1.58-2.66,8.6,8.6,0,0,1,1.66-1.8,5.87,5.87,0,0,1,1.75-1,5.56,5.56,0,0,1,1.87-.31,4.2,4.2,0,0,1,2.35.64,6.3,6.3,0,0,1,1.78,2A20.17,20.17,0,0,1,200.09,77a19.88,19.88,0,0,0,1.06,2.22,6.17,6.17,0,0,0,1.32,1.67,2.51,2.51,0,0,0,1.68.63,2.1,2.1,0,0,1,1.69.63,2.28,2.28,0,0,1,.55,1.57,2.32,2.32,0,0,1-.67,1.7,2.53,2.53,0,0,1-1.89.68,6.41,6.41,0,0,1-2.71-.56A5.5,5.5,0,0,1,199,83.86l.94-.52a5.79,5.79,0,0,1-.84,1.59,3.92,3.92,0,0,1-1.42,1.19,4.54,4.54,0,0,1-2.08.44,6.89,6.89,0,0,1-1.91-.34,8.19,8.19,0,0,1-2.29-1.15,10.19,10.19,0,0,1-2.31-2.36,8.14,8.14,0,0,1-1.71,2.15,5.07,5.07,0,0,1-1.86,1A8.4,8.4,0,0,1,183.43,86.1Zm7.8-7.21a12.34,12.34,0,0,0,.82,1.14,6.52,6.52,0,0,0,1.07,1,6.78,6.78,0,0,0,1.21.74,3.06,3.06,0,0,0,1.24.28,1,1,0,0,0,1-.58,2.49,2.49,0,0,0,0-1.63L195.8,78c-.22-.52-.43-1-.61-1.33a2.34,2.34,0,0,0-.6-.78,1,1,0,0,0-.63-.25,1.45,1.45,0,0,0-1,.47,6.1,6.1,0,0,0-.93,1.21A16.1,16.1,0,0,0,191.23,78.89Z\"><\/path><path class=\"cls-1\" d=\"M203.8,86.1l.31-4.58a19.11,19.11,0,0,0,3.2-.27,25.06,25.06,0,0,0,3.17-.73,21.84,21.84,0,0,0,3.1-1.21,22.36,22.36,0,0,0,3-1.75,16.13,16.13,0,0,0-2.31-1.1,15.58,15.58,0,0,0-2.29-.67,12,12,0,0,0-2.33-.22q-.55,0-1.08,0c-.35,0-.71.06-1.07.11a7.34,7.34,0,0,0-1.1.21l-.81-4.62a12.76,12.76,0,0,1,1.91-.41,15.43,15.43,0,0,1,1.91-.12,12.58,12.58,0,0,1,3.39.42,16.16,16.16,0,0,1,2.73,1q1.23.61,2.22,1.23a18.25,18.25,0,0,0,1.91,1,4.31,4.31,0,0,0,1.82.42h.91l.56,4.27a6.29,6.29,0,0,0-2.27.65,18,18,0,0,0-2.24,1.33c-.77.52-1.61,1.07-2.51,1.63a27.06,27.06,0,0,1-3.06,1.61,19.87,19.87,0,0,1-3.94,1.24A25.16,25.16,0,0,1,203.8,86.1Zm19.91,0a9.82,9.82,0,0,1-2.2-.24,6.24,6.24,0,0,1-2-.88,6.43,6.43,0,0,1-1.7-1.71,10,10,0,0,1-1.24-2.7l2.7-2a4.85,4.85,0,0,0,1.2,1.82,4,4,0,0,0,1.63.87,7.68,7.68,0,0,0,2,.25,2.13,2.13,0,0,1,1.7.63,2.32,2.32,0,0,1,.54,1.57,2.35,2.35,0,0,1-.65,1.73A2.6,2.6,0,0,1,223.71,86.1Z\"><\/path><path class=\"cls-1\" d=\"M223.71,86.1l.32-4.58a1.9,1.9,0,0,0,1.22-.39,5.06,5.06,0,0,0,1.07-1.38c.38-.67.88-1.61,1.49-2.82a18.89,18.89,0,0,1,1.57-2.66,8.87,8.87,0,0,1,1.66-1.8,6.13,6.13,0,0,1,1.75-1,5.62,5.62,0,0,1,1.88-.31,4.14,4.14,0,0,1,2.34.64,6.32,6.32,0,0,1,1.79,2A20.22,20.22,0,0,1,240.37,77a19.89,19.89,0,0,0,1.07,2.22,6,6,0,0,0,1.31,1.67,2.51,2.51,0,0,0,1.68.63,2.13,2.13,0,0,1,1.7.63,2.32,2.32,0,0,1,.54,1.57,2.35,2.35,0,0,1-.66,1.7,2.56,2.56,0,0,1-1.89.68,6.45,6.45,0,0,1-2.72-.56,5.57,5.57,0,0,1-2.08-1.68l1-.52a5.79,5.79,0,0,1-.84,1.59A4.1,4.1,0,0,1,238,86.12a4.57,4.57,0,0,1-2.08.44,6.83,6.83,0,0,1-1.91-.34,8.06,8.06,0,0,1-2.29-1.15,9.81,9.81,0,0,1-2.31-2.36,8.15,8.15,0,0,1-1.72,2.15,5,5,0,0,1-1.85,1A8.54,8.54,0,0,1,223.71,86.1Zm7.81-7.21a10.71,10.71,0,0,0,.82,1.14,6.15,6.15,0,0,0,1.07,1,6.71,6.71,0,0,0,1.2.74,3.11,3.11,0,0,0,1.25.28,1,1,0,0,0,1-.58,2.5,2.5,0,0,0,0-1.63c-.3-.75-.57-1.38-.79-1.91s-.42-1-.61-1.33a2.33,2.33,0,0,0-.59-.78,1,1,0,0,0-.63-.25,1.43,1.43,0,0,0-1,.47,5.75,5.75,0,0,0-.93,1.21A14.23,14.23,0,0,0,231.52,78.89Z\"><\/path><path class=\"cls-1\" d=\"M244.08,86.1l.32-4.58a3.68,3.68,0,0,0,1.89-.37,1.91,1.91,0,0,0,.71-1.38,15.57,15.57,0,0,0,.09-2.91l-.67-16.69h4.77l.69,17.08a18.61,18.61,0,0,1-.12,3.65,6.26,6.26,0,0,1-1,2.79,5.13,5.13,0,0,1-2.4,1.78A11.79,11.79,0,0,1,244.08,86.1Z\"><\/path><path class=\"cls-1\" d=\"M256.68,85.93,256,60.17h4.76l.73,25.76Z\"><\/path><path class=\"cls-1\" d=\"M273.58,85.23a14.89,14.89,0,0,1,.13-1.89,15.07,15.07,0,0,1,.52-2.45,24.89,24.89,0,0,1,1.21-3.22l4.13,1.54c-.3.79-.55,1.49-.74,2.1a12.61,12.61,0,0,0-.4,1.68,10.62,10.62,0,0,0-.12,1.64,5.07,5.07,0,0,0,.63,2.59,4.17,4.17,0,0,0,1.77,1.66,5.7,5.7,0,0,0,2.64.58,5.94,5.94,0,0,0,3.71-1,5.35,5.35,0,0,0,1.77-3.14,20.78,20.78,0,0,0,.29-5.44l-.66-19.7h4.79l.57,16.73a8.66,8.66,0,0,0,.47,2.88,2.38,2.38,0,0,0,1.24,1.37,5.44,5.44,0,0,0,2.14.37,2.11,2.11,0,0,1,1.67.63,2.48,2.48,0,0,1-.12,3.3,2.61,2.61,0,0,1-1.9.65,6.7,6.7,0,0,1-1.51-.19,6,6,0,0,1-1.61-.63,4.53,4.53,0,0,1-1.35-1.21,4.88,4.88,0,0,1-.82-2l1.75-.28a17.79,17.79,0,0,1-.66,5,10.54,10.54,0,0,1-2,3.83,9,9,0,0,1-3.31,2.45,11.34,11.34,0,0,1-4.58.86,11.88,11.88,0,0,1-3.6-.54,10,10,0,0,1-3.1-1.59,7.06,7.06,0,0,1-2.15-2.72A9.19,9.19,0,0,1,273.58,85.23Z\"><\/path><path class=\"cls-1\" d=\"M297.28,86.1l.35-4.58a6.23,6.23,0,0,0,2-.27,2.64,2.64,0,0,0,1.33-1,7,7,0,0,0,.91-2.27c.24-1,.48-2.35.71-4l4.41.74c0,.37-.11.78-.19,1.24s-.15.92-.21,1.4a11.14,11.14,0,0,0-.09,1.38,3,3,0,0,0,.23,1.19,2.08,2.08,0,0,0,.74.88,4.2,4.2,0,0,0,1.4.56,9.63,9.63,0,0,0,2.18.21,2.13,2.13,0,0,1,1.7.63,2.58,2.58,0,0,1-.12,3.3,2.62,2.62,0,0,1-1.93.65,14.21,14.21,0,0,1-3-.28,5.94,5.94,0,0,1-2.13-.87,4.08,4.08,0,0,1-1.31-1.54,6.71,6.71,0,0,1-.62-2.31l1.58,0a8.35,8.35,0,0,1-1.47,2.68,5.88,5.88,0,0,1-2,1.49,8.14,8.14,0,0,1-2.22.64A15.72,15.72,0,0,1,297.28,86.1Zm3.36,7.81a2.3,2.3,0,0,1-2.31-2.28A2.37,2.37,0,0,1,299,90a2.19,2.19,0,0,1,1.65-.7,2.12,2.12,0,0,1,1.61.7,2.37,2.37,0,0,1,.66,1.68,2.2,2.2,0,0,1-.66,1.59A2.15,2.15,0,0,1,300.64,93.91Zm5.84,0a2.25,2.25,0,0,1-1.68-.69,2.2,2.2,0,0,1-.66-1.59A2.37,2.37,0,0,1,304.8,90a2.23,2.23,0,0,1,1.68-.7,2.09,2.09,0,0,1,1.58.7,2.37,2.37,0,0,1,.66,1.68,2.2,2.2,0,0,1-.66,1.59A2.12,2.12,0,0,1,306.48,93.91Z\"><\/path><path class=\"cls-1\" d=\"M310.65,86.1l.31-4.58a19.23,19.23,0,0,0,3.21-.27,25.31,25.31,0,0,0,3.16-.73,21.38,21.38,0,0,0,3.1-1.21,21.75,21.75,0,0,0,3-1.75,16.13,16.13,0,0,0-2.31-1.1,15.58,15.58,0,0,0-2.29-.67,12,12,0,0,0-2.33-.22q-.56,0-1.08,0c-.35,0-.71.06-1.07.11a7.34,7.34,0,0,0-1.1.21l-.81-4.62a12.76,12.76,0,0,1,1.91-.41,15.43,15.43,0,0,1,1.91-.12,12.58,12.58,0,0,1,3.39.42,15.53,15.53,0,0,1,2.73,1c.82.41,1.56.82,2.23,1.23a18.16,18.16,0,0,0,1.9,1,4.35,4.35,0,0,0,1.82.42h.91l.56,4.27a6.29,6.29,0,0,0-2.27.65,18.75,18.75,0,0,0-2.24,1.33c-.77.52-1.61,1.07-2.5,1.63a26.41,26.41,0,0,1-3.07,1.61,20,20,0,0,1-3.93,1.24A25.26,25.26,0,0,1,310.65,86.1Zm9.59,7.67a2.3,2.3,0,0,1-2.31-2.28,2.37,2.37,0,0,1,.66-1.68,2.23,2.23,0,0,1,1.68-.7,2.12,2.12,0,0,1,1.61.7,2.3,2.3,0,0,1,.67,1.65,2.2,2.2,0,0,1-.67,1.62A2.18,2.18,0,0,1,320.24,93.77Zm10.32-7.67a9.82,9.82,0,0,1-2.2-.24,6.24,6.24,0,0,1-2-.88,6.4,6.4,0,0,1-1.69-1.71,10,10,0,0,1-1.25-2.7l2.7-2a4.86,4.86,0,0,0,1.21,1.82,3.93,3.93,0,0,0,1.62.87,7.68,7.68,0,0,0,2,.25,2.13,2.13,0,0,1,1.7.63,2.61,2.61,0,0,1-.1,3.3A2.61,2.61,0,0,1,330.56,86.1Z\"><\/path><path class=\"cls-1\" d=\"M330.56,86.1l.35-4.58a4.12,4.12,0,0,0,1.47-.23,2.05,2.05,0,0,0,1-1,8.47,8.47,0,0,0,.77-2.17c.23-1,.5-2.27.8-3.9l4.41.81c-.09.51-.22,1.16-.38,2a10,10,0,0,0-.25,2.06,3.39,3.39,0,0,0,.21,1.28,1.55,1.55,0,0,0,.76.8,3.25,3.25,0,0,0,1.55.3,3.5,3.5,0,0,0,1.3-.21,1.89,1.89,0,0,0,.91-.94,9.73,9.73,0,0,0,.73-2.24c.24-1,.47-2.36.7-4.06l4.48.7c-.09.56-.19,1.13-.29,1.73s-.2,1.16-.27,1.7a10.43,10.43,0,0,0-.1,1.33,2.16,2.16,0,0,0,.23,1.06,1.52,1.52,0,0,0,.82.7,4.17,4.17,0,0,0,1.68.27,2.48,2.48,0,0,0,1.94-.72,3.5,3.5,0,0,0,.65-2.36c0-.54,0-1.12,0-1.75s-.07-1.35-.14-2.14-.17-1.68-.31-2.66l4.41-.35c.16,2.08.34,3.77.54,5.08a12.43,12.43,0,0,0,.77,3,3,3,0,0,0,1.23,1.47,3.78,3.78,0,0,0,1.87.42,2.17,2.17,0,0,1,1.73.63,2.61,2.61,0,0,1-.1,3.3,2.63,2.63,0,0,1-1.95.65,8.17,8.17,0,0,1-1.57-.17,5.64,5.64,0,0,1-1.7-.69,5.51,5.51,0,0,1-1.56-1.4,7.39,7.39,0,0,1-1.15-2.32l.73.17a6.09,6.09,0,0,1-1.2,2.61,4.8,4.8,0,0,1-1.91,1.38,7,7,0,0,1-2.52.42,6.88,6.88,0,0,1-2.42-.42A3.61,3.61,0,0,1,347,84.26a4.86,4.86,0,0,1-.7-2.64h1.08a9.17,9.17,0,0,1-1.48,2.89,4,4,0,0,1-1.95,1.28,10.35,10.35,0,0,1-2.76.31,7.45,7.45,0,0,1-2.12-.31,4.42,4.42,0,0,1-2-1.28,6.2,6.2,0,0,1-1.31-2.92l1.92-.07a8.84,8.84,0,0,1-1.89,3.06,4.8,4.8,0,0,1-2.32,1.26A15.12,15.12,0,0,1,330.56,86.1Z\"><\/path><path class=\"cls-1\" d=\"M362.06,86.1l.35-4.58a15.25,15.25,0,0,0,3.1-.25,2.42,2.42,0,0,0,1.54-.86,3,3,0,0,0,.44-1.73,14.35,14.35,0,0,0-.26-2.5c-.18-1-.4-1.91-.67-2.89s-.54-1.88-.82-2.69l4.44-1.3a26.16,26.16,0,0,1,.88,2.77c.28,1.05.52,2.13.72,3.25a19.53,19.53,0,0,1,.29,3.26,8.58,8.58,0,0,1-.75,3.86,5.32,5.32,0,0,1-2.12,2.28A9.22,9.22,0,0,1,366,85.8,24.41,24.41,0,0,1,362.06,86.1Zm3.12-19.88a2.27,2.27,0,0,1-1.65-.66,2.21,2.21,0,0,1-.66-1.61,2.34,2.34,0,0,1,.66-1.65,2.23,2.23,0,0,1,1.68-.7,2.11,2.11,0,0,1,1.58.7,2.28,2.28,0,0,1,.66,1.61,2.29,2.29,0,0,1-2.27,2.31Zm5.84,0a2.26,2.26,0,0,1-1.66-.69,2.18,2.18,0,0,1-.68-1.59,2.37,2.37,0,0,1,.66-1.68,2.23,2.23,0,0,1,1.68-.7,2.09,2.09,0,0,1,1.58.7,2.34,2.34,0,0,1,.66,1.65,2.23,2.23,0,0,1-.66,1.62A2.12,2.12,0,0,1,371,66.26Z\"><\/path><path class=\"cls-1\" d=\"M94.84,56.78H90.77V50.66a20.4,20.4,0,0,0-40.79,0v6.12H45.9a4.06,4.06,0,0,0-4.07,4.08V69a28.54,28.54,0,0,0,26.5,28.47v4.16a4.08,4.08,0,0,0-4.07,4.08v4.08H51A6.12,6.12,0,1,0,51,122H89.75a6.12,6.12,0,0,0,0-12.23H76.49v-4.08a4.08,4.08,0,0,0-4.08-4.08V97.48A28.54,28.54,0,0,0,98.92,69V60.86a4.06,4.06,0,0,0-4.08-4.08Zm-3,59.14a2,2,0,0,1-2,2H51a2,2,0,0,1,0-4.08H89.75a2,2,0,0,1,1.44.59,2.09,2.09,0,0,1,.6,1.45ZM68.33,109.8v-4.08h4.08v4.08ZM94.84,60.86v4.08H90.77V60.86Zm-8.15-10.2v3.06H78.53a2,2,0,0,1,0-4.08h8.16v1Zm0,16.32V70H78.53a2,2,0,1,1,0-4.07h8.16ZM70.37,34.35A16.31,16.31,0,0,1,85.86,45.57H78.53a6.12,6.12,0,1,0,0,12.23h8.16v4.08H78.53a6.12,6.12,0,1,0,0,12.23h7.33a16.31,16.31,0,0,1-31,0h7.33a6.12,6.12,0,1,0,0-12.23H54.06V57.8h8.16a6.12,6.12,0,1,0,0-12.23H54.89A16.29,16.29,0,0,1,70.37,34.35ZM54.06,69V66h8.16a2,2,0,1,1,0,4.07H54.06V69Zm0-19.38h8.16a2,2,0,1,1,0,4.08H54.06V50.66a7,7,0,0,1,0-1ZM45.9,60.86H50v4.08H45.9ZM70.37,93.49A24.48,24.48,0,0,1,45.9,69H50a20.4,20.4,0,0,0,40.79,0h4.07A24.46,24.46,0,0,1,70.37,93.49Z\"><\/path><rect class=\"cls-2\" x=\"0.5\" y=\"0.5\" width=\"520\" height=\"152\"><\/rect><\/svg>\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-border\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-accordion-tab-content\" id=\"premium-accordion-content-1\">\r\n\t\t\t\t\t\t\t\t\t\t<section id=\"section-iconbox-1-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3534\" class=\"elementor elementor-3534 elementor-1309\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3f21d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3f21d4\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5995502\" data-id=\"5995502\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a19ea dce_masking-none elementor-widget elementor-widget-image\" data-id=\"39a19ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"1262\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder.png\" class=\"attachment-full size-full wp-image-4444\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder.png 697w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder-166x300.png 166w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder-566x1024.png 566w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4d7361\" data-id=\"c4d7361\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9d3588f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d3588f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c3761db\" data-id=\"c3761db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ea779b elementor-widget elementor-widget-text-editor\" data-id=\"9ea779b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-1-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p><strong>\u0645\u0647\u0645\u0627 \u0643\u0627\u0646 \u062c\u0647\u0627\u0632\u0643 <\/strong><\/p><p>: \u0625\u0630\u0627 \u0643\u0627\u0646 \u0645\u0632\u0648\u062f\u064b\u0627 \u0628\u0645\u064a\u0643\u0631\u0648\u0641\u0648\u0646 \u0623\u0648 \u062e\u0637 \u0625\u062f\u062e\u0627\u0644 \u060c \u0641\u0625\u0646 Colmena \u062a\u0642\u0648\u0645 \u0628\u062a\u062d\u0648\u064a\u0644\u0647 \u0625\u0644\u0649 \u0645\u0633\u062c\u0644 \u0635\u0648\u062a \u0645\u0639 \u0645\u0642\u064a\u0627\u0633 vu \u0648\u0636\u063a\u0637 \u0627\u0644\u062c\u0648\u062f\u0629.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/section>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-tabs-nav-list-item elementor-repeater-item-1910df0\" data-list-index=\"2\" data-content-id=\"#premium-accordion-content-2\">\r\n\t\t\t\t\t\t\t\t<a class=\"premium-tab-link\" aria-label=\"#section-2-09e7e9d\" href=\"#section-iconbox-2-09e7e9d\">\r\n\r\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 521 153\"><defs><style>.cls-1{fill:#fff;}.cls-2{fill:none;}<\/style><\/defs><path class=\"cls-1\" d=\"M144.37,84.82a18.85,18.85,0,0,1,.12-1.91,16.74,16.74,0,0,1,.54-2.64,24,24,0,0,1,1.19-3.22l4.17,1.51c-.31.81-.56,1.55-.76,2.2a16.34,16.34,0,0,0-.42,1.77,9.84,9.84,0,0,0-.12,1.49,4.81,4.81,0,0,0,.41,2,4.18,4.18,0,0,0,1.17,1.52,5,5,0,0,0,1.91,1,9.83,9.83,0,0,0,2.64.32,13.51,13.51,0,0,0,3.2-.28,9.28,9.28,0,0,0,2.33-.83,4.2,4.2,0,0,0,1.4-1.1,1.88,1.88,0,0,0,.45-1.12.91.91,0,0,0-.22-.56,3.06,3.06,0,0,0-.74-.58,12.88,12.88,0,0,0-1.35-.63c-.56-.22-1.26-.46-2.1-.71l1.26-4.52,2.84,1c.86.32,1.67.58,2.43.79a19.23,19.23,0,0,0,2.08.47,15.16,15.16,0,0,0,1.75.2,2.06,2.06,0,0,1,1.66.63,2.28,2.28,0,0,1,.55,1.57,2.33,2.33,0,0,1-.65,1.73,2.56,2.56,0,0,1-1.91.65h-.4a2.82,2.82,0,0,1-.42,0H167c0,.21.05.39.09.56a2.63,2.63,0,0,1,.05.49,4.4,4.4,0,0,1-.75,2.32,7.72,7.72,0,0,1-2.22,2.24,12.39,12.39,0,0,1-3.71,1.68,19,19,0,0,1-5.32.65,15.65,15.65,0,0,1-5.78-1,8,8,0,0,1-3.73-2.89A8.17,8.17,0,0,1,144.37,84.82Zm8,16.49A2.32,2.32,0,0,1,150.07,99a2.34,2.34,0,0,1,.67-1.68,2.2,2.2,0,0,1,1.68-.7,2.16,2.16,0,0,1,1.59.7,2.31,2.31,0,0,1,.68,1.65,2.34,2.34,0,0,1-2.31,2.31Zm5.85,0A2.3,2.3,0,0,1,155.92,99a2.37,2.37,0,0,1,.66-1.68,2.21,2.21,0,0,1,1.68-.7,2,2,0,0,1,1.56.7,2.37,2.37,0,0,1,.65,1.65,2.2,2.2,0,0,1-.67,1.62A2.11,2.11,0,0,1,158.23,101.31Z\"><\/path><path class=\"cls-1\" d=\"M184.83,86a33,33,0,0,1-4.87-.3,16.05,16.05,0,0,1-3.24-.78,5.76,5.76,0,0,1-2-1.25A7.12,7.12,0,0,1,173.45,82l1-.24a7,7,0,0,1-1.87,2.43,5.8,5.8,0,0,1-2.19,1.1,8.91,8.91,0,0,1-2.2.28l.35-4.58a2.5,2.5,0,0,0,1.43-.37,2.77,2.77,0,0,0,.88-1.19,13.86,13.86,0,0,0,.66-2.22c.21-.94.5-2.08.88-3.43l4.34,1.08c-.17.63-.3,1.18-.41,1.65s-.18.87-.24,1.2a5.13,5.13,0,0,0-.09.86,2.37,2.37,0,0,0,.3,1.24,2.19,2.19,0,0,0,1.14.84,10,10,0,0,0,2.46.53,37.58,37.58,0,0,0,4.26.19,27.52,27.52,0,0,0,4.35-.28,10.67,10.67,0,0,0,2.75-.75,3.33,3.33,0,0,0,1.47-1.19,3,3,0,0,0,.46-1.59,2.61,2.61,0,0,0-.3-1.26,2.4,2.4,0,0,0-.86-.93,2.45,2.45,0,0,0-1.4-.37,4.58,4.58,0,0,0-2.19.6,10.21,10.21,0,0,0-2.17,1.61,21.83,21.83,0,0,0-2,2.22c-.66.8-1.26,1.62-1.82,2.43l-4.8-.59a38.68,38.68,0,0,1,2.91-4.24,27.27,27.27,0,0,1,3.3-3.52,15.75,15.75,0,0,1,3.56-2.39,8.38,8.38,0,0,1,3.71-.88,7.12,7.12,0,0,1,3.6.89A6.14,6.14,0,0,1,197,73.64a7.72,7.72,0,0,1,.84,3.66,7.6,7.6,0,0,1-1.4,4.55,9.08,9.08,0,0,1-4.29,3.06A21,21,0,0,1,184.83,86ZM190,66.83a2.27,2.27,0,0,1-1.66-.68,2.21,2.21,0,0,1-.68-1.63,2.33,2.33,0,0,1,.68-1.71,2.26,2.26,0,0,1,1.7-.7,2.16,2.16,0,0,1,1.62.7,2.29,2.29,0,0,1,.69,1.68A2.34,2.34,0,0,1,190,66.83Z\"><\/path><path class=\"cls-1\" d=\"M202.05,85.42l-.74-25.76h4.76l.74,25.76Z\"><\/path><path class=\"cls-1\" d=\"M208.94,93.5l-2.41-4.41a19.23,19.23,0,0,0,2.9-1.66,12.34,12.34,0,0,0,2.12-1.87,7,7,0,0,0,1.28-2.1,6.74,6.74,0,0,0,.42-2.38,9.31,9.31,0,0,0-.65-3.26,38.37,38.37,0,0,0-1.59-3.6L215.42,72a21.23,21.23,0,0,1,1,2.17c.3.75.56,1.45.79,2.1s.41,1.2.53,1.65a4.28,4.28,0,0,0,1.4,2.41,3.88,3.88,0,0,0,2.38.67,2.1,2.1,0,0,1,1.69.63,2.28,2.28,0,0,1,.55,1.57,2.33,2.33,0,0,1-.65,1.73,2.6,2.6,0,0,1-1.94.65,5.23,5.23,0,0,1-2.19-.44,3.7,3.7,0,0,1-1.59-1.26,5,5,0,0,1-.84-1.83l1.36-.63a11.09,11.09,0,0,1-.65,3.6,12.38,12.38,0,0,1-1.73,3.24,15.32,15.32,0,0,1-2.76,2.83A21.12,21.12,0,0,1,208.94,93.5Z\"><\/path><path class=\"cls-1\" d=\"M221.16,85.59l.35-4.58a6.12,6.12,0,0,0,2-.27,2.55,2.55,0,0,0,1.33-1,6.54,6.54,0,0,0,.91-2.27,40.06,40.06,0,0,0,.72-4l4.41.74c0,.37-.11.78-.19,1.24s-.15.92-.21,1.4a11.14,11.14,0,0,0-.09,1.38,3,3,0,0,0,.23,1.19,2.08,2.08,0,0,0,.74.88,4.13,4.13,0,0,0,1.39.56,9.79,9.79,0,0,0,2.19.21,2.13,2.13,0,0,1,1.7.63,2.28,2.28,0,0,1,.54,1.54,2.35,2.35,0,0,1-.66,1.76,2.64,2.64,0,0,1-1.93.65,14.21,14.21,0,0,1-3-.28,5.77,5.77,0,0,1-2.13-.87,4.19,4.19,0,0,1-1.32-1.54,6.72,6.72,0,0,1-.61-2.31l1.58,0a8.35,8.35,0,0,1-1.47,2.68,6,6,0,0,1-2,1.49,8.24,8.24,0,0,1-2.22.64A15.82,15.82,0,0,1,221.16,85.59Zm4.34-16.06a2.29,2.29,0,0,1-1.67-.67,2.18,2.18,0,0,1-.68-1.61,2.34,2.34,0,0,1,.67-1.66,2.18,2.18,0,0,1,1.68-.72,2.12,2.12,0,0,1,1.61.72,2.34,2.34,0,0,1,.66,1.63,2.23,2.23,0,0,1-.66,1.64A2.18,2.18,0,0,1,225.5,69.53Zm5.81,0A2.29,2.29,0,0,1,229,67.29a2.34,2.34,0,0,1,.66-1.68,2.23,2.23,0,0,1,1.68-.7,2.11,2.11,0,0,1,1.58.7,2.3,2.3,0,0,1,.66,1.64,2.25,2.25,0,0,1-.68,1.63A2.21,2.21,0,0,1,231.31,69.56Z\"><\/path><path class=\"cls-1\" d=\"M234.53,85.59l.31-4.58c1,0,1.95,0,2.78,0s1.57-.06,2.21-.1a15.19,15.19,0,0,0,1.73-.23,4.94,4.94,0,0,0,1.3-.44,3,3,0,0,0,1-1,4.3,4.3,0,0,0,.61-1.59,12.52,12.52,0,0,0,.19-2.38,15.43,15.43,0,0,0-.24-3,4.53,4.53,0,0,0-.76-1.86,1.45,1.45,0,0,0-1.17-.64,1.36,1.36,0,0,0-.93.4,3,3,0,0,0-.71,1.1,4.39,4.39,0,0,0-.28,1.65A1.83,1.83,0,0,0,240.9,74a1.56,1.56,0,0,0,.75.61,2.85,2.85,0,0,0,1.1.19,6.08,6.08,0,0,0,1.35-.17,6.63,6.63,0,0,0,1.42-.53l.14,3.5a5.55,5.55,0,0,1-1.18.72,6.18,6.18,0,0,1-1.38.44,8.29,8.29,0,0,1-1.5.14,6.37,6.37,0,0,1-2.86-.62,4.32,4.32,0,0,1-1.9-1.76,5.62,5.62,0,0,1-.67-2.87,9.41,9.41,0,0,1,.46-2.94A8.28,8.28,0,0,1,238,68.13a7,7,0,0,1,2.1-1.84,5.39,5.39,0,0,1,2.72-.68,5.1,5.1,0,0,1,3.5,1.27,8,8,0,0,1,2.17,3.52,16.66,16.66,0,0,1,.73,5.18,13.15,13.15,0,0,1-.8,4.8,6.65,6.65,0,0,1-2.49,3.15,7.71,7.71,0,0,1-2.06,1.06,14.11,14.11,0,0,1-2.56.62,29.66,29.66,0,0,1-3.08.29C237.08,85.56,235.86,85.59,234.53,85.59Zm8.15-23.41a2.24,2.24,0,0,1-1.66-.69,2.18,2.18,0,0,1-.68-1.62,2.35,2.35,0,0,1,.68-1.72,2.29,2.29,0,0,1,1.7-.7,2.2,2.2,0,0,1,1.62.7,2.32,2.32,0,0,1,.69,1.68,2.36,2.36,0,0,1-2.35,2.35Z\"><\/path><path class=\"cls-1\" d=\"M263.23,66.66a19.87,19.87,0,0,0-.13-2.31c-.08-.77-.18-1.5-.29-2.19s-.23-1.29-.32-1.8l4.69-.7c.09.46.19,1.08.28,1.85s.18,1.58.25,2.43.1,1.67.1,2.44a15.4,15.4,0,0,1-.3,3.08,13.3,13.3,0,0,1-.89,2.83,20.49,20.49,0,0,1-1.4,2.66l-.73,1a21.65,21.65,0,0,1-2,2.48A33.24,33.24,0,0,1,260,80.83h2a8.31,8.31,0,0,0,1.89-.16,1.51,1.51,0,0,0,.89-.45,1.06,1.06,0,0,0,.23-.68,3.51,3.51,0,0,0-1-2,29,29,0,0,0-2.84-2.83c-1.2-1.08-2.59-2.21-4.18-3.42s-3.29-2.42-5.11-3.65l2.38-3.75q3.81,2.56,6.51,4.69a50.75,50.75,0,0,1,4.43,3.89,22.66,22.66,0,0,1,2.69,3.18,11.29,11.29,0,0,1,1.35,2.57,6.44,6.44,0,0,1,.39,2,5.94,5.94,0,0,1-.32,1.94,4.41,4.41,0,0,1-1,1.65A5,5,0,0,1,266.38,85a8,8,0,0,1-2.77.42h-9.34V80.73a39,39,0,0,0,5.18-4.9,17.37,17.37,0,0,0,2.87-4.55A12.35,12.35,0,0,0,263.23,66.66Z\"><\/path><path class=\"cls-1\" d=\"M274.43,85.42l-.74-25.76h4.76l.74,25.76Z\"><\/path><path class=\"cls-1\" d=\"M292.1,93.47l-1-4.45a32.17,32.17,0,0,0,4-.79,10.08,10.08,0,0,0,3-1.27,5.24,5.24,0,0,0,1.84-2.14,7.45,7.45,0,0,0,.59-3.32,11.13,11.13,0,0,0-.52-4c-.38-1-.91-1.47-1.61-1.47a1.32,1.32,0,0,0-1,.49,3.25,3.25,0,0,0-.63,1.23,5.33,5.33,0,0,0-.21,1.47,2.48,2.48,0,0,0,.18,1,1.26,1.26,0,0,0,.71.66,4.31,4.31,0,0,0,1.63.28,19.83,19.83,0,0,0,2.91-.17h5.39a2.17,2.17,0,0,1,1.69.63,2.21,2.21,0,0,1,.58,1.57,2.3,2.3,0,0,1-.66,1.75,2.72,2.72,0,0,1-1.93.63h-7.56a11.43,11.43,0,0,1-4-.63,5.15,5.15,0,0,1-2.52-1.87,5.23,5.23,0,0,1-.86-3,9.79,9.79,0,0,1,.49-3,11.22,11.22,0,0,1,1.37-2.83A6.87,6.87,0,0,1,296,72.12a4.82,4.82,0,0,1,2.68-.77,5,5,0,0,1,3.43,1.27,8.22,8.22,0,0,1,2.2,3.5,16.15,16.15,0,0,1,.81,5,12.35,12.35,0,0,1-1.68,6.53,10.91,10.91,0,0,1-4.55,4A19.8,19.8,0,0,1,292.1,93.47Z\"><\/path><path class=\"cls-1\" d=\"M307,85.59l.35-4.58a14.62,14.62,0,0,0,3.1-.25A2.45,2.45,0,0,0,312,79.9a2.93,2.93,0,0,0,.44-1.73,13.53,13.53,0,0,0-.27-2.5c-.17-1-.39-1.91-.66-2.89s-.54-1.88-.82-2.69l4.44-1.3c.3.8.6,1.72.88,2.77s.51,2.13.71,3.25a18.56,18.56,0,0,1,.3,3.26,8.58,8.58,0,0,1-.75,3.86,5.32,5.32,0,0,1-2.12,2.28A9.27,9.27,0,0,1,311,85.29,24.2,24.2,0,0,1,307,85.59Zm2.49,7.81a2.3,2.3,0,0,1-2.31-2.28,2.37,2.37,0,0,1,.66-1.68,2.2,2.2,0,0,1,1.68-.7,2.11,2.11,0,0,1,1.58.7,2.34,2.34,0,0,1,.66,1.65,2.21,2.21,0,0,1-.68,1.62A2.18,2.18,0,0,1,309.5,93.4Zm5.81,0A2.3,2.3,0,0,1,313,91.12a2.37,2.37,0,0,1,.66-1.68,2.2,2.2,0,0,1,1.68-.7,2.11,2.11,0,0,1,1.58.7,2.34,2.34,0,0,1,.66,1.65,2.23,2.23,0,0,1-.66,1.62A2.16,2.16,0,0,1,315.31,93.4Z\"><\/path><path class=\"cls-1\" d=\"M320.21,84.47l1.05-4.34a11.8,11.8,0,0,0,2.29.58,14.3,14.3,0,0,0,2.19.19,5.49,5.49,0,0,0,1.62-.21,2,2,0,0,0,1.05-.68,2,2,0,0,0,.37-1.24,7.77,7.77,0,0,0-.28-1.89A15.24,15.24,0,0,0,327.33,74a42.79,42.79,0,0,0-2.71-4.43L329,67a52.68,52.68,0,0,1,2.7,4.69,30.7,30.7,0,0,1,1.71,4.1,10.73,10.73,0,0,1,.6,3.25,6.88,6.88,0,0,1-.79,3.22,5.8,5.8,0,0,1-2.5,2.42,9.75,9.75,0,0,1-4.52.91,17.47,17.47,0,0,1-2.05-.13,13.45,13.45,0,0,1-2.17-.4A9.38,9.38,0,0,1,320.21,84.47Z\"><\/path><path class=\"cls-1\" d=\"M337.11,93.47l-1-4.45a32,32,0,0,0,4-.79,10.08,10.08,0,0,0,3-1.27,5.24,5.24,0,0,0,1.84-2.14,7.59,7.59,0,0,0,.59-3.32,11.13,11.13,0,0,0-.52-4c-.38-1-.91-1.47-1.61-1.47a1.32,1.32,0,0,0-1,.49,3.25,3.25,0,0,0-.63,1.23,5.33,5.33,0,0,0-.21,1.47,2.48,2.48,0,0,0,.18,1,1.26,1.26,0,0,0,.71.66,4.31,4.31,0,0,0,1.63.28A19.83,19.83,0,0,0,347,81h5.38a2.18,2.18,0,0,1,1.7.63,2.21,2.21,0,0,1,.58,1.57A2.3,2.3,0,0,1,354,85a2.72,2.72,0,0,1-1.93.63h-7.56a11.43,11.43,0,0,1-4-.63,5.15,5.15,0,0,1-2.52-1.87,5.23,5.23,0,0,1-.86-3,9.79,9.79,0,0,1,.49-3,11.54,11.54,0,0,1,1.36-2.83A7,7,0,0,1,341,72.12a4.8,4.8,0,0,1,2.68-.77,5,5,0,0,1,3.42,1.27,8.14,8.14,0,0,1,2.21,3.5,15.86,15.86,0,0,1,.8,5,12.26,12.26,0,0,1-1.67,6.53,10.91,10.91,0,0,1-4.55,4A19.8,19.8,0,0,1,337.11,93.47Z\"><\/path><path class=\"cls-1\" d=\"M352,85.59l.35-4.58a6.23,6.23,0,0,0,2-.27,2.58,2.58,0,0,0,1.33-1,7,7,0,0,0,.91-2.27c.24-1,.48-2.35.71-4l4.41.74c0,.37-.11.78-.19,1.24s-.15.92-.21,1.4a11.14,11.14,0,0,0-.09,1.38,3,3,0,0,0,.23,1.19,2.08,2.08,0,0,0,.74.88,4.2,4.2,0,0,0,1.4.56,9.63,9.63,0,0,0,2.18.21,2.13,2.13,0,0,1,1.7.63,2.28,2.28,0,0,1,.54,1.54,2.35,2.35,0,0,1-.66,1.76,2.62,2.62,0,0,1-1.93.65,14.21,14.21,0,0,1-3-.28,5.77,5.77,0,0,1-2.13-.87A4.08,4.08,0,0,1,359,82.9a6.71,6.71,0,0,1-.62-2.31l1.58,0a8.35,8.35,0,0,1-1.47,2.68,5.88,5.88,0,0,1-2,1.49,8,8,0,0,1-2.22.64A15.72,15.72,0,0,1,352,85.59Zm4.34-16.06a2.26,2.26,0,0,1-1.66-.67,2.15,2.15,0,0,1-.69-1.61,2.39,2.39,0,0,1,.67-1.66,2.18,2.18,0,0,1,1.68-.72,2.11,2.11,0,0,1,1.61.72,2.34,2.34,0,0,1,.66,1.63,2.23,2.23,0,0,1-.66,1.64A2.17,2.17,0,0,1,356.36,69.53Zm5.81,0a2.29,2.29,0,0,1-2.31-2.27,2.34,2.34,0,0,1,.66-1.68,2.23,2.23,0,0,1,1.68-.7,2.09,2.09,0,0,1,1.58.7,2.3,2.3,0,0,1,.66,1.64,2.21,2.21,0,0,1-.68,1.63A2.18,2.18,0,0,1,362.17,69.56Z\"><\/path><path class=\"cls-1\" d=\"M365.39,85.59l.35-4.58a4.42,4.42,0,0,0,1.54-.23,2,2,0,0,0,1-1,8.11,8.11,0,0,0,.77-2.17q.36-1.44.81-3.9l4.38.81c-.08.42-.16.87-.25,1.34s-.18,1-.25,1.46a9.81,9.81,0,0,0-.1,1.4A2,2,0,0,0,376.06,81a3.52,3.52,0,0,0,1.35-.23,1.86,1.86,0,0,0,.91-1,10,10,0,0,0,.7-2.24c.22-1,.46-2.36.72-4.06l4.48.7c-.09.49-.19,1-.3,1.66s-.19,1.2-.26,1.75a11.41,11.41,0,0,0-.11,1.38,2.07,2.07,0,0,0,.25,1,1.76,1.76,0,0,0,.82.74,3.75,3.75,0,0,0,1.56.28,3.7,3.7,0,0,0,1.49-.28,1.92,1.92,0,0,0,.92-.88,3.34,3.34,0,0,0,.32-1.57,14.27,14.27,0,0,0-.56-3.56c-.37-1.38-.83-2.86-1.37-4.42l4.59-1.44c.37,1,.71,2.11,1,3.26s.52,2.25.7,3.32a18.55,18.55,0,0,1,.26,2.84,8.52,8.52,0,0,1-.54,3.15,6.36,6.36,0,0,1-1.53,2.29,6.56,6.56,0,0,1-2.25,1.4,8.18,8.18,0,0,1-2.82.47,7.13,7.13,0,0,1-2.68-.44A3.68,3.68,0,0,1,382,83.74a6.5,6.5,0,0,1-.89-2.63h1.12a8.66,8.66,0,0,1-1.58,3,3.93,3.93,0,0,1-2,1.24,10.45,10.45,0,0,1-2.58.28,8.35,8.35,0,0,1-2.08-.28,3.91,3.91,0,0,1-2-1.26,6.74,6.74,0,0,1-1.33-3l1.89-.07a7.5,7.5,0,0,1-1.83,3,5.32,5.32,0,0,1-2.47,1.29A13.36,13.36,0,0,1,365.39,85.59Z\"><\/path><path class=\"cls-1\" d=\"M408.05,66.66a22.34,22.34,0,0,0-.12-2.31q-.12-1.15-.3-2.19c-.11-.69-.22-1.29-.31-1.8l4.69-.7c.09.46.19,1.08.28,1.85s.17,1.58.24,2.43.11,1.67.11,2.44a15.4,15.4,0,0,1-.3,3.08,13.89,13.89,0,0,1-.89,2.83,20.49,20.49,0,0,1-1.4,2.66l-.74,1a20.64,20.64,0,0,1-2,2.48,33.07,33.07,0,0,1-2.48,2.38h2a8.31,8.31,0,0,0,1.89-.16,1.51,1.51,0,0,0,.89-.45,1.12,1.12,0,0,0,.23-.68,3.57,3.57,0,0,0-1-2,30.19,30.19,0,0,0-2.84-2.83c-1.2-1.08-2.59-2.21-4.18-3.42s-3.29-2.42-5.11-3.65L399,63.89q3.81,2.56,6.51,4.69a50.75,50.75,0,0,1,4.43,3.89,22.66,22.66,0,0,1,2.69,3.18A11.71,11.71,0,0,1,414,78.22a6.41,6.41,0,0,1,.38,2,5.93,5.93,0,0,1-.31,1.94,4.31,4.31,0,0,1-1,1.65A4.8,4.8,0,0,1,411.2,85a7.86,7.86,0,0,1-2.76.42h-9.35V80.73a37.84,37.84,0,0,0,5.18-4.9,16.86,16.86,0,0,0,2.87-4.55A12.15,12.15,0,0,0,408.05,66.66Z\"><\/path><path class=\"cls-1\" d=\"M71.39,26.74A38.52,38.52,0,0,0,32.91,63.18,3.79,3.79,0,0,0,34,66a3.87,3.87,0,0,0,.81.64A36.51,36.51,0,0,0,40,84.21a7.46,7.46,0,0,0-2.55,3.69,7.56,7.56,0,0,0,0,4.49l3,9.53a7.52,7.52,0,0,0,7.16,5.26h.46l5.95-.36h0a6.58,6.58,0,0,0,11.9-5.35L58.57,78.15a6.48,6.48,0,0,0-3.23-3.86,6.55,6.55,0,0,0-5-.44A6.24,6.24,0,0,0,48,75.14a25.39,25.39,0,0,1-2-8.46,3.74,3.74,0,0,0,1.88-3,23.5,23.5,0,0,1,46.88,0,3.77,3.77,0,0,0,1.88,3,25.14,25.14,0,0,1-1.94,8.46,6.36,6.36,0,0,0-2.33-1.29,6.52,6.52,0,0,0-5,.44,6.6,6.6,0,0,0-3.24,3.86l-7.3,23.31a6.58,6.58,0,0,0,11.9,5.35l6,.35h.46a7.52,7.52,0,0,0,7.16-5.26l3-9.53a7.54,7.54,0,0,0-2.55-8.18,36.48,36.48,0,0,0,5.25-17.56,3.87,3.87,0,0,0,.81-.64,3.79,3.79,0,0,0,1-2.82A38.54,38.54,0,0,0,71.39,26.74ZM38.57,67.15h3.76a29,29,0,0,0,3.47,12,6.48,6.48,0,0,0-.06,1.39L43.2,82.17a32.86,32.86,0,0,1-4.63-15Zm11.2,11.67a2.85,2.85,0,0,1,3.81-1.2A2.79,2.79,0,0,1,55,79.28l7.34,23.31a2.78,2.78,0,0,1-.66,2.68,2.82,2.82,0,0,1-2.64.83,2.79,2.79,0,0,1-2.07-1.82L49.6,81a2.82,2.82,0,0,1,.17-2.15Zm-3,5.53,5.89,18.8-4.8.29h0A3.78,3.78,0,0,1,44,100.81l-3-9.57a3.78,3.78,0,0,1,1.62-4.33Zm39.08,19.93A2.84,2.84,0,0,1,84.46,106a2.83,2.83,0,0,1-3.87-1.22,2.83,2.83,0,0,1-.14-2.19l7.34-23.31a2.85,2.85,0,0,1,1.38-1.68A2.86,2.86,0,0,1,93,78.77a2.85,2.85,0,0,1,.21,2.16Zm16-13-3,9.53A3.73,3.73,0,0,1,95,103.4l-4.76-.25L96,84.35l4.1,2.52a3.76,3.76,0,0,1,1.62,4.37Zm-2.22-9.07L97,80.59a6,6,0,0,0-.05-1.4,28.76,28.76,0,0,0,3.47-12h3.76a33,33,0,0,1-4.63,15Zm-1-18.8a27.26,27.26,0,0,0-54.37,0H36.66a34.78,34.78,0,0,1,69.45,0Z\"><\/path><rect class=\"cls-2\" x=\"0.5\" y=\"0.5\" width=\"520\" height=\"152\"><\/rect><\/svg>\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-border\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-accordion-tab-content\" id=\"premium-accordion-content-2\">\r\n\t\t\t\t\t\t\t\t\t\t<section id=\"section-iconbox-2-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3544\" class=\"elementor elementor-3544 elementor-1313\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7545dd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7545dd5\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7c9cedc\" data-id=\"7c9cedc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-571e5d7 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"571e5d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1082\" height=\"1922\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4.png\" class=\"attachment-full size-full wp-image-4782\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4.png 1082w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-576x1024.png 576w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-768x1364.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-865x1536.png 865w\" sizes=\"(max-width: 1082px) 100vw, 1082px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c19e27b\" data-id=\"c19e27b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-2891f6e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2891f6e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-42a1fcb\" data-id=\"42a1fcb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a11853c elementor-widget elementor-widget-text-editor\" data-id=\"a11853c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0645\u0633\u0627\u062d\u062a\u0643 \u0644\u0644\u062a\u0641\u0627\u0639\u0644 \u0645\u0639 \u0627\u0644\u0636\u064a\u0648\u0641 \u0648\u0627\u0644\u062e\u0628\u0631\u0627\u0621 \u0641\u064a \u0645\u0646\u0627\u0642\u0634\u0627\u062a \u0627\u0644\u0645\u0627\u0626\u062f\u0629 \u0627\u0644\u0645\u0633\u062a\u062f\u064a\u0631\u0629 \u0627\u0644\u0627\u0641\u062a\u0631\u0627\u0636\u064a\u0629 \u0648\u0627\u0644\u0645\u0642\u0627\u0628\u0644\u0627\u062a \u0627\u0644\u062c\u0645\u0627\u0639\u064a\u0629 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a. \u064a\u0645\u0643\u0646 \u062a\u0633\u062c\u064a\u0644 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u062d\u0627\u062f\u062b\u0627\u062a \u0623\u0648 \u0645\u0634\u0627\u0631\u0643\u062a\u0647\u0627 \u0645\u0628\u0627\u0634\u0631\u0629 \u0643\u062a\u062f\u0641\u0642\u0627\u062a \u0635\u0648\u062a\u064a\u0629.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/section>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-tabs-nav-list-item elementor-repeater-item-2d93fea\" data-list-index=\"3\" data-content-id=\"#premium-accordion-content-3\">\r\n\t\t\t\t\t\t\t\t<a class=\"premium-tab-link\" aria-label=\"#section-3-09e7e9d\" href=\"#section-iconbox-3-09e7e9d\">\r\n\r\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 521 153\"><defs><style>.cls-1{fill:#fff;}.cls-2{fill:none;}<\/style><\/defs><path class=\"cls-1\" d=\"M144.37,84.76a16.8,16.8,0,0,1,.12-1.89,16.22,16.22,0,0,1,.52-2.45,26.45,26.45,0,0,1,1.21-3.22l4.13,1.54c-.3.79-.55,1.49-.73,2.1a12.74,12.74,0,0,0-.41,1.68,10.62,10.62,0,0,0-.12,1.64,5.21,5.21,0,0,0,.63,2.66,4,4,0,0,0,1.79,1.63,6.27,6.27,0,0,0,2.69.54,6.13,6.13,0,0,0,3-.66A4.33,4.33,0,0,0,159,86.4a9.34,9.34,0,0,0,.81-3.13,32.58,32.58,0,0,0,.12-4.32l-.7-19.25h4.83l.6,19a32.88,32.88,0,0,1-.2,4.74,17.93,17.93,0,0,1-.94,4.08,9.6,9.6,0,0,1-1.91,3.2,8.19,8.19,0,0,1-3.1,2.1,12,12,0,0,1-4.49.75,12.51,12.51,0,0,1-3.61-.52,9.18,9.18,0,0,1-3.11-1.6,7.51,7.51,0,0,1-2.16-2.71A9.12,9.12,0,0,1,144.37,84.76Z\"><\/path><path class=\"cls-1\" d=\"M168.52,93.51l-1-4.45a32,32,0,0,0,4-.79A10,10,0,0,0,174.48,87a5.17,5.17,0,0,0,1.84-2.14,7.44,7.44,0,0,0,.6-3.32,11.1,11.1,0,0,0-.53-4c-.37-1-.91-1.47-1.61-1.47a1.3,1.3,0,0,0-1,.49,3.25,3.25,0,0,0-.63,1.23,5.33,5.33,0,0,0-.21,1.47,2.68,2.68,0,0,0,.17,1,1.31,1.31,0,0,0,.72.66,4.27,4.27,0,0,0,1.63.28,19.64,19.64,0,0,0,2.9-.17h5.39a2.2,2.2,0,0,1,1.7.63,2.25,2.25,0,0,1,.58,1.57,2.3,2.3,0,0,1-.67,1.75,2.68,2.68,0,0,1-1.92.63h-7.56a11.48,11.48,0,0,1-4.05-.63,4.86,4.86,0,0,1-3.37-4.9,9.79,9.79,0,0,1,.49-3,11.2,11.2,0,0,1,1.36-2.83,7,7,0,0,1,2.08-2.08,4.84,4.84,0,0,1,2.68-.77,5,5,0,0,1,3.43,1.27,8.23,8.23,0,0,1,2.21,3.5,15.86,15.86,0,0,1,.8,5,12.17,12.17,0,0,1-1.68,6.53,10.85,10.85,0,0,1-4.55,4A19.8,19.8,0,0,1,168.52,93.51Z\"><\/path><path class=\"cls-1\" d=\"M183.43,85.63l.31-4.58a1.93,1.93,0,0,0,1.23-.39A4.91,4.91,0,0,0,186,79.28c.39-.67.89-1.6,1.49-2.82a20.54,20.54,0,0,1,1.58-2.66,8.86,8.86,0,0,1,1.66-1.8,5.87,5.87,0,0,1,1.75-1,5.56,5.56,0,0,1,1.87-.31,4.2,4.2,0,0,1,2.35.64,6.3,6.3,0,0,1,1.78,2,20.6,20.6,0,0,1,1.58,3.25,19.07,19.07,0,0,0,1.06,2.22,6.17,6.17,0,0,0,1.32,1.67,2.51,2.51,0,0,0,1.68.63,2.1,2.1,0,0,1,1.69.63,2.28,2.28,0,0,1,.55,1.57,2.32,2.32,0,0,1-.67,1.7,2.53,2.53,0,0,1-1.89.68,6.26,6.26,0,0,1-2.71-.56A5.5,5.5,0,0,1,199,83.39l.94-.52a5.79,5.79,0,0,1-.84,1.59,3.92,3.92,0,0,1-1.42,1.19,4.54,4.54,0,0,1-2.08.44,6.54,6.54,0,0,1-1.91-.34,8.19,8.19,0,0,1-2.29-1.15,10.19,10.19,0,0,1-2.31-2.36,8.14,8.14,0,0,1-1.71,2.15,5.07,5.07,0,0,1-1.86,1A8.4,8.4,0,0,1,183.43,85.63Zm7.8-7.21a11.12,11.12,0,0,0,.82,1.14,6.52,6.52,0,0,0,1.07,1,6.25,6.25,0,0,0,1.21.74,3.06,3.06,0,0,0,1.24.28,1,1,0,0,0,1-.58,2.49,2.49,0,0,0,0-1.63l-.79-1.91c-.22-.52-.43-1-.61-1.33a2.34,2.34,0,0,0-.6-.78,1,1,0,0,0-.63-.25,1.45,1.45,0,0,0-1,.47,6.1,6.1,0,0,0-.93,1.21A16.1,16.1,0,0,0,191.23,78.42Z\"><\/path><path class=\"cls-1\" d=\"M203.8,85.63l.31-4.58a19.11,19.11,0,0,0,3.2-.27,25.46,25.46,0,0,0,3.17-.73,21.84,21.84,0,0,0,3.1-1.21,22.36,22.36,0,0,0,3-1.75,16.13,16.13,0,0,0-2.31-1.1,15.58,15.58,0,0,0-2.29-.67,12,12,0,0,0-2.33-.22q-.55,0-1.08,0c-.35,0-.71.06-1.07.11a7.34,7.34,0,0,0-1.1.21l-.81-4.62a12.76,12.76,0,0,1,1.91-.41,15.43,15.43,0,0,1,1.91-.12,12.58,12.58,0,0,1,3.39.42,16.16,16.16,0,0,1,2.73,1q1.23.61,2.22,1.23a18.25,18.25,0,0,0,1.91,1,4.31,4.31,0,0,0,1.82.42h.91l.56,4.27a6.29,6.29,0,0,0-2.27.65,18,18,0,0,0-2.24,1.33c-.77.52-1.61,1.07-2.51,1.63a27.06,27.06,0,0,1-3.06,1.61,19.87,19.87,0,0,1-3.94,1.24A25.16,25.16,0,0,1,203.8,85.63Zm19.91,0a9.82,9.82,0,0,1-2.2-.24,6.24,6.24,0,0,1-2-.88,6.43,6.43,0,0,1-1.7-1.71,9.81,9.81,0,0,1-1.24-2.7l2.7-2a4.85,4.85,0,0,0,1.2,1.82,4,4,0,0,0,1.63.87,7.26,7.26,0,0,0,2,.25,2.13,2.13,0,0,1,1.7.63,2.59,2.59,0,0,1-.11,3.3A2.6,2.6,0,0,1,223.71,85.63Z\"><\/path><path class=\"cls-1\" d=\"M223.71,85.63l.32-4.58a1.9,1.9,0,0,0,1.22-.39,4.91,4.91,0,0,0,1.07-1.38c.38-.67.88-1.6,1.49-2.82a19.48,19.48,0,0,1,1.57-2.66A9.15,9.15,0,0,1,231,72a6.13,6.13,0,0,1,1.75-1,5.62,5.62,0,0,1,1.88-.31,4.14,4.14,0,0,1,2.34.64,6.32,6.32,0,0,1,1.79,2,20.64,20.64,0,0,1,1.57,3.25,19.08,19.08,0,0,0,1.07,2.22,6,6,0,0,0,1.31,1.67,2.51,2.51,0,0,0,1.68.63,2.13,2.13,0,0,1,1.7.63,2.32,2.32,0,0,1,.54,1.57A2.35,2.35,0,0,1,246,85a2.56,2.56,0,0,1-1.89.68,6.3,6.3,0,0,1-2.72-.56,5.57,5.57,0,0,1-2.08-1.68l1-.52a5.79,5.79,0,0,1-.84,1.59A4.1,4.1,0,0,1,238,85.65a4.57,4.57,0,0,1-2.08.44,6.48,6.48,0,0,1-1.91-.34,8.06,8.06,0,0,1-2.29-1.15,9.81,9.81,0,0,1-2.31-2.36,8.15,8.15,0,0,1-1.72,2.15,5,5,0,0,1-1.85,1A8.54,8.54,0,0,1,223.71,85.63Zm7.81-7.21a9.78,9.78,0,0,0,.82,1.14,6.78,6.78,0,0,0,2.27,1.77,3.11,3.11,0,0,0,1.25.28,1,1,0,0,0,1-.58,2.5,2.5,0,0,0,0-1.63c-.3-.74-.57-1.38-.79-1.91s-.42-1-.61-1.33a2.33,2.33,0,0,0-.59-.78,1,1,0,0,0-.63-.25,1.43,1.43,0,0,0-1,.47,5.75,5.75,0,0,0-.93,1.21A14.23,14.23,0,0,0,231.52,78.42Z\"><\/path><path class=\"cls-1\" d=\"M244.08,85.63l.32-4.58a3.68,3.68,0,0,0,1.89-.37A1.91,1.91,0,0,0,247,79.3a15.57,15.57,0,0,0,.09-2.91l-.67-16.69h4.77l.69,17.08a18.61,18.61,0,0,1-.12,3.65,6.26,6.26,0,0,1-1,2.79,5.13,5.13,0,0,1-2.4,1.78A11.79,11.79,0,0,1,244.08,85.63Z\"><\/path><path class=\"cls-1\" d=\"M256.68,85.46,256,59.7h4.76l.73,25.76Z\"><\/path><path class=\"cls-1\" d=\"M286.08,86.19a24.07,24.07,0,0,1-5.58-.56A10.62,10.62,0,0,1,276.77,84a6.09,6.09,0,0,1-2.08-2.49,7.83,7.83,0,0,1-.65-3.23,13.75,13.75,0,0,1,.19-2.21,18.21,18.21,0,0,1,.53-2.29c.22-.74.41-1.39.57-2l4.06,1c-.11.42-.24.88-.38,1.37a9.63,9.63,0,0,0-.31,1.47,9.09,9.09,0,0,0-.11,1.47,3.86,3.86,0,0,0,.7,2.24,4.72,4.72,0,0,0,2.5,1.59,18,18,0,0,0,5.17.58l.7,3.5ZM285.62,70a2.25,2.25,0,0,1-2.3-2.27,2.4,2.4,0,0,1,.66-1.67,2.2,2.2,0,0,1,1.68-.71,2.12,2.12,0,0,1,1.58.71,2.36,2.36,0,0,1,.66,1.63A2.25,2.25,0,0,1,285.62,70Zm.46,16.17.91-4.58q2.86,0,5-.21a18,18,0,0,0,3.64-.67,5.57,5.57,0,0,0,2.2-1.14,2.1,2.1,0,0,0,.74-1.62,13.84,13.84,0,0,0-.42-3.17,34.23,34.23,0,0,0-1.08-3.62l4.34-1.33c.3.79.59,1.66.87,2.6a26.37,26.37,0,0,1,.68,2.86,14.46,14.46,0,0,1,.26,2.69,6.82,6.82,0,0,1-1,3.68,7.16,7.16,0,0,1-3,2.55A18.23,18.23,0,0,1,294,85.72,56.78,56.78,0,0,1,286.08,86.19ZM291.43,70a2.23,2.23,0,0,1-1.64-.66,2.19,2.19,0,0,1-.67-1.58,2.38,2.38,0,0,1,.67-1.68,2.23,2.23,0,0,1,1.68-.7,2.1,2.1,0,0,1,1.59.7,2.37,2.37,0,0,1,.65,1.65A2.27,2.27,0,0,1,291.43,70Z\"><\/path><path class=\"cls-1\" d=\"M306.87,93.51l-1-4.45a32,32,0,0,0,4-.79,10.2,10.2,0,0,0,3-1.27,5.22,5.22,0,0,0,1.83-2.14,7.44,7.44,0,0,0,.6-3.32,10.88,10.88,0,0,0-.53-4c-.37-1-.91-1.47-1.61-1.47a1.31,1.31,0,0,0-1,.49,3.25,3.25,0,0,0-.63,1.23,5.33,5.33,0,0,0-.21,1.47,2.68,2.68,0,0,0,.17,1,1.31,1.31,0,0,0,.72.66,4.31,4.31,0,0,0,1.63.28,19.64,19.64,0,0,0,2.9-.17h5.39a2.18,2.18,0,0,1,1.7.63,2.21,2.21,0,0,1,.58,1.57A2.27,2.27,0,0,1,323.7,85a2.68,2.68,0,0,1-1.92.63h-7.56a11.39,11.39,0,0,1-4-.63,4.88,4.88,0,0,1-3.38-4.9,9.79,9.79,0,0,1,.49-3,11.54,11.54,0,0,1,1.36-2.83,7,7,0,0,1,2.09-2.08,4.79,4.79,0,0,1,2.67-.77,5,5,0,0,1,3.43,1.27,8.14,8.14,0,0,1,2.21,3.5,15.86,15.86,0,0,1,.8,5,12.17,12.17,0,0,1-1.68,6.53,10.79,10.79,0,0,1-4.55,4A19.67,19.67,0,0,1,306.87,93.51Z\"><\/path><path class=\"cls-1\" d=\"M338.44,86.05a33,33,0,0,1-4.87-.3,15.77,15.77,0,0,1-3.23-.78,5.58,5.58,0,0,1-2-1.25,6.89,6.89,0,0,1-1.25-1.66l1-.24a6.87,6.87,0,0,1-1.87,2.43,5.8,5.8,0,0,1-2.19,1.1,8.85,8.85,0,0,1-2.2.28l.35-4.58a2.5,2.5,0,0,0,1.43-.37,2.69,2.69,0,0,0,.88-1.19,13.86,13.86,0,0,0,.66-2.22c.21-.94.5-2.08.88-3.43l4.34,1.08c-.16.63-.3,1.18-.4,1.65s-.19.87-.25,1.2a5.13,5.13,0,0,0-.09.86,2.44,2.44,0,0,0,.3,1.25,2.23,2.23,0,0,0,1.14.83,10,10,0,0,0,2.47.53,37.27,37.27,0,0,0,4.25.19,27.75,27.75,0,0,0,4.36-.28,10.58,10.58,0,0,0,2.74-.75,3.33,3.33,0,0,0,1.47-1.19,2.87,2.87,0,0,0,.46-1.59,2.61,2.61,0,0,0-.3-1.26,2.4,2.4,0,0,0-.86-.93,2.45,2.45,0,0,0-1.4-.37,4.51,4.51,0,0,0-2.18.6,9.74,9.74,0,0,0-2.17,1.61,20.81,20.81,0,0,0-2.05,2.22c-.65.8-1.26,1.62-1.82,2.43l-4.8-.59a38.68,38.68,0,0,1,2.91-4.24,26.65,26.65,0,0,1,3.31-3.52A15.7,15.7,0,0,1,341,71.18a8.38,8.38,0,0,1,3.71-.88,7.09,7.09,0,0,1,3.6.89,6.14,6.14,0,0,1,2.38,2.49,7.72,7.72,0,0,1,.84,3.66,7.6,7.6,0,0,1-1.4,4.55A9.1,9.1,0,0,1,345.81,85,21.09,21.09,0,0,1,338.44,86.05Zm15.33-.42a10,10,0,0,1-2.71-.37,13.06,13.06,0,0,1-2.47-.92,8.22,8.22,0,0,1-1.86-1.23L349.67,80a7.91,7.91,0,0,0,2.14.8,10.12,10.12,0,0,0,2.27.25,2.2,2.2,0,0,1,1.72.63,2.53,2.53,0,0,1-.11,3.3A2.6,2.6,0,0,1,353.77,85.63Z\"><\/path><path class=\"cls-1\" d=\"M353.77,85.63l.31-4.58a3.63,3.63,0,0,0,1.89-.37,1.89,1.89,0,0,0,.72-1.38,15.57,15.57,0,0,0,.09-2.91l-.67-16.69h4.76l.7,17.08a19.42,19.42,0,0,1-.12,3.65,6.26,6.26,0,0,1-1,2.79A5.13,5.13,0,0,1,358,85,11.79,11.79,0,0,1,353.77,85.63Z\"><\/path><path class=\"cls-1\" d=\"M366.37,85.46l-.74-25.76h4.76l.74,25.76Z\"><\/path><path class=\"cls-1\" d=\"M383,93.51l-2.17-4.41a16.41,16.41,0,0,0,3.8-2.37,7.64,7.64,0,0,0,2.05-2.64,7.13,7.13,0,0,0,.63-3A8.92,8.92,0,0,0,387,79a16.12,16.12,0,0,0-.79-2.26q-.51-1.17-1.17-2.46l4.41-2.21a31.15,31.15,0,0,1,2,4.67,13.77,13.77,0,0,1,.63,4,14.12,14.12,0,0,1-.32,3,11.67,11.67,0,0,1-1,2.8A13.29,13.29,0,0,1,389,89.17a15.17,15.17,0,0,1-2.55,2.31A23.51,23.51,0,0,1,383,93.51Z\"><\/path><path class=\"cls-1\" d=\"M395.63,93.54l-2.42-4.41a18.87,18.87,0,0,0,2.91-1.66,11.85,11.85,0,0,0,2.11-1.87,6.82,6.82,0,0,0,1.28-2.1,6.74,6.74,0,0,0,.42-2.38,9.08,9.08,0,0,0-.65-3.26,38.37,38.37,0,0,0-1.59-3.6l4.41-2.21a19.34,19.34,0,0,1,1,2.17c.29.75.55,1.45.79,2.1s.4,1.2.52,1.65a4.39,4.39,0,0,0,1.4,2.41,3.9,3.9,0,0,0,2.38.67,2.13,2.13,0,0,1,1.7.63,2.32,2.32,0,0,1,.54,1.57,2.29,2.29,0,0,1-.65,1.73,2.59,2.59,0,0,1-1.94.65,5.29,5.29,0,0,1-2.19-.44,3.82,3.82,0,0,1-1.59-1.26,5.18,5.18,0,0,1-.84-1.83l1.37-.63a11.36,11.36,0,0,1-.65,3.6,13,13,0,0,1-1.73,3.24,15.07,15.07,0,0,1-2.77,2.83A21.38,21.38,0,0,1,395.63,93.54Z\"><\/path><path class=\"cls-1\" d=\"M407.84,85.63l.32-4.58a19.11,19.11,0,0,0,3.2-.27,25.46,25.46,0,0,0,3.17-.73,21.26,21.26,0,0,0,3.09-1.21,21.85,21.85,0,0,0,3-1.75,16.13,16.13,0,0,0-2.31-1.1,15.7,15.7,0,0,0-2.3-.67,11.85,11.85,0,0,0-2.32-.22c-.38,0-.74,0-1.09,0s-.7.06-1.07.11a7.34,7.34,0,0,0-1.1.21l-.8-4.62a12.63,12.63,0,0,1,1.9-.41,15.55,15.55,0,0,1,1.91-.12,12.71,12.71,0,0,1,3.4.42,16.16,16.16,0,0,1,2.73,1q1.21.61,2.22,1.23a17.3,17.3,0,0,0,1.91,1,4.28,4.28,0,0,0,1.82.42h.91L427,78.7a6.28,6.28,0,0,0-2.28.65,18.75,18.75,0,0,0-2.24,1.33c-.77.52-1.6,1.07-2.5,1.63a27.06,27.06,0,0,1-3.06,1.61A20.3,20.3,0,0,1,413,85.16,25.19,25.19,0,0,1,407.84,85.63Zm19.92,0a9.91,9.91,0,0,1-2.21-.24,6.19,6.19,0,0,1-2-.88,6.43,6.43,0,0,1-1.7-1.71,9.53,9.53,0,0,1-1.24-2.7l2.69-2a4.86,4.86,0,0,0,1.21,1.82,4,4,0,0,0,1.63.87,7.21,7.21,0,0,0,2,.25,2.1,2.1,0,0,1,1.69.63,2.28,2.28,0,0,1,.55,1.57A2.33,2.33,0,0,1,429.7,85,2.6,2.6,0,0,1,427.76,85.63Z\"><\/path><path class=\"cls-1\" d=\"M427.76,85.63l.31-4.58a1.9,1.9,0,0,0,1.28-.46,5,5,0,0,0,1.1-1.5c.38-.7.82-1.62,1.33-2.77A14.63,14.63,0,0,1,433.72,73a6.45,6.45,0,0,1,2.07-1.7,5.29,5.29,0,0,1,2.26-.5,5,5,0,0,1,2.57.68,6.6,6.6,0,0,1,2,1.85A9.91,9.91,0,0,1,444,76a9.51,9.51,0,0,1,.49,3,7.76,7.76,0,0,1-.74,3.48,5.6,5.6,0,0,1-2,2.3,5.21,5.21,0,0,1-2.88.8,9.36,9.36,0,0,1-3.24-.68,14.39,14.39,0,0,1-3.9-2.43l1.78-3.78a10.66,10.66,0,0,0,2.63,1.69,5.84,5.84,0,0,0,2.27.62,2.12,2.12,0,0,0,.95-.2,1.19,1.19,0,0,0,.56-.57,2.53,2.53,0,0,0,.17-1,5,5,0,0,0-.3-1.68,4.72,4.72,0,0,0-.78-1.44,1.52,1.52,0,0,0-1.19-.59,1.4,1.4,0,0,0-.95.4,4.89,4.89,0,0,0-1,1.4c-.34.66-.75,1.6-1.24,2.82A20.11,20.11,0,0,1,433.18,83a6.2,6.2,0,0,1-1.54,1.68,4.69,4.69,0,0,1-1.75.79A9.85,9.85,0,0,1,427.76,85.63Z\"><\/path><path class=\"cls-1\" d=\"M53,97.25a1.9,1.9,0,0,0-2.58.72l-2.76,5a1.9,1.9,0,0,0,1.67,2.83,1.9,1.9,0,0,0,1.65-1l2.79-5h0a1.92,1.92,0,0,0-.78-2.6Z\"><\/path><path class=\"cls-1\" d=\"M86.08,104.79a1.88,1.88,0,0,0,1.65.95,2,2,0,0,0,1-.24,1.9,1.9,0,0,0,.66-2.57L86.5,98a1.9,1.9,0,0,0-3.3,1.9Z\"><\/path><path class=\"cls-1\" d=\"M105.47,45H95.3a11.38,11.38,0,0,0-5.08-13.81A1.88,1.88,0,0,0,88.77,31a1.86,1.86,0,0,0-1.14,1L80.25,45H56.7L49.32,31.87a1.89,1.89,0,0,0-2.58-.72A11.39,11.39,0,0,0,41.64,45H31.48a5.68,5.68,0,0,0-5.69,5.69V75.31A5.68,5.68,0,0,0,31.48,81H59.94l-4,7A9.49,9.49,0,0,0,43,91.66L38.38,100A9.46,9.46,0,0,0,42,112.89l3.3,1.9h0A9.37,9.37,0,0,0,49.93,116a9.51,9.51,0,0,0,8.27-4.83L68.48,92.88,78.75,111.1a9.49,9.49,0,0,0,12.92,3.61l3.3-1.9h0A9.47,9.47,0,0,0,98.57,100L93.92,91.7A9.5,9.5,0,0,0,81,88.1L77,81h28.46a5.68,5.68,0,0,0,5.69-5.69V50.65A5.7,5.7,0,0,0,105.47,45ZM89.88,35.59a7.56,7.56,0,0,1,1.36,9.2l-.09.17H84.6Zm-44.17,9.2a7.59,7.59,0,0,1,1.35-9.2L52.35,45H45.81ZM78.62,91.57a1.9,1.9,0,0,0,2.58.72l1.66-1a5.69,5.69,0,0,1,7.75,2.17l4.66,8.26h0a5.67,5.67,0,0,1,.55,4.32,5.76,5.76,0,0,1-2.68,3.45l-3.31,1.89h0a5.67,5.67,0,0,1-7.75-2.16L70.69,89.05,74,83.25ZM54.91,109.24a5.69,5.69,0,0,1-7.75,2.17l-3.31-1.9h0a5.68,5.68,0,0,1-2.16-7.75l4.65-8.26a5.7,5.7,0,0,1,5-2.85,5.6,5.6,0,0,1,2.78.73l1.66,1h0a1.9,1.9,0,0,0,2.58-.72l6-10.61h6.54Zm52.46-33.93a1.86,1.86,0,0,1-.56,1.34,1.89,1.89,0,0,1-1.34.56h-74a1.9,1.9,0,0,1-1.9-1.9V50.65a1.9,1.9,0,0,1,1.9-1.9h74a1.91,1.91,0,0,1,1.9,1.9Z\"><\/path><path class=\"cls-1\" d=\"M68.47,52.55a1.89,1.89,0,0,0-1.89,1.89V71.52a1.9,1.9,0,0,0,3.79,0V54.44a1.88,1.88,0,0,0-1.9-1.89Z\"><\/path><path class=\"cls-1\" d=\"M83.65,52.55a1.9,1.9,0,0,0-1.9,1.89V71.52a1.9,1.9,0,0,0,3.8,0V54.44a1.89,1.89,0,0,0-1.9-1.89Z\"><\/path><path class=\"cls-1\" d=\"M76.06,56.34a1.89,1.89,0,0,0-1.89,1.9v9.48a1.9,1.9,0,1,0,3.79,0V58.24a1.91,1.91,0,0,0-1.9-1.9Z\"><\/path><path class=\"cls-1\" d=\"M98.83,52.55a1.9,1.9,0,0,0-1.9,1.89V71.52a1.9,1.9,0,0,0,3.8,0V54.44a1.89,1.89,0,0,0-.56-1.34,1.93,1.93,0,0,0-1.34-.55Z\"><\/path><path class=\"cls-1\" d=\"M91.24,56.34a1.9,1.9,0,0,0-1.9,1.9v9.48a1.9,1.9,0,0,0,3.8,0V58.24a1.91,1.91,0,0,0-1.9-1.9Z\"><\/path><path class=\"cls-1\" d=\"M38.12,52.55a1.9,1.9,0,0,0-1.9,1.89V71.52a1.9,1.9,0,0,0,3.8,0V54.44a1.89,1.89,0,0,0-1.9-1.89Z\"><\/path><path class=\"cls-1\" d=\"M53.3,52.55a1.9,1.9,0,0,0-1.9,1.89V71.52a1.9,1.9,0,0,0,3.8,0V54.44a1.89,1.89,0,0,0-.56-1.34,1.93,1.93,0,0,0-1.34-.55Z\"><\/path><path class=\"cls-1\" d=\"M45.71,56.34a1.9,1.9,0,0,0-1.9,1.9v9.48a1.9,1.9,0,0,0,3.8,0V58.24a1.86,1.86,0,0,0-.56-1.34,1.89,1.89,0,0,0-1.34-.56Z\"><\/path><path class=\"cls-1\" d=\"M60.89,56.34a1.9,1.9,0,0,0-1.9,1.9v9.48a1.9,1.9,0,1,0,3.79,0V58.24a1.89,1.89,0,0,0-1.89-1.9Z\"><\/path><rect class=\"cls-2\" x=\"0.5\" y=\"0.5\" width=\"520\" height=\"152\"><\/rect><\/svg>\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-border\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-accordion-tab-content\" id=\"premium-accordion-content-3\">\r\n\t\t\t\t\t\t\t\t\t\t<section id=\"section-iconbox-3-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3554\" class=\"elementor elementor-3554 elementor-2324\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-359b942 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"359b942\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c44573\" data-id=\"5c44573\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40375f5 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"40375f5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1236\" height=\"697\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2.png\" class=\"attachment-full size-full wp-image-4439\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2.png 1236w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2-300x169.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2-1024x577.png 1024w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2-768x433.png 768w\" sizes=\"(max-width: 1236px) 100vw, 1236px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4e1e59\" data-id=\"c4e1e59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-729adfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"729adfe\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-62e38ef\" data-id=\"62e38ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcdb26f elementor-widget elementor-widget-text-editor\" data-id=\"fcdb26f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0642\u0645 \u0628\u0642\u0635 \u0627\u0644\u0645\u0642\u0627\u0628\u0644\u0627\u062a \u0623\u0648 \u062a\u062d\u0631\u064a\u0631 \u062d\u0644\u0642\u0627\u062a \u0627\u0644\u0628\u0648\u062f\u0643\u0627\u0633\u062a \u0627\u0644\u0643\u0627\u0645\u0644\u0629 \u0645\u0646 \u0647\u0627\u062a\u0641\u0643 \u0627\u0644\u0645\u062d\u0645\u0648\u0644 \u0623\u0648 \u062c\u0647\u0627\u0632 \u0633\u0637\u062d \u0627\u0644\u0645\u0643\u062a\u0628. \u064a\u0645\u0643\u0646 \u0625\u062c\u0631\u0627\u0621 \u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u062a\u062d\u0631\u064a\u0631 \u0627\u0644\u0645\u062d\u0644\u064a\u0629 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0632\u0627\u0645\u0646\u0629 \u0645\u0639 \u0627\u0644\u062a\u062e\u0632\u064a\u0646 \u0627\u0644\u0633\u062d\u0627\u0628\u064a \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u062d\u0631\u064a\u0631 \u0627\u0644\u062c\u0645\u0627\u0639\u064a.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/section>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-tabs-nav-list-item elementor-repeater-item-67af4d9\" data-list-index=\"4\" data-content-id=\"#premium-accordion-content-4\">\r\n\t\t\t\t\t\t\t\t<a class=\"premium-tab-link\" aria-label=\"#section-4-09e7e9d\" href=\"#section-iconbox-4-09e7e9d\">\r\n\r\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 521 153\"><defs><style>.cls-1{fill:#fff;}.cls-2{fill:none;}<\/style><\/defs><path class=\"cls-1\" d=\"M155.53,82.32a15.48,15.48,0,0,1-4,.43A10.45,10.45,0,0,1,147.8,82a6.1,6.1,0,0,1-2.66-2,5.55,5.55,0,0,1-1-3.4,7.23,7.23,0,0,1,.78-3.36,8.94,8.94,0,0,1,2.19-2.67,13,13,0,0,1,3.27-2,21.09,21.09,0,0,1,4-1.26l.46,4.79a9.47,9.47,0,0,0-2.4.44,8,8,0,0,0-1.93.91,4.4,4.4,0,0,0-1.27,1.23,2.56,2.56,0,0,0-.46,1.48,1.47,1.47,0,0,0,.42,1.09,2.91,2.91,0,0,0,1.1.66,5.2,5.2,0,0,0,1.55.3,7.79,7.79,0,0,0,1.73-.09,7.2,7.2,0,0,0,1.64-.45Zm-5.7-21.25a2.24,2.24,0,0,1-1.65-.66,2.21,2.21,0,0,1-.66-1.61,2.4,2.4,0,0,1,.66-1.67,2.22,2.22,0,0,1,1.68-.71,2.12,2.12,0,0,1,1.58.71,2.36,2.36,0,0,1,.66,1.63,2.25,2.25,0,0,1-.66,1.65A2.21,2.21,0,0,1,149.83,61.07Zm11.23,24.68a10,10,0,0,1-3.69-.63A5.24,5.24,0,0,1,154.85,83a7.82,7.82,0,0,1-1-3.91l-.67-14.24h4.69l.6,12.63a7.87,7.87,0,0,0,.36,2.26,1.89,1.89,0,0,0,.93,1.09,4,4,0,0,0,1.65.29,2.17,2.17,0,0,1,1.73.63,2.35,2.35,0,0,1,.54,1.58A2.31,2.31,0,0,1,163,85.1,2.68,2.68,0,0,1,161.06,85.75Zm-5.42-24.68a2.25,2.25,0,0,1-1.65-.66,2.18,2.18,0,0,1-.66-1.58,2.37,2.37,0,0,1,.66-1.68,2.26,2.26,0,0,1,1.68-.7,2.1,2.1,0,0,1,1.59.7,2.33,2.33,0,0,1,.65,1.65,2.25,2.25,0,0,1-2.27,2.27Z\"><\/path><path class=\"cls-1\" d=\"M161.06,85.75l.35-4.59a6.17,6.17,0,0,0,2-.26,2.65,2.65,0,0,0,1.33-1,7,7,0,0,0,.91-2.28c.25-1,.48-2.34.72-4l4.41.73c0,.38-.11.79-.19,1.24s-.16.93-.21,1.4a11.17,11.17,0,0,0-.09,1.39,2.84,2.84,0,0,0,.23,1.19,2,2,0,0,0,.73.87,4.08,4.08,0,0,0,1.4.56,9.67,9.67,0,0,0,2.19.21,2.1,2.1,0,0,1,1.69.63,2.31,2.31,0,0,1,.55,1.58,2.28,2.28,0,0,1-.67,1.73,2.64,2.64,0,0,1-1.92.65,14.75,14.75,0,0,1-3-.28,5.75,5.75,0,0,1-2.14-.88A4.09,4.09,0,0,1,168,83.05a6.72,6.72,0,0,1-.61-2.31l1.57,0a8,8,0,0,1-1.47,2.68,5.62,5.62,0,0,1-2,1.48,8.06,8.06,0,0,1-2.22.65A17.29,17.29,0,0,1,161.06,85.75Zm3.36,7.8a2.31,2.31,0,0,1-2.31-2.27,2.31,2.31,0,0,1,.67-1.68,2.16,2.16,0,0,1,1.64-.7,2.12,2.12,0,0,1,1.61.7,2.31,2.31,0,0,1,.67,1.68,2.19,2.19,0,0,1-.67,1.59A2.14,2.14,0,0,1,164.42,93.55Zm5.85,0a2.22,2.22,0,0,1-1.68-.68,2.19,2.19,0,0,1-.67-1.59,2.31,2.31,0,0,1,.67-1.68,2.2,2.2,0,0,1,1.68-.7,2.08,2.08,0,0,1,1.57.7,2.31,2.31,0,0,1,.67,1.68,2.19,2.19,0,0,1-.67,1.59A2.1,2.1,0,0,1,170.27,93.55Z\"><\/path><path class=\"cls-1\" d=\"M174.43,85.75l.35-4.59a4.47,4.47,0,0,0,1.65-.26,2,2,0,0,0,1-.89,3.59,3.59,0,0,0,.35-1.72,14.92,14.92,0,0,0-.24-2.46,29.24,29.24,0,0,0-.67-2.89q-.42-1.47-.84-2.7L180.49,69a28.61,28.61,0,0,1,.87,2.76,32.38,32.38,0,0,1,.7,3.29,20.58,20.58,0,0,1,.28,3.36,9.07,9.07,0,0,1-.47,3.12,6.54,6.54,0,0,1-1.26,2.11,5.45,5.45,0,0,1-1.82,1.32,8.94,8.94,0,0,1-2.14.64A12.64,12.64,0,0,1,174.43,85.75Zm3.85-19.88a2.24,2.24,0,0,1-1.66-.69,2.18,2.18,0,0,1-.68-1.62,2.35,2.35,0,0,1,.68-1.72,2.29,2.29,0,0,1,1.7-.7,2.2,2.2,0,0,1,1.62.7,2.32,2.32,0,0,1,.69,1.68,2.36,2.36,0,0,1-2.35,2.35Z\"><\/path><path class=\"cls-1\" d=\"M186,93.62l-1-4.44a28.91,28.91,0,0,0,3.9-.74,9.63,9.63,0,0,0,2.94-1.29,5.31,5.31,0,0,0,1.88-2.21,8.26,8.26,0,0,0,.63-3.46,16.65,16.65,0,0,0-.13-2.1,8.85,8.85,0,0,0-.36-1.67,3.09,3.09,0,0,0-.63-1.1,1.33,1.33,0,0,0-.95-.38,1.3,1.3,0,0,0-1,.44,3.1,3.1,0,0,0-.7,1.13,4.26,4.26,0,0,0-.26,1.54,2,2,0,0,0,.26,1.1,1.47,1.47,0,0,0,.73.64,3.14,3.14,0,0,0,1.11.19,6.86,6.86,0,0,0,1.36-.16,6.59,6.59,0,0,0,1.4-.47l.14,3.74a7.29,7.29,0,0,1-1.8,1,6.58,6.58,0,0,1-2.26.38,6.26,6.26,0,0,1-2.15-.35,4.51,4.51,0,0,1-1.72-1,4.75,4.75,0,0,1-1.12-1.73,6.45,6.45,0,0,1-.4-2.36,10.78,10.78,0,0,1,.47-3.15,9.53,9.53,0,0,1,1.39-2.8,7.23,7.23,0,0,1,2.1-2,5.06,5.06,0,0,1,5.3,0,6.37,6.37,0,0,1,2,2.15,11.41,11.41,0,0,1,1.26,3.17,16,16,0,0,1,.44,3.81,11.65,11.65,0,0,1-1.63,6.28,11.18,11.18,0,0,1-4.52,4.08A18.26,18.26,0,0,1,186,93.62Z\"><\/path><path class=\"cls-1\" d=\"M210.45,85.75a10.76,10.76,0,0,1-4.19-.67A4.26,4.26,0,0,1,204,83a8.5,8.5,0,0,1-.77-3.57l-.74-19.64h4.73l.7,17.22a10.3,10.3,0,0,0,.35,2.64,1.84,1.84,0,0,0,.87,1.2,3.91,3.91,0,0,0,1.65.29,2.16,2.16,0,0,1,1.69.61,2.29,2.29,0,0,1,.55,1.6,2.32,2.32,0,0,1-.67,1.73A2.64,2.64,0,0,1,210.45,85.75Z\"><\/path><path class=\"cls-1\" d=\"M210.41,85.75l.35-4.59a17.76,17.76,0,0,0,3.92-.4,16.35,16.35,0,0,0,3.19-1.05,10,10,0,0,0,2.32-1.45,6.76,6.76,0,0,0,1.44-1.7,3.49,3.49,0,0,0,.51-1.73,1.4,1.4,0,0,0-.3-.9,1.83,1.83,0,0,0-.81-.55,3.46,3.46,0,0,0-1.24-.2,6.69,6.69,0,0,0-1.21.12,8.34,8.34,0,0,0-1.27.37,3.92,3.92,0,0,0-1.12.67,17.34,17.34,0,0,1,1.55,1.54c.48.53.95,1.08,1.4,1.62s.9,1.11,1.32,1.67a11.15,11.15,0,0,0,1.62.82,12.81,12.81,0,0,0,2,.61,21.85,21.85,0,0,0,2.27.4,17.41,17.41,0,0,0,2.38.16,2.08,2.08,0,0,1,1.65.63,2.35,2.35,0,0,1,.56,1.61,2.24,2.24,0,0,1-.68,1.72,2.66,2.66,0,0,1-1.87.63,24.9,24.9,0,0,1-4-.3,14.51,14.51,0,0,1-6.8-3c-.6-.75-1.18-1.44-1.73-2.08s-1.08-1.25-1.59-1.83-1-1.11-1.57-1.62a3.61,3.61,0,0,1-.25-.63,10,10,0,0,1-.3-1.07,4.07,4.07,0,0,1-.12-.79,3.06,3.06,0,0,1,.68-1.77,8,8,0,0,1,1.86-1.73,11.71,11.71,0,0,1,2.62-1.33,8.67,8.67,0,0,1,3-.52,9.21,9.21,0,0,1,3.4.56,4.85,4.85,0,0,1,2.24,1.68,4.57,4.57,0,0,1,.8,2.73,8.3,8.3,0,0,1-.8,3.53,12,12,0,0,1-2.24,3.2,14.12,14.12,0,0,1-3.43,2.59,18.58,18.58,0,0,1-4.47,1.74A21.05,21.05,0,0,1,210.41,85.75Z\"><\/path><path class=\"cls-1\" d=\"M228.33,85.75l.35-4.59a15.45,15.45,0,0,0,3.1-.24,2.5,2.5,0,0,0,1.54-.86,3,3,0,0,0,.43-1.73,13.35,13.35,0,0,0-.26-2.5c-.17-1-.39-1.91-.66-2.89s-.54-1.88-.83-2.7L236.45,69c.3.79.59,1.71.88,2.76s.51,2.14.71,3.26a18.45,18.45,0,0,1,.3,3.25,8.6,8.6,0,0,1-.75,3.87,5.38,5.38,0,0,1-2.12,2.28,9.49,9.49,0,0,1-3.17,1.08A24.2,24.2,0,0,1,228.33,85.75Zm3.12-19.88a2.29,2.29,0,0,1-2.32-2.28A2.31,2.31,0,0,1,229.8,62a2.2,2.2,0,0,1,1.68-.7,2.07,2.07,0,0,1,1.57.7,2.29,2.29,0,0,1,0,3.25A2.2,2.2,0,0,1,231.45,65.87Zm5.84,0a2.27,2.27,0,0,1-1.66-.68,2.17,2.17,0,0,1-.68-1.59,2.34,2.34,0,0,1,.66-1.68,2.2,2.2,0,0,1,1.68-.7,2.11,2.11,0,0,1,1.58.7,2.3,2.3,0,0,1,.66,1.64,2.27,2.27,0,0,1-.66,1.63A2.16,2.16,0,0,1,237.29,65.9Z\"><\/path><path class=\"cls-1\" d=\"M261.65,82.32a15.48,15.48,0,0,1-4,.43,10.46,10.46,0,0,1-3.7-.73,6.16,6.16,0,0,1-2.66-2,5.61,5.61,0,0,1-1-3.4,7.24,7.24,0,0,1,.79-3.36,8.94,8.94,0,0,1,2.19-2.67,12.61,12.61,0,0,1,3.27-2,21.09,21.09,0,0,1,4-1.26l.45,4.79a9.39,9.39,0,0,0-2.39.44,8,8,0,0,0-1.93.91,4.44,4.44,0,0,0-1.28,1.23,2.63,2.63,0,0,0-.45,1.48,1.47,1.47,0,0,0,.42,1.09,2.91,2.91,0,0,0,1.1.66,5.2,5.2,0,0,0,1.54.3,7.76,7.76,0,0,0,1.73-.09,7.15,7.15,0,0,0,1.65-.45Zm-5.71-21.25a2.27,2.27,0,0,1-2.31-2.27,2.41,2.41,0,0,1,.67-1.67,2.2,2.2,0,0,1,1.68-.71,2.08,2.08,0,0,1,1.57.71,2.33,2.33,0,0,1,.67,1.63,2.22,2.22,0,0,1-.67,1.65A2.2,2.2,0,0,1,255.94,61.07Zm11.24,24.68a10,10,0,0,1-3.69-.63A5.15,5.15,0,0,1,261,83a7.82,7.82,0,0,1-1-3.91l-.66-14.24H264l.59,12.63a7.81,7.81,0,0,0,.37,2.26,1.89,1.89,0,0,0,.93,1.09,4,4,0,0,0,1.64.29,2.17,2.17,0,0,1,1.74.63,2.35,2.35,0,0,1,.54,1.58,2.28,2.28,0,0,1-.67,1.73A2.64,2.64,0,0,1,267.18,85.75Zm-5.43-24.68a2.23,2.23,0,0,1-1.64-.66,2.19,2.19,0,0,1-.67-1.58,2.38,2.38,0,0,1,.67-1.68,2.23,2.23,0,0,1,1.68-.7,2.1,2.1,0,0,1,1.59.7A2.37,2.37,0,0,1,264,58.8a2.27,2.27,0,0,1-2.28,2.27Z\"><\/path><path class=\"cls-1\" d=\"M267.18,85.75l.35-4.59a6.25,6.25,0,0,0,2-.26,2.69,2.69,0,0,0,1.33-1,7,7,0,0,0,.91-2.28c.24-1,.48-2.34.71-4l4.42.73c-.05.38-.12.79-.2,1.24s-.15.93-.21,1.4a11.17,11.17,0,0,0-.09,1.39,3,3,0,0,0,.23,1.19,2,2,0,0,0,.74.87,4,4,0,0,0,1.4.56,9.63,9.63,0,0,0,2.18.21,2.11,2.11,0,0,1,1.7.63,2.35,2.35,0,0,1,.54,1.58,2.31,2.31,0,0,1-.66,1.73,2.66,2.66,0,0,1-1.93.65,14.9,14.9,0,0,1-3-.28,5.77,5.77,0,0,1-2.13-.88,4,4,0,0,1-1.31-1.54,6.71,6.71,0,0,1-.62-2.31l1.58,0a8.35,8.35,0,0,1-1.47,2.68,5.71,5.71,0,0,1-2,1.48,8.06,8.06,0,0,1-2.22.65A17.29,17.29,0,0,1,267.18,85.75Zm3.36,7.8a2.29,2.29,0,0,1-2.31-2.27,2.34,2.34,0,0,1,.66-1.68,2.19,2.19,0,0,1,1.65-.7,2.12,2.12,0,0,1,1.61.7,2.34,2.34,0,0,1,.66,1.68,2.22,2.22,0,0,1-.66,1.59A2.14,2.14,0,0,1,270.54,93.55Zm5.84,0a2.21,2.21,0,0,1-1.67-.68,2.19,2.19,0,0,1-.67-1.59,2.31,2.31,0,0,1,.67-1.68,2.19,2.19,0,0,1,1.67-.7,2.09,2.09,0,0,1,1.58.7,2.34,2.34,0,0,1,.66,1.68,2.22,2.22,0,0,1-.66,1.59A2.11,2.11,0,0,1,276.38,93.55Z\"><\/path><path class=\"cls-1\" d=\"M297.21,86.17a33,33,0,0,1-4.87-.3,15.72,15.72,0,0,1-3.23-.79,5.57,5.57,0,0,1-2-1.24,7.1,7.1,0,0,1-1.25-1.66l1-.25a6.82,6.82,0,0,1-1.87,2.44,6.11,6.11,0,0,1-2.19,1.1,9.34,9.34,0,0,1-2.2.28l.35-4.59a2.43,2.43,0,0,0,1.43-.37,2.63,2.63,0,0,0,.88-1.19,13.25,13.25,0,0,0,.66-2.22c.21-.93.51-2.07.88-3.43L289.09,75c-.16.63-.3,1.18-.4,1.64s-.19.87-.25,1.21a5,5,0,0,0-.09.86,2.4,2.4,0,0,0,.3,1.24,2.19,2.19,0,0,0,1.14.84,10.07,10.07,0,0,0,2.47.52,36.92,36.92,0,0,0,4.25.2,29,29,0,0,0,4.36-.28,10.54,10.54,0,0,0,2.74-.76,3.31,3.31,0,0,0,1.47-1.18,2.88,2.88,0,0,0,.46-1.6,2.66,2.66,0,0,0-.3-1.26A2.4,2.4,0,0,0,303,75.18a4.61,4.61,0,0,0-2.18.59,10.4,10.4,0,0,0-2.17,1.61,22.94,22.94,0,0,0-2.05,2.22c-.65.81-1.26,1.62-1.82,2.44l-4.8-.6a39.53,39.53,0,0,1,2.91-4.23,26.65,26.65,0,0,1,3.31-3.52,15.76,15.76,0,0,1,3.55-2.4,8.51,8.51,0,0,1,3.71-.87,7,7,0,0,1,3.6.89,6.05,6.05,0,0,1,2.38,2.48,7.78,7.78,0,0,1,.84,3.66,7.56,7.56,0,0,1-1.4,4.55,9,9,0,0,1-4.28,3.06A20.8,20.8,0,0,1,297.21,86.17Zm15.33-.42a10.41,10.41,0,0,1-2.71-.37,13.33,13.33,0,0,1-2.47-.93,8.21,8.21,0,0,1-1.86-1.22l2.94-3.12a7.93,7.93,0,0,0,2.14.81,10.8,10.8,0,0,0,2.27.24,2.19,2.19,0,0,1,1.72.63,2.31,2.31,0,0,1,.56,1.58,2.28,2.28,0,0,1-.67,1.73A2.64,2.64,0,0,1,312.54,85.75Z\"><\/path><path class=\"cls-1\" d=\"M312.54,85.75l.35-4.59a4.37,4.37,0,0,0,1.64-.26,2,2,0,0,0,1-.89,3.59,3.59,0,0,0,.35-1.72,14,14,0,0,0-.25-2.46,26.57,26.57,0,0,0-.66-2.89q-.42-1.47-.84-2.7L318.59,69a25.93,25.93,0,0,1,.88,2.76c.28,1.05.51,2.15.7,3.29a21.76,21.76,0,0,1,.28,3.36,9.07,9.07,0,0,1-.47,3.12,6.54,6.54,0,0,1-1.26,2.11,5.55,5.55,0,0,1-1.82,1.32,8.94,8.94,0,0,1-2.14.64A12.73,12.73,0,0,1,312.54,85.75Zm3.85-19.88a2.23,2.23,0,0,1-1.66-.69,2.19,2.19,0,0,1-.69-1.62,2.36,2.36,0,0,1,.69-1.72,2.29,2.29,0,0,1,1.69-.7,2.22,2.22,0,0,1,1.63.7,2.31,2.31,0,0,1,.68,1.68,2.22,2.22,0,0,1-.68,1.66A2.24,2.24,0,0,1,316.39,65.87Z\"><\/path><path class=\"cls-1\" d=\"M343.55,82.32a15.56,15.56,0,0,1-4.05.43,10.45,10.45,0,0,1-3.69-.73,6.16,6.16,0,0,1-2.66-2,5.61,5.61,0,0,1-1-3.4,7.24,7.24,0,0,1,.79-3.36,8.79,8.79,0,0,1,2.19-2.67,12.61,12.61,0,0,1,3.27-2,20.86,20.86,0,0,1,4-1.26l.45,4.79a9.39,9.39,0,0,0-2.39.44,8,8,0,0,0-1.93.91,4.44,4.44,0,0,0-1.28,1.23,2.63,2.63,0,0,0-.45,1.48,1.47,1.47,0,0,0,.42,1.09,2.91,2.91,0,0,0,1.1.66,5.2,5.2,0,0,0,1.54.3,7.76,7.76,0,0,0,1.73-.09,7.29,7.29,0,0,0,1.65-.45Zm-5.71-21.25a2.23,2.23,0,0,1-1.64-.66,2.18,2.18,0,0,1-.67-1.61,2.37,2.37,0,0,1,.67-1.67,2.2,2.2,0,0,1,1.68-.71,2.09,2.09,0,0,1,1.57.71,2.33,2.33,0,0,1,.67,1.63,2.22,2.22,0,0,1-.67,1.65A2.2,2.2,0,0,1,337.84,61.07Zm11.24,24.68a10,10,0,0,1-3.69-.63A5.15,5.15,0,0,1,342.87,83a7.82,7.82,0,0,1-1-3.91l-.66-14.24h4.69l.59,12.63a7.81,7.81,0,0,0,.37,2.26,1.89,1.89,0,0,0,.93,1.09,4,4,0,0,0,1.64.29,2.15,2.15,0,0,1,1.73.63,2.31,2.31,0,0,1,.55,1.58A2.28,2.28,0,0,1,351,85.1,2.64,2.64,0,0,1,349.08,85.75Zm-5.43-24.68a2.23,2.23,0,0,1-1.64-.66,2.15,2.15,0,0,1-.67-1.58,2.34,2.34,0,0,1,.67-1.68,2.23,2.23,0,0,1,1.68-.7,2.1,2.1,0,0,1,1.59.7,2.37,2.37,0,0,1,.65,1.65,2.27,2.27,0,0,1-2.28,2.27Z\"><\/path><path class=\"cls-1\" d=\"M349,85.75l.35-4.59a17.69,17.69,0,0,0,3.92-.4,16.35,16.35,0,0,0,3.19-1.05,9.82,9.82,0,0,0,2.32-1.45,6.76,6.76,0,0,0,1.44-1.7,3.49,3.49,0,0,0,.51-1.73,1.4,1.4,0,0,0-.3-.9,1.85,1.85,0,0,0-.8-.55,3.52,3.52,0,0,0-1.25-.2,6.78,6.78,0,0,0-1.21.12,8.34,8.34,0,0,0-1.27.37,3.92,3.92,0,0,0-1.12.67,17.47,17.47,0,0,1,1.56,1.54c.47.53.94,1.08,1.39,1.62s.9,1.11,1.32,1.67a11.15,11.15,0,0,0,1.62.82,12.81,12.81,0,0,0,2,.61A22,22,0,0,0,365,81a17.2,17.2,0,0,0,2.38.16,2.07,2.07,0,0,1,1.64.63,2.31,2.31,0,0,1,.56,1.61,2.24,2.24,0,0,1-.68,1.72,2.65,2.65,0,0,1-1.87.63,24.9,24.9,0,0,1-4-.3,14.73,14.73,0,0,1-3.52-1,14.44,14.44,0,0,1-3.27-2c-.61-.75-1.19-1.44-1.74-2.08s-1.07-1.25-1.59-1.83-1-1.11-1.57-1.62a3.61,3.61,0,0,1-.25-.63c-.11-.35-.21-.71-.3-1.07a4.07,4.07,0,0,1-.12-.79,3.06,3.06,0,0,1,.68-1.77,8,8,0,0,1,1.86-1.73,11.93,11.93,0,0,1,2.62-1.33,8.67,8.67,0,0,1,3-.52,9.21,9.21,0,0,1,3.4.56,4.85,4.85,0,0,1,2.24,1.68,4.57,4.57,0,0,1,.8,2.73,8.3,8.3,0,0,1-.8,3.53,12,12,0,0,1-2.24,3.2,14.12,14.12,0,0,1-3.43,2.59,18.58,18.58,0,0,1-4.47,1.74A21.05,21.05,0,0,1,349,85.75Z\"><\/path><path class=\"cls-1\" d=\"M367,85.75l.35-4.59a3.74,3.74,0,0,0,1.52-.26,2.3,2.3,0,0,0,1.05-1,8,8,0,0,0,.76-2.26c.21-1,.44-2.34.7-4l4.41.73c-.05.38-.11.8-.2,1.26s-.15.94-.21,1.4a12.88,12.88,0,0,0-.08,1.37,3.31,3.31,0,0,0,.33,1.52,2.12,2.12,0,0,0,1.08,1,5.16,5.16,0,0,0,2,.33,2.1,2.1,0,0,1,1.69.63,2.31,2.31,0,0,1,.55,1.58,2.35,2.35,0,0,1-.65,1.73,2.6,2.6,0,0,1-1.91.65,8.63,8.63,0,0,1-3.17-.51,4.12,4.12,0,0,1-2-1.61,6.27,6.27,0,0,1-.89-2.85H374a8,8,0,0,1-1.42,2.74A5.63,5.63,0,0,1,370.71,85a6.46,6.46,0,0,1-2,.59A13.22,13.22,0,0,1,367,85.75Zm5.18,7.84a2.32,2.32,0,0,1-2.31-2.28,2.34,2.34,0,0,1,.67-1.68,2.23,2.23,0,0,1,1.68-.7,2.17,2.17,0,0,1,1.61.7,2.34,2.34,0,0,1,.66,1.65,2.3,2.3,0,0,1-2.31,2.31Z\"><\/path><path class=\"cls-1\" d=\"M378.34,85.75l.31-4.59h7.67a32.18,32.18,0,0,0,4.53-.26,12.88,12.88,0,0,0,3-.73A3.69,3.69,0,0,0,395.42,79a2.81,2.81,0,0,0,.49-1.64,2.93,2.93,0,0,0-.28-1.25,2.25,2.25,0,0,0-.84-.92,2.55,2.55,0,0,0-1.4-.35,4.86,4.86,0,0,0-2.26.57A10.32,10.32,0,0,0,389,76.94a23.56,23.56,0,0,0-2.09,2.21A31,31,0,0,0,385,81.79l-4.9-.45a43.28,43.28,0,0,1,3-4.45,28,28,0,0,1,3.32-3.57A15.27,15.27,0,0,1,390,70.91a8.78,8.78,0,0,1,3.82-.88,6.76,6.76,0,0,1,3.6,1,6.47,6.47,0,0,1,2.38,2.52,7.53,7.53,0,0,1,.84,3.6,7.17,7.17,0,0,1-1.28,4.27,8.78,8.78,0,0,1-3.79,2.94,13.55,13.55,0,0,1-2.4.77,21.82,21.82,0,0,1-3.05.47c-1.13.11-2.37.16-3.72.16ZM382,82.18l-.7-22.37H386l.59,16.87Z\"><\/path><path class=\"cls-1\" d=\"M96.88,47.76,82.34,33.23h0a1.82,1.82,0,0,0-1.29-.54H44.73a5.45,5.45,0,0,0-5.45,5.45V109a5.43,5.43,0,0,0,5.45,5.45H92A5.45,5.45,0,0,0,97.42,109V49a1.86,1.86,0,0,0-.54-1.28Zm-14-8.86,8.33,8.33H84.7a1.82,1.82,0,0,1-1.82-1.82ZM92,110.82H44.73A1.81,1.81,0,0,1,42.91,109V38.14a1.81,1.81,0,0,1,1.82-1.81H79.25v9.08a5.43,5.43,0,0,0,5.45,5.45h9.08V109a1.83,1.83,0,0,1-.53,1.29,1.81,1.81,0,0,1-1.28.53Z\"><\/path><rect class=\"cls-1\" x=\"50.22\" y=\"59.01\" width=\"30.98\" height=\"3.63\" rx=\"1.82\"><\/rect><rect class=\"cls-1\" x=\"50.22\" y=\"70.57\" width=\"35.05\" height=\"3.63\" rx=\"1.82\"><\/rect><rect class=\"cls-1\" x=\"50.22\" y=\"82.13\" width=\"35.05\" height=\"3.63\" rx=\"1.82\"><\/rect><rect class=\"cls-1\" x=\"50.22\" y=\"93.68\" width=\"35.05\" height=\"3.63\" rx=\"1.82\"><\/rect><rect class=\"cls-2\" x=\"0.5\" y=\"0.5\" width=\"520\" height=\"152\"><\/rect><\/svg>\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-border\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-accordion-tab-content\" id=\"premium-accordion-content-4\">\r\n\t\t\t\t\t\t\t\t\t\t<section id=\"section-iconbox-4-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3564\" class=\"elementor elementor-3564 elementor-2328\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a381ffe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a381ffe\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3698989\" data-id=\"3698989\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c3b420 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"1c3b420\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1084\" height=\"1925\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2.png\" class=\"attachment-full size-full wp-image-4440\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2.png 1084w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-577x1024.png 577w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-768x1364.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-865x1536.png 865w\" sizes=\"(max-width: 1084px) 100vw, 1084px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17f3bbc\" data-id=\"17f3bbc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-053f2f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"053f2f6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-005a5c2\" data-id=\"005a5c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48685cc elementor-widget elementor-widget-text-editor\" data-id=\"48685cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0623\u062f\u0627\u0629 \u064a\u062f\u0648\u064a\u0629 \u0644\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0641\u064a \u062a\u062d\u0631\u064a\u0631 \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639 \u0623\u0648 \u0627\u0644\u0646\u0635\u0648\u0635 \u0623\u0648 \u0627\u0644\u0645\u0642\u0627\u0644\u0627\u062a. \u064a\u0645\u0643\u0646\u0643 \u0623\u064a\u0636\u064b\u0627 \u0625\u062f\u0631\u0627\u062c \u0635\u0648\u0631 \u0645\u0646 \u0635\u0627\u0644\u0627\u062a \u0627\u0644\u0639\u0631\u0636 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u0648\u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0645\u0646\u0634\u0648\u0631\u0627\u062a \u0628\u0634\u0643\u0644 \u062c\u0645\u0627\u0639\u064a\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/section>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-tabs-nav-list-item elementor-repeater-item-447aea6\" data-list-index=\"5\" data-content-id=\"#premium-accordion-content-5\">\r\n\t\t\t\t\t\t\t\t<a class=\"premium-tab-link\" aria-label=\"#section-5-09e7e9d\" href=\"#section-iconbox-5-09e7e9d\">\r\n\r\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 521 153\"><defs><style>.cls-1{fill:#fff;}.cls-2{fill:none;}<\/style><\/defs><path class=\"cls-1\" d=\"M144.37,82.64a17.33,17.33,0,0,1,.12-1.93,15.77,15.77,0,0,1,.52-2.43A25.71,25.71,0,0,1,146.26,75l4.13,1.58a21,21,0,0,0-.77,2.1,13.55,13.55,0,0,0-.41,1.68,10.42,10.42,0,0,0-.12,1.61,5.21,5.21,0,0,0,.6,2.62,4,4,0,0,0,1.69,1.62,5.77,5.77,0,0,0,2.61.55,6.57,6.57,0,0,0,2.77-.5,4.16,4.16,0,0,0,1.71-1.44,5.94,5.94,0,0,0,.89-2.06,10.25,10.25,0,0,0,.27-2.37,14.67,14.67,0,0,0-.51-3.65,24.18,24.18,0,0,0-1.73-4.47l4.37-1.92a16.44,16.44,0,0,1,1.33,2.85,20.82,20.82,0,0,1,.93,3.43,19.71,19.71,0,0,1,.33,3.55,16.39,16.39,0,0,1-.3,3.08,11.37,11.37,0,0,1-1,3,9,9,0,0,1-1.93,2.59,8.62,8.62,0,0,1-3,1.8,12.08,12.08,0,0,1-4.27.67,13.07,13.07,0,0,1-3.59-.49,8.55,8.55,0,0,1-3.06-1.57,7.54,7.54,0,0,1-2.08-2.75A9.52,9.52,0,0,1,144.37,82.64Zm10-13.76a2.23,2.23,0,0,1-1.66-.68,2.18,2.18,0,0,1-.68-1.62,2.35,2.35,0,0,1,.68-1.72,2.26,2.26,0,0,1,1.7-.7,2.16,2.16,0,0,1,1.62.7,2.32,2.32,0,0,1,.69,1.68A2.24,2.24,0,0,1,156,68.2,2.22,2.22,0,0,1,154.34,68.88Z\"><\/path><path class=\"cls-1\" d=\"M168,91.39,167,87a30.56,30.56,0,0,0,3.9-.74,9.88,9.88,0,0,0,2.94-1.29,5.35,5.35,0,0,0,1.87-2.21,8.29,8.29,0,0,0,.63-3.46,16.82,16.82,0,0,0-.12-2.11,8,8,0,0,0-.37-1.66,2.75,2.75,0,0,0-.63-1.1,1.25,1.25,0,0,0-.94-.38,1.37,1.37,0,0,0-1,.43,3.2,3.2,0,0,0-.7,1.14,4.48,4.48,0,0,0-.26,1.54,2.16,2.16,0,0,0,.26,1.1,1.57,1.57,0,0,0,.74.63,2.88,2.88,0,0,0,1.1.2,7,7,0,0,0,1.37-.16,6.78,6.78,0,0,0,1.4-.47l.14,3.74a7.64,7.64,0,0,1-1.8.94,6.39,6.39,0,0,1-2.26.39,6.61,6.61,0,0,1-2.16-.35,4.55,4.55,0,0,1-1.71-1,4.84,4.84,0,0,1-1.12-1.73,6.47,6.47,0,0,1-.4-2.37,10.55,10.55,0,0,1,.47-3.15A9.57,9.57,0,0,1,169.74,72a7.49,7.49,0,0,1,2.1-2,4.93,4.93,0,0,1,2.63-.74,4.85,4.85,0,0,1,2.68.78,6.25,6.25,0,0,1,2,2.15,11.8,11.8,0,0,1,1.27,3.16,16.14,16.14,0,0,1,.43,3.82,11.67,11.67,0,0,1-1.62,6.28,11.18,11.18,0,0,1-4.52,4.08A18.26,18.26,0,0,1,168,91.39Z\"><\/path><path class=\"cls-1\" d=\"M192.49,83.51a10.91,10.91,0,0,1-4.18-.66,4.32,4.32,0,0,1-2.26-2.06,8.67,8.67,0,0,1-.77-3.58l-.73-19.63h4.72L190,74.8a10.77,10.77,0,0,0,.35,2.64,1.86,1.86,0,0,0,.88,1.19,3.66,3.66,0,0,0,1.64.3,2.15,2.15,0,0,1,1.7.61,2.62,2.62,0,0,1-.12,3.33A2.68,2.68,0,0,1,192.49,83.51Z\"><\/path><path class=\"cls-1\" d=\"M192.46,83.51l.35-4.58a17.76,17.76,0,0,0,3.92-.4,16,16,0,0,0,3.18-1A9.79,9.79,0,0,0,202.24,76a6.5,6.5,0,0,0,1.43-1.69,3.5,3.5,0,0,0,.51-1.74,1.39,1.39,0,0,0-.3-.89,1.83,1.83,0,0,0-.8-.56,3.48,3.48,0,0,0-1.24-.19,6.61,6.61,0,0,0-1.21.12,7.45,7.45,0,0,0-1.28.37,4,4,0,0,0-1.12.66,18.93,18.93,0,0,1,1.56,1.54c.48.54.94,1.08,1.4,1.63s.89,1.11,1.31,1.66a10.8,10.8,0,0,0,1.63.83,12.16,12.16,0,0,0,2,.61c.72.16,1.48.3,2.27.4a17.3,17.3,0,0,0,2.38.16,2.11,2.11,0,0,1,1.65.63,2.35,2.35,0,0,1,.56,1.61,2.2,2.2,0,0,1-.69,1.71,2.65,2.65,0,0,1-1.87.63,25.12,25.12,0,0,1-4-.29,14.31,14.31,0,0,1-6.79-3c-.61-.74-1.18-1.44-1.73-2.08s-1.08-1.25-1.59-1.82-1-1.11-1.58-1.62a3.35,3.35,0,0,1-.24-.64,9.82,9.82,0,0,1-.3-1.06,4.18,4.18,0,0,1-.12-.79,3,3,0,0,1,.68-1.77,7.56,7.56,0,0,1,1.85-1.73,11.38,11.38,0,0,1,2.63-1.33,8.64,8.64,0,0,1,3-.53,9.19,9.19,0,0,1,3.39.57,4.85,4.85,0,0,1,2.24,1.67,4.56,4.56,0,0,1,.81,2.74,8.17,8.17,0,0,1-.81,3.53,11.9,11.9,0,0,1-2.24,3.2,14.38,14.38,0,0,1-3.43,2.59,18.65,18.65,0,0,1-4.46,1.73A21.11,21.11,0,0,1,192.46,83.51Z\"><\/path><path class=\"cls-1\" d=\"M210.38,83.51l.35-4.58a6.44,6.44,0,0,0,2-.26,2.62,2.62,0,0,0,1.33-1,6.74,6.74,0,0,0,.91-2.27,39.54,39.54,0,0,0,.72-4l4.41.74c0,.37-.11.79-.19,1.24s-.15.92-.21,1.4a11.14,11.14,0,0,0-.09,1.38,3.06,3.06,0,0,0,.23,1.2,2.1,2.1,0,0,0,.73.87,4.29,4.29,0,0,0,1.4.56,9.79,9.79,0,0,0,2.19.21,2.13,2.13,0,0,1,1.7.63,2.28,2.28,0,0,1,.54,1.54,2.36,2.36,0,0,1-.66,1.77,2.68,2.68,0,0,1-1.93.64,14.14,14.14,0,0,1-3-.28,5.6,5.6,0,0,1-2.13-.87,4.19,4.19,0,0,1-1.32-1.54,6.72,6.72,0,0,1-.61-2.31l1.58,0a8.13,8.13,0,0,1-1.47,2.68,5.84,5.84,0,0,1-2,1.49,8.23,8.23,0,0,1-2.23.65A17.12,17.12,0,0,1,210.38,83.51Zm4.34-16.06a2.32,2.32,0,0,1-1.67-.66,2.21,2.21,0,0,1-.68-1.62,2.34,2.34,0,0,1,.67-1.66,2.18,2.18,0,0,1,1.68-.72,2.12,2.12,0,0,1,1.61.72,2.34,2.34,0,0,1,.66,1.63,2.27,2.27,0,0,1-.66,1.65A2.21,2.21,0,0,1,214.72,67.45Zm5.81,0a2.29,2.29,0,0,1-2.31-2.27,2.37,2.37,0,0,1,.66-1.68,2.2,2.2,0,0,1,1.68-.7,2.11,2.11,0,0,1,1.58.7,2.31,2.31,0,0,1,.66,1.64,2.24,2.24,0,0,1-.68,1.63A2.17,2.17,0,0,1,220.53,67.48Z\"><\/path><path class=\"cls-1\" d=\"M223.75,83.51l.31-4.58a3.53,3.53,0,0,0,1.89-.37,1.91,1.91,0,0,0,.72-1.38,16.65,16.65,0,0,0,.08-2.91l-.66-16.69h4.76l.7,17.08a19.56,19.56,0,0,1-.12,3.66,6.39,6.39,0,0,1-1,2.78,5.13,5.13,0,0,1-2.4,1.78A11.79,11.79,0,0,1,223.75,83.51Z\"><\/path><path class=\"cls-1\" d=\"M41.06,76.55a9.12,9.12,0,1,0-6.45-2.67A9.12,9.12,0,0,0,41.06,76.55Zm0-14.59h0a5.46,5.46,0,1,1-3.87,1.6A5.46,5.46,0,0,1,41.06,62Z\"><\/path><path class=\"cls-1\" d=\"M104.89,76.55a9.12,9.12,0,1,0-6.45-2.67A9.12,9.12,0,0,0,104.89,76.55Zm0-14.59h0a5.46,5.46,0,1,1-3.87,1.6,5.46,5.46,0,0,1,3.87-1.6Z\"><\/path><path class=\"cls-1\" d=\"M108.86,76.91c-2.54-.86-5-.22-7.3,1.91-1.46,1.33-2.8,2.79-4.08,4.2l-1.64,1.82L95,85.7H83.92a6.38,6.38,0,0,0-5.76,9.12H74.8V85.51l3.32-3.33h0a3.74,3.74,0,0,0,2.17.52,3.64,3.64,0,0,0,2.06-.85l5.14-4.35h0A6.38,6.38,0,1,0,82.4,66.2a6.41,6.41,0,0,0-2.34,3.88l-4.35,5.14a3.72,3.72,0,0,0-.85,2.18,3.67,3.67,0,0,0,.64,2.25L73,82.17l-2.53-2.52a3.67,3.67,0,0,0-.21-4.43l-4.35-5.14h0A6.38,6.38,0,1,0,55.1,75.74a6.21,6.21,0,0,0,3.36,1.76l5.14,4.35h0a3.62,3.62,0,0,0,4.23.33l3.32,3.33v9.27H67.79a6.31,6.31,0,0,0,.63-2.73A6.38,6.38,0,0,0,62,85.66H51l-.79-.85L48.54,83c-1.29-1.41-2.63-2.87-4.09-4.2-2.32-2.12-4.79-2.74-7.29-1.91h0a7.79,7.79,0,0,0-5.22,7.51v25.9a5.48,5.48,0,0,0,5.48,5.47h71.12a5.46,5.46,0,0,0,5.47-5.47V84.38a7.78,7.78,0,0,0-5.15-7.47ZM84.41,69.3a2.74,2.74,0,0,1,3.87,0,2.73,2.73,0,0,1,0,3.86,2.79,2.79,0,0,1-3.87,0,2.73,2.73,0,0,1,0-3.86ZM81,74.67a9.39,9.39,0,0,0,2,2L80,79.12l-1.49-1.5ZM61.54,73.16h0a2.78,2.78,0,0,1-3.86,0,2.73,2.73,0,0,1,0-3.86,2.73,2.73,0,1,1,3.86,3.86ZM66,79.07l-2.9-2.46a6.21,6.21,0,0,0,1.07-.91A5.86,5.86,0,0,0,65,74.62l2.47,2.91Zm-5.74,33H37.41a1.83,1.83,0,0,1-1.82-1.83V84.38a4.18,4.18,0,0,1,2.67-4,3,3,0,0,1,1-.18A4.1,4.1,0,0,1,42,81.52c1.34,1.21,2.61,2.61,3.85,4,.56.61,1.11,1.22,1.68,1.83l1.36,1.43h0a1.82,1.82,0,0,0,1.32.57H62a2.74,2.74,0,1,1,0,5.47H44.71a1.82,1.82,0,0,0-1.82,1.83v9.12a1.81,1.81,0,0,0,1.82,1.82H57.48a2.73,2.73,0,0,1,2.73,2.73Zm21.89-1.83v1.83H63.86v-1.83a6.38,6.38,0,0,0-6.38-6.38H46.53V98.43H99.42v5.47H88.48a6.37,6.37,0,0,0-6.38,6.38Zm28.26,0h0a1.83,1.83,0,0,1-1.82,1.83H85.74v-1.83a2.73,2.73,0,0,1,2.74-2.73h12.76a1.84,1.84,0,0,0,1.83-1.82V96.61a1.78,1.78,0,0,0-.54-1.29,1.82,1.82,0,0,0-1.29-.54H83.92a2.74,2.74,0,0,1,0-5.47H95.77a1.86,1.86,0,0,0,1.33-.57l1.35-1.43q.85-.91,1.68-1.83c1.24-1.35,2.52-2.73,3.85-4,1.71-1.56,2.87-1.44,3.71-1.15h0a4.18,4.18,0,0,1,2.67,4Z\"><\/path><path class=\"cls-1\" d=\"M52.92,61H93a3.62,3.62,0,0,0,3.64-3.64V37.34A3.64,3.64,0,0,0,93,33.69H52.92a3.65,3.65,0,0,0-3.65,3.65V57.4A3.64,3.64,0,0,0,52.92,61Zm0-23.7H93V57.4H52.92Z\"><\/path><rect class=\"cls-2\" x=\"0.5\" y=\"0.5\" width=\"520\" height=\"152\"><\/rect><\/svg>\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-border\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-accordion-tab-content\" id=\"premium-accordion-content-5\">\r\n\t\t\t\t\t\t\t\t\t\t<section id=\"section-iconbox-5-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3574\" class=\"elementor elementor-3574 elementor-2332\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-919470c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"919470c\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2921d21\" data-id=\"2921d21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36fb80e dce_masking-none elementor-widget elementor-widget-image\" data-id=\"36fb80e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1087\" height=\"2507\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2.png\" class=\"attachment-full size-full wp-image-4441\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2.png 1087w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-130x300.png 130w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-444x1024.png 444w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-768x1771.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-666x1536.png 666w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-888x2048.png 888w\" sizes=\"(max-width: 1087px) 100vw, 1087px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc8b18f\" data-id=\"fc8b18f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-4983175 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4983175\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c94c2d5\" data-id=\"c94c2d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab7469a elementor-widget elementor-widget-text-editor\" data-id=\"ab7469a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0627\u0644\u0645\u0633\u0627\u062d\u0627\u062a \u0627\u0644\u0627\u0641\u062a\u0631\u0627\u0636\u064a\u0629 \u060c \u0639\r\n\u0644\u0649 \u063a\u0631\u0627\u0631 \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0639\u0633\u0644 \u0627\u0644\u062a\u064a \u062a\u0631\u0643\u0632 \u0639\u0644\u0649 \u0627\u0644\u062a\u0628\u0627\u062f\u0644 \u0648\u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u062c\u0645\u0627\u0639\u064a \u060c \u0645\u062f\u0641\u0648\u0639\u0629 \u0628\u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u0645\u062a\u0639\u0627\u0648\u0646\u0629. \u0642\u0645 \u0628\u0625\u0646\u0634\u0627\u0621 \u0627\u0644\u0645\u0633\u0627\u062d\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u0645\u062b\u0644 \u062a\u0648\u0641\u064a\u0631 \u0645\u0633\u0627\u062d\u0627\u062a \u0644\u0644\u0646\u0633\u0627\u0621 \u060c \u0648\u0645\u062c\u0645\u0648\u0639\u0627\u062a \u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0627\u0644\u062d\u0642\u0627\u0626\u0642 \u060c \u0648\u062d\u0648\u0627\u0631\u0627\u062a \u0627\u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u060c \u0648\u0645\u0627 \u0625\u0644\u0649 \u0630\u0644\u0643 \u060c \u0633\u062a\u0648\u062c\u0647\u0643 \u0627\u0644\u0643\u062a\u064a\u0628\u0627\u062a \u0627\u0644\u0645\u0635\u063a\u0631\u0629 \u0637\u0631\u064a\u0642\u0643 &#8230;\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/section>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-tabs-nav-list-item elementor-repeater-item-b98275d\" data-list-index=\"6\" data-content-id=\"#premium-accordion-content-6\">\r\n\t\t\t\t\t\t\t\t<a class=\"premium-tab-link\" aria-label=\"#section-6-09e7e9d\" href=\"#section-iconbox-6-09e7e9d\">\r\n\r\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 521 153\"><defs><style>.cls-1{fill:#fff;}.cls-2{fill:none;}<\/style><\/defs><path class=\"cls-1\" d=\"M144.33,76.49l-2.41-4.41a18.41,18.41,0,0,0,2.9-1.66,11.93,11.93,0,0,0,2.12-1.87,6.58,6.58,0,0,0,1.7-4.48,9.31,9.31,0,0,0-.65-3.26,38.37,38.37,0,0,0-1.59-3.6L150.81,55a21.23,21.23,0,0,1,1,2.17c.3.75.56,1.45.79,2.1s.41,1.21.53,1.65a4.28,4.28,0,0,0,1.4,2.41,3.88,3.88,0,0,0,2.38.67,2.1,2.1,0,0,1,1.69.63,2.28,2.28,0,0,1,.55,1.57,2.37,2.37,0,0,1-.65,1.74,2.64,2.64,0,0,1-1.94.64,5.38,5.38,0,0,1-2.19-.43,3.86,3.86,0,0,1-1.59-1.26,5.06,5.06,0,0,1-.84-1.84l1.36-.63a11.09,11.09,0,0,1-.65,3.6,12.07,12.07,0,0,1-1.73,3.24,15.05,15.05,0,0,1-2.76,2.84A21.67,21.67,0,0,1,144.33,76.49Z\"><\/path><path class=\"cls-1\" d=\"M156.55,68.58,156.9,64a4.2,4.2,0,0,0,1.47-.23,2.1,2.1,0,0,0,1-.94,8.38,8.38,0,0,0,.77-2.17c.23-1,.5-2.27.81-3.91l4.41.81c-.1.51-.23,1.17-.39,2a10.6,10.6,0,0,0-.24,2.06,3.36,3.36,0,0,0,.21,1.28,1.63,1.63,0,0,0,.75.81,3.41,3.41,0,0,0,1.56.29,3.48,3.48,0,0,0,1.29-.21,1.85,1.85,0,0,0,.91-.94,10.16,10.16,0,0,0,.74-2.24c.23-1,.46-2.36.7-4.06l4.48.7c-.1.56-.2,1.14-.3,1.73s-.19,1.16-.26,1.7a10.7,10.7,0,0,0-.11,1.33,2.35,2.35,0,0,0,.23,1.07,1.65,1.65,0,0,0,.82.7,4.41,4.41,0,0,0,1.68.26,2.48,2.48,0,0,0,1.94-.72,3.43,3.43,0,0,0,.65-2.36c0-.54,0-1.12,0-1.75s-.07-1.34-.14-2.14-.18-1.68-.32-2.66L184,54c.17,2.08.35,3.77.54,5.08a12.3,12.3,0,0,0,.77,3,3.06,3.06,0,0,0,1.23,1.47,3.8,3.8,0,0,0,1.87.42,2.15,2.15,0,0,1,1.73.63,2.28,2.28,0,0,1,.55,1.57,2.37,2.37,0,0,1-.65,1.74,2.64,2.64,0,0,1-1.94.64,8.27,8.27,0,0,1-1.58-.17,6,6,0,0,1-1.7-.68,5.65,5.65,0,0,1-1.55-1.4A7.45,7.45,0,0,1,182.06,64l.74.17a6.09,6.09,0,0,1-1.21,2.61,4.73,4.73,0,0,1-1.91,1.38,6.93,6.93,0,0,1-2.52.42,6.78,6.78,0,0,1-2.41-.42A3.67,3.67,0,0,1,173,66.75a5,5,0,0,1-.7-2.65h1.09A9,9,0,0,1,171.86,67a4,4,0,0,1-1.94,1.28,10.43,10.43,0,0,1-2.77.31,7.5,7.5,0,0,1-2.12-.31,4.42,4.42,0,0,1-2-1.28,6.16,6.16,0,0,1-1.31-2.92l1.93-.07a8.65,8.65,0,0,1-1.89,3.06,4.67,4.67,0,0,1-2.33,1.26A14.27,14.27,0,0,1,156.55,68.58Zm13.23-17.29a2.1,2.1,0,0,1-1.56-.66,2.19,2.19,0,0,1-.65-1.58,2.26,2.26,0,0,1,.65-1.59,2.12,2.12,0,0,1,1.59-.68,2.16,2.16,0,0,1,1.58.68,2.25,2.25,0,0,1-1.61,3.83Zm2.76-4.93a2.17,2.17,0,0,1-1.57-.65,2.11,2.11,0,0,1-.67-1.59,2.21,2.21,0,0,1,.65-1.58,2.14,2.14,0,0,1,1.59-.66,2.1,2.1,0,0,1,1.56.66,2.17,2.17,0,0,1,.65,1.54,2.21,2.21,0,0,1-.65,1.63A2.13,2.13,0,0,1,172.54,46.36Zm2.94,4.93a2.08,2.08,0,0,1-1.57-.66,2.21,2.21,0,0,1-.63-1.58,2.27,2.27,0,0,1,.63-1.61,2.12,2.12,0,0,1,1.61-.66,2.06,2.06,0,0,1,1.54.66,2.31,2.31,0,0,1,0,3.19A2.1,2.1,0,0,1,175.48,51.29Z\"><\/path><path class=\"cls-1\" d=\"M188.05,68.58,188.4,64a4,4,0,0,0,1.52-.26,2.28,2.28,0,0,0,1.05-1,8.13,8.13,0,0,0,.75-2.25c.21-1,.45-2.34.7-4.05l4.41.74c0,.37-.11.79-.19,1.26s-.15.93-.21,1.4a10.7,10.7,0,0,0-.09,1.36,3.35,3.35,0,0,0,.33,1.53,2.23,2.23,0,0,0,1.09,1,5.07,5.07,0,0,0,2,.33,2.13,2.13,0,0,1,1.7.63,2.61,2.61,0,0,1-.11,3.31,2.57,2.57,0,0,1-1.9.64,8.82,8.82,0,0,1-3.17-.5,4.2,4.2,0,0,1-2-1.61,6.52,6.52,0,0,1-.89-2.86h1.65a8.43,8.43,0,0,1-1.42,2.75,5.55,5.55,0,0,1-1.84,1.51,6.38,6.38,0,0,1-2,.59A14.76,14.76,0,0,1,188.05,68.58Zm5.74-16.17a2.32,2.32,0,0,1-2.35-2.31,2.39,2.39,0,0,1,.68-1.71,2.27,2.27,0,0,1,1.7-.7,2.2,2.2,0,0,1,1.63.7,2.35,2.35,0,0,1,.68,1.68,2.27,2.27,0,0,1-.68,1.66A2.25,2.25,0,0,1,193.79,52.41Z\"><\/path><path class=\"cls-1\" d=\"M199.42,68.58l.32-4.58a3.58,3.58,0,0,0,1.89-.37,1.89,1.89,0,0,0,.71-1.38,15.57,15.57,0,0,0,.09-2.91l-.66-16.69h4.76l.7,17.08a18.7,18.7,0,0,1-.13,3.66,6.27,6.27,0,0,1-1,2.78,5,5,0,0,1-2.4,1.78A11.76,11.76,0,0,1,199.42,68.58Z\"><\/path><path class=\"cls-1\" d=\"M212,68.41l-.73-25.76h4.76l.73,25.76Z\"><\/path><path class=\"cls-1\" d=\"M241.42,69.14a23.53,23.53,0,0,1-5.58-.56A10.62,10.62,0,0,1,232.11,67,6.13,6.13,0,0,1,230,64.51a7.91,7.91,0,0,1-.65-3.24,13.75,13.75,0,0,1,.19-2.21,18.63,18.63,0,0,1,.53-2.29c.22-.73.41-1.39.58-2l4.06,1.05-.39,1.37a11,11,0,0,0-.31,1.47,10.39,10.39,0,0,0-.11,1.47,3.86,3.86,0,0,0,.7,2.24,4.6,4.6,0,0,0,2.5,1.59,17.65,17.65,0,0,0,5.17.58l.7,3.5ZM241,53a2.24,2.24,0,0,1-1.65-.66,2.2,2.2,0,0,1-.66-1.61,2.36,2.36,0,0,1,.66-1.66,2.18,2.18,0,0,1,1.68-.72,2.09,2.09,0,0,1,1.58.72,2.32,2.32,0,0,1,.66,1.62,2.24,2.24,0,0,1-.66,1.65A2.21,2.21,0,0,1,241,53Zm.45,16.17.91-4.58q2.86,0,5-.21a18,18,0,0,0,3.64-.67,5.76,5.76,0,0,0,2.21-1.13,2.15,2.15,0,0,0,.73-1.63,13.91,13.91,0,0,0-.42-3.17,35,35,0,0,0-1.08-3.62l4.34-1.33q.45,1.19.87,2.61a25.65,25.65,0,0,1,.68,2.85,14.51,14.51,0,0,1,.27,2.69,6.73,6.73,0,0,1-1,3.68,7.09,7.09,0,0,1-3,2.55,17.83,17.83,0,0,1-5.32,1.49A55.27,55.27,0,0,1,241.42,69.14ZM246.78,53a2.24,2.24,0,0,1-1.65-.66,2.16,2.16,0,0,1-.66-1.58,2.37,2.37,0,0,1,.66-1.68,2.23,2.23,0,0,1,1.68-.7,2.1,2.1,0,0,1,1.59.7,2.37,2.37,0,0,1,.65,1.65A2.25,2.25,0,0,1,246.78,53Z\"><\/path><path class=\"cls-1\" d=\"M263.26,68.41l-.73-25.76h4.76L268,68.41Z\"><\/path><path class=\"cls-1\" d=\"M271.87,76.46,270.82,72a29,29,0,0,0,3.9-.73,9.89,9.89,0,0,0,2.94-1.3,5.28,5.28,0,0,0,1.88-2.2,8.31,8.31,0,0,0,.63-3.47,16.65,16.65,0,0,0-.13-2.1,8.74,8.74,0,0,0-.36-1.66,3,3,0,0,0-.63-1.1,1.3,1.3,0,0,0-.95-.39,1.34,1.34,0,0,0-1,.44,3.07,3.07,0,0,0-.7,1.14,4.26,4.26,0,0,0-.26,1.54,2.06,2.06,0,0,0,.26,1.1,1.5,1.5,0,0,0,.73.63,2.93,2.93,0,0,0,1.11.19,6.81,6.81,0,0,0,1.36-.15,6.61,6.61,0,0,0,1.4-.48l.14,3.75a7.27,7.27,0,0,1-1.8.94,6.35,6.35,0,0,1-2.26.39A6.51,6.51,0,0,1,275,68.2a4.64,4.64,0,0,1-1.72-1,4.93,4.93,0,0,1-1.12-1.73,6.47,6.47,0,0,1-.4-2.37,10.88,10.88,0,0,1,.47-3.15,9.65,9.65,0,0,1,1.39-2.8,7.19,7.19,0,0,1,2.1-2,4.87,4.87,0,0,1,2.62-.74,4.93,4.93,0,0,1,2.68.77,6.41,6.41,0,0,1,2,2.16,11.35,11.35,0,0,1,1.26,3.16,16.07,16.07,0,0,1,.44,3.82,11.67,11.67,0,0,1-1.63,6.28,11.18,11.18,0,0,1-4.52,4.08A18.46,18.46,0,0,1,271.87,76.46Z\"><\/path><path class=\"cls-1\" d=\"M287.44,67.46l1.06-4.34a11.62,11.62,0,0,0,2.29.58,14.18,14.18,0,0,0,2.18.19,5.56,5.56,0,0,0,1.63-.21,2,2,0,0,0,1-.68,1.93,1.93,0,0,0,.37-1.24,7.91,7.91,0,0,0-.28-1.89A15.24,15.24,0,0,0,294.57,57a41.44,41.44,0,0,0-2.72-4.43L296.23,50a50.11,50.11,0,0,1,2.69,4.69,29.58,29.58,0,0,1,1.72,4.1,10.74,10.74,0,0,1,.59,3.25,6.87,6.87,0,0,1-.78,3.22,5.77,5.77,0,0,1-2.51,2.42,9.56,9.56,0,0,1-4.51.91,19.72,19.72,0,0,1-2.05-.12,14.63,14.63,0,0,1-2.17-.41A9.5,9.5,0,0,1,287.44,67.46Z\"><\/path><path class=\"cls-1\" d=\"M303.69,42.54l-.49-2.17,1.73-.33,1.2-.26-.38.84a4.05,4.05,0,0,1-1.59-1.12,2.93,2.93,0,0,1-.79-2.1,3.08,3.08,0,0,1,.47-1.77,3,3,0,0,1,1.26-1,4.31,4.31,0,0,1,1.73-.35,6.06,6.06,0,0,1,.92.07,5,5,0,0,1,.87.21l-.28,2.06-.67-.12a5.14,5.14,0,0,0-.66,0,1.45,1.45,0,0,0-1,.3,1,1,0,0,0-.35.78,1.5,1.5,0,0,0,.4,1,3.19,3.19,0,0,0,.95.72,2.82,2.82,0,0,0,.89.29l-1.54.14c.58-.16,1.13-.32,1.63-.49s1-.32,1.45-.49l.63,2.07q-.81.29-1.89.63T306,42C305.22,42.21,304.46,42.38,303.69,42.54Zm1.64,25.87-.66-23.21h4.83l.66,23.21Z\"><\/path><path class=\"cls-1\" d=\"M164.63,99.15a15.08,15.08,0,0,1-4,.44,10.45,10.45,0,0,1-3.69-.73,6,6,0,0,1-2.66-2,5.5,5.5,0,0,1-1-3.39,7.17,7.17,0,0,1,.78-3.36,8.85,8.85,0,0,1,2.19-2.68,13.56,13.56,0,0,1,3.27-2,22.62,22.62,0,0,1,4-1.26L164,89a9,9,0,0,0-2.4.44,7.67,7.67,0,0,0-1.93.91,4.51,4.51,0,0,0-1.27,1.22,2.59,2.59,0,0,0-.46,1.49,1.46,1.46,0,0,0,.42,1.08,2.93,2.93,0,0,0,1.1.67,5.93,5.93,0,0,0,1.54.3,8.5,8.5,0,0,0,1.74-.09,7.22,7.22,0,0,0,1.64-.46Zm-5.7-21.24a2.27,2.27,0,0,1-2.31-2.28,2.38,2.38,0,0,1,.66-1.66,2.19,2.19,0,0,1,1.68-.72,2.09,2.09,0,0,1,1.58.72,2.34,2.34,0,0,1,.66,1.63,2.23,2.23,0,0,1-.66,1.64A2.18,2.18,0,0,1,158.93,77.91Zm11.23,24.67a10,10,0,0,1-3.69-.63A5.19,5.19,0,0,1,164,99.87a7.81,7.81,0,0,1-1-3.9l-.67-14.25h4.69l.6,12.64a7.87,7.87,0,0,0,.36,2.26,1.87,1.87,0,0,0,.93,1.08,3.86,3.86,0,0,0,1.65.3,2.17,2.17,0,0,1,1.73.63,2.59,2.59,0,0,1-.12,3.31A2.68,2.68,0,0,1,170.16,102.58Zm-5.42-24.67a2.22,2.22,0,0,1-1.65-.67,2.14,2.14,0,0,1-.66-1.57,2.37,2.37,0,0,1,.66-1.68,2.21,2.21,0,0,1,1.68-.7,2.07,2.07,0,0,1,1.59.7,2.3,2.3,0,0,1,.65,1.64,2.27,2.27,0,0,1-2.27,2.28Z\"><\/path><path class=\"cls-1\" d=\"M170.16,102.58l.35-4.58a6.55,6.55,0,0,0,2-.26,2.66,2.66,0,0,0,1.33-1,7,7,0,0,0,.91-2.27c.24-1,.48-2.35.72-4l4.41.74c-.05.37-.11.79-.19,1.24s-.16.92-.21,1.4a11.14,11.14,0,0,0-.09,1.38,3,3,0,0,0,.22,1.19,2.09,2.09,0,0,0,.74.88,4.2,4.2,0,0,0,1.4.56,9.67,9.67,0,0,0,2.19.21,2.1,2.1,0,0,1,1.69.63,2.28,2.28,0,0,1,.55,1.57,2.31,2.31,0,0,1-.67,1.74,2.64,2.64,0,0,1-1.92.64,14.08,14.08,0,0,1-3-.28,5.59,5.59,0,0,1-2.14-.87,4.08,4.08,0,0,1-1.31-1.54,6.5,6.5,0,0,1-.61-2.31l1.57,0a8.06,8.06,0,0,1-1.47,2.68,5.65,5.65,0,0,1-2,1.49,8.06,8.06,0,0,1-2.22.65A17.27,17.27,0,0,1,170.16,102.58Zm3.36,7.81a2.3,2.3,0,0,1-2.31-2.28,2.34,2.34,0,0,1,.67-1.68,2.19,2.19,0,0,1,1.64-.7,2.16,2.16,0,0,1,1.61.7,2.34,2.34,0,0,1,.67,1.68,2.21,2.21,0,0,1-.67,1.6A2.18,2.18,0,0,1,173.52,110.39Zm5.85,0a2.25,2.25,0,0,1-1.68-.68,2.21,2.21,0,0,1-.67-1.6,2.34,2.34,0,0,1,.67-1.68,2.23,2.23,0,0,1,1.68-.7,2.12,2.12,0,0,1,1.57.7,2.38,2.38,0,0,1,.67,1.68,2.25,2.25,0,0,1-.67,1.6A2.14,2.14,0,0,1,179.37,110.39Z\"><\/path><path class=\"cls-1\" d=\"M200.19,103a34.41,34.41,0,0,1-4.86-.29,15.66,15.66,0,0,1-3.24-.79,5.8,5.8,0,0,1-2-1.24A7.1,7.1,0,0,1,188.82,99l1-.24a7,7,0,0,1-1.88,2.43,5.83,5.83,0,0,1-2.18,1.1,9,9,0,0,1-2.21.28l.35-4.58a2.44,2.44,0,0,0,1.44-.37,2.62,2.62,0,0,0,.87-1.19,13.74,13.74,0,0,0,.67-2.22c.21-.93.5-2.08.87-3.43l4.34,1.08c-.16.63-.3,1.18-.4,1.65s-.19.87-.25,1.21a6,6,0,0,0-.08.85,2.54,2.54,0,0,0,.29,1.25,2.3,2.3,0,0,0,1.14.84,10.57,10.57,0,0,0,2.47.52,37.27,37.27,0,0,0,4.25.19,27.75,27.75,0,0,0,4.36-.28,10.39,10.39,0,0,0,2.75-.75,3.38,3.38,0,0,0,1.47-1.19,2.94,2.94,0,0,0,.45-1.59,2.61,2.61,0,0,0-.3-1.26,2.51,2.51,0,0,0-.85-.93A2.56,2.56,0,0,0,206,92a4.52,4.52,0,0,0-2.19.6,9.74,9.74,0,0,0-2.17,1.61,24.27,24.27,0,0,0-2.05,2.22c-.65.81-1.26,1.62-1.82,2.43L193,98.28a38.18,38.18,0,0,1,2.9-4.24,25.94,25.94,0,0,1,3.31-3.51,15.43,15.43,0,0,1,3.55-2.4,8.38,8.38,0,0,1,3.71-.88,7,7,0,0,1,3.61.9,6.11,6.11,0,0,1,2.38,2.48,8.22,8.22,0,0,1-.56,8.21,9,9,0,0,1-4.29,3.06A20.82,20.82,0,0,1,200.19,103Zm15.33-.42a10.46,10.46,0,0,1-2.71-.36,14.08,14.08,0,0,1-2.47-.93,7.83,7.83,0,0,1-1.85-1.23L211.43,97a7.72,7.72,0,0,0,2.13.8,10.28,10.28,0,0,0,2.28.25,2.16,2.16,0,0,1,1.71.63,2.29,2.29,0,0,1,.56,1.57,2.34,2.34,0,0,1-.66,1.74A2.68,2.68,0,0,1,215.52,102.58Z\"><\/path><path class=\"cls-1\" d=\"M215.52,102.58l.32-4.58a20.21,20.21,0,0,0,3.2-.26,25.51,25.51,0,0,0,3.17-.74,20.18,20.18,0,0,0,3.09-1.21,21.85,21.85,0,0,0,3-1.75,16.13,16.13,0,0,0-2.31-1.1,14.5,14.5,0,0,0-2.3-.66,11.2,11.2,0,0,0-2.32-.23c-.38,0-.74,0-1.09,0s-.71.06-1.07.11a11.18,11.18,0,0,0-1.1.21l-.8-4.62a11.48,11.48,0,0,1,1.9-.4,13.73,13.73,0,0,1,1.91-.13,12.71,12.71,0,0,1,3.4.42,15.35,15.35,0,0,1,2.73,1c.81.4,1.55.81,2.22,1.22a17.3,17.3,0,0,0,1.91,1,4.28,4.28,0,0,0,1.82.42h.91l.56,4.27a6.28,6.28,0,0,0-2.28.65,20.18,20.18,0,0,0-2.24,1.33c-.77.53-1.6,1.07-2.5,1.63a25.53,25.53,0,0,1-3.06,1.61,19.63,19.63,0,0,1-3.94,1.24A24.5,24.5,0,0,1,215.52,102.58Zm5.92-18.83a2.32,2.32,0,0,1-2.35-2.31,2.39,2.39,0,0,1,.68-1.71,2.27,2.27,0,0,1,1.7-.7,2.2,2.2,0,0,1,1.63.7,2.33,2.33,0,0,1,.68,1.68,2.27,2.27,0,0,1-.68,1.66A2.25,2.25,0,0,1,221.44,83.75Zm14,18.83a9.91,9.91,0,0,1-2.21-.24,6.19,6.19,0,0,1-2-.88,6.43,6.43,0,0,1-1.7-1.71,9.4,9.4,0,0,1-1.24-2.7l2.69-2a4.86,4.86,0,0,0,1.21,1.82,4,4,0,0,0,1.63.87,7.21,7.21,0,0,0,2,.25,2.1,2.1,0,0,1,1.69.63,2.33,2.33,0,0,1,.55,1.57,2.37,2.37,0,0,1-.65,1.74A2.64,2.64,0,0,1,235.44,102.58Z\"><\/path><path class=\"cls-1\" d=\"M235.44,102.58l.35-4.58a4.2,4.2,0,0,0,1.47-.23,2.1,2.1,0,0,0,1-.94,8.38,8.38,0,0,0,.77-2.17c.23-1,.5-2.27.81-3.91l4.41.81c-.1.51-.23,1.17-.39,2a10.6,10.6,0,0,0-.24,2.06,3.36,3.36,0,0,0,.21,1.28,1.63,1.63,0,0,0,.75.81,3.41,3.41,0,0,0,1.56.29,3.48,3.48,0,0,0,1.29-.21,1.89,1.89,0,0,0,.91-.94,10.16,10.16,0,0,0,.74-2.24c.23-1,.46-2.36.7-4.06l4.48.7c-.1.56-.2,1.14-.3,1.73s-.19,1.16-.26,1.7A10.7,10.7,0,0,0,253.6,96a2.35,2.35,0,0,0,.23,1.07,1.61,1.61,0,0,0,.82.7,4.41,4.41,0,0,0,1.68.26,2.48,2.48,0,0,0,1.94-.72,3.49,3.49,0,0,0,.65-2.36c0-.54,0-1.12,0-1.75s-.07-1.34-.14-2.14-.18-1.68-.32-2.66l4.41-.35c.16,2.08.34,3.77.54,5.08a12.3,12.3,0,0,0,.77,3,3.06,3.06,0,0,0,1.23,1.47,3.78,3.78,0,0,0,1.87.42,2.17,2.17,0,0,1,1.73.63,2.33,2.33,0,0,1,.55,1.57,2.37,2.37,0,0,1-.65,1.74,2.64,2.64,0,0,1-1.94.64,8.27,8.27,0,0,1-1.58-.17,5.87,5.87,0,0,1-1.7-.68,5.65,5.65,0,0,1-1.55-1.4A7.25,7.25,0,0,1,261,98l.74.17a6.09,6.09,0,0,1-1.21,2.61,4.8,4.8,0,0,1-1.91,1.38,6.93,6.93,0,0,1-2.52.42,6.78,6.78,0,0,1-2.41-.42,3.62,3.62,0,0,1-1.79-1.41,4.92,4.92,0,0,1-.7-2.65h1.09a9,9,0,0,1-1.49,2.89,4,4,0,0,1-1.94,1.28,10.43,10.43,0,0,1-2.77.31,7.45,7.45,0,0,1-2.12-.31,4.42,4.42,0,0,1-2-1.28,6.16,6.16,0,0,1-1.31-2.92l1.93-.07a8.65,8.65,0,0,1-1.89,3.06,4.67,4.67,0,0,1-2.33,1.26A14.27,14.27,0,0,1,235.44,102.58Zm13.23-17.29a2.1,2.1,0,0,1-1.56-.66,2.19,2.19,0,0,1-.65-1.58,2.26,2.26,0,0,1,.65-1.59,2.12,2.12,0,0,1,1.59-.68,2.16,2.16,0,0,1,1.58.68,2.25,2.25,0,0,1-1.61,3.83Zm2.76-4.93a2.17,2.17,0,0,1-1.57-.65,2.11,2.11,0,0,1-.67-1.59,2.21,2.21,0,0,1,.65-1.58,2.14,2.14,0,0,1,1.59-.66,2.1,2.1,0,0,1,1.56.66,2.17,2.17,0,0,1,.65,1.54,2.21,2.21,0,0,1-.65,1.63A2.13,2.13,0,0,1,251.43,80.36Zm2.94,4.93a2.08,2.08,0,0,1-1.57-.66,2.21,2.21,0,0,1-.63-1.58,2.27,2.27,0,0,1,.63-1.61,2.12,2.12,0,0,1,1.61-.66,2.06,2.06,0,0,1,1.54.66,2.31,2.31,0,0,1,0,3.19A2.1,2.1,0,0,1,254.37,85.29Z\"><\/path><path class=\"cls-1\" d=\"M266.94,102.58l.31-4.58a3.53,3.53,0,0,0,1.89-.37,1.93,1.93,0,0,0,.72-1.38,17.54,17.54,0,0,0,.09-2.91l-.67-16.69H274l.7,17.08a19.56,19.56,0,0,1-.12,3.66,6.39,6.39,0,0,1-1,2.78,5.13,5.13,0,0,1-2.4,1.78A11.79,11.79,0,0,1,266.94,102.58Z\"><\/path><path class=\"cls-1\" d=\"M279.54,102.41l-.74-25.76h4.76l.73,25.76Z\"><\/path><path class=\"cls-1\" d=\"M305.78,116.06a15.65,15.65,0,0,1-3.92-.49,10,10,0,0,1-3.27-1.51,7.18,7.18,0,0,1-2.22-2.55,7.81,7.81,0,0,1-.81-3.68,8.46,8.46,0,0,1,.86-3.86,12.33,12.33,0,0,1,2.19-3.08,25.54,25.54,0,0,1,2.85-2.56c1-.78,2-1.53,2.89-2.24A15.62,15.62,0,0,0,306.61,94a3.56,3.56,0,0,0,.92-2.24,1.2,1.2,0,0,0-.26-.87,2,2,0,0,0-.82-.61,3.12,3.12,0,0,0-1.3-.23,5.75,5.75,0,0,0-1.24.14,7.81,7.81,0,0,0-1.22.38,5,5,0,0,0-1.11.63c.49.45,1,.94,1.56,1.49s1.09,1.12,1.61,1.72,1,1.2,1.49,1.83a6.51,6.51,0,0,0,1.64.84,16.22,16.22,0,0,0,1.91.53,19.46,19.46,0,0,0,2,.31c.7.07,1.38.11,2,.11a2.12,2.12,0,0,1,1.68.63,2.29,2.29,0,0,1,.56,1.57,2.31,2.31,0,0,1-.68,1.74,2.63,2.63,0,0,1-1.88.64,22.63,22.63,0,0,1-4.14-.36,13.79,13.79,0,0,1-3.68-1.25,16.39,16.39,0,0,1-3.38-2.31c-.42-.6-.89-1.21-1.41-1.82l-1.53-1.71c-.49-.54-.91-1-1.26-1.33a2.86,2.86,0,0,1-.28-.63c-.11-.33-.22-.68-.31-1.07a4.28,4.28,0,0,1-.14-.82,3,3,0,0,1,.68-1.73,8,8,0,0,1,1.82-1.75,10.37,10.37,0,0,1,2.61-1.35,9,9,0,0,1,3-.53,7.12,7.12,0,0,1,4.73,1.4A4.72,4.72,0,0,1,312,91a7.09,7.09,0,0,1-.79,3.49A12,12,0,0,1,309,97.4a35.06,35.06,0,0,1-2.8,2.51c-1,.78-1.92,1.55-2.82,2.32a11.49,11.49,0,0,0-2.19,2.44,4.83,4.83,0,0,0-.84,2.71,3.67,3.67,0,0,0,.49,2,3.89,3.89,0,0,0,1.28,1.24,5.7,5.7,0,0,0,1.75.68,9.08,9.08,0,0,0,1.94.21,12.79,12.79,0,0,0,1.91-.15,17.63,17.63,0,0,0,2.08-.48,23.18,23.18,0,0,0,2.28-.8l1.47,3.92a15.29,15.29,0,0,1-2.52,1.14,18.7,18.7,0,0,1-2.71.71A13.89,13.89,0,0,1,305.78,116.06Z\"><\/path><path class=\"cls-1\" d=\"M313.55,102.58,313.9,98a14.56,14.56,0,0,0,3.1-.25,2.46,2.46,0,0,0,1.54-.85,3,3,0,0,0,.44-1.74,14.44,14.44,0,0,0-.26-2.5c-.18-.94-.4-1.91-.67-2.89s-.54-1.87-.82-2.69l4.44-1.3a26.93,26.93,0,0,1,.88,2.77c.28,1,.52,2.13.72,3.25a19.53,19.53,0,0,1,.29,3.26,8.63,8.63,0,0,1-.75,3.87,5.3,5.3,0,0,1-2.12,2.27,9.23,9.23,0,0,1-3.16,1.09A25.64,25.64,0,0,1,313.55,102.58Zm2.49,7.81a2.29,2.29,0,0,1-2.31-2.28,2.37,2.37,0,0,1,.66-1.68,2.26,2.26,0,0,1,1.68-.7,2.13,2.13,0,0,1,1.58.7,2.34,2.34,0,0,1,.66,1.65,2.21,2.21,0,0,1-.68,1.63A2.18,2.18,0,0,1,316,110.39Zm5.81,0a2.29,2.29,0,0,1-2.31-2.28,2.37,2.37,0,0,1,.66-1.68,2.26,2.26,0,0,1,1.68-.7,2.13,2.13,0,0,1,1.58.7,2.34,2.34,0,0,1,.66,1.65,2.27,2.27,0,0,1-.66,1.63A2.18,2.18,0,0,1,321.85,110.39Z\"><\/path><path class=\"cls-1\" d=\"M326.33,110.46l-2.17-4.41a16.75,16.75,0,0,0,3.8-2.36,7.85,7.85,0,0,0,2-2.65,7.13,7.13,0,0,0,.63-3,8.45,8.45,0,0,0-.28-2.14,14.38,14.38,0,0,0-.78-2.25c-.34-.79-.73-1.61-1.18-2.47L332.8,89a29.8,29.8,0,0,1,2,4.68,13.65,13.65,0,0,1,.63,4,14.28,14.28,0,0,1-.31,3,11.58,11.58,0,0,1-1,2.8,13,13,0,0,1-1.73,2.57,14.47,14.47,0,0,1-2.56,2.31A22.88,22.88,0,0,1,326.33,110.46Zm4.44-25.27a2.29,2.29,0,0,1-1.66-.68,2.25,2.25,0,0,1-.68-1.63,2.39,2.39,0,0,1,.68-1.72,2.31,2.31,0,0,1,1.7-.7,2.23,2.23,0,0,1,1.63.7,2.35,2.35,0,0,1,.68,1.68,2.32,2.32,0,0,1-2.35,2.35Z\"><\/path><path class=\"cls-1\" d=\"M339.77,110.46l-1-4.45a34,34,0,0,0,4-.78,10.36,10.36,0,0,0,3-1.28,5.22,5.22,0,0,0,1.83-2.14,7.44,7.44,0,0,0,.6-3.32,10.88,10.88,0,0,0-.53-4c-.37-1-.91-1.47-1.61-1.47a1.31,1.31,0,0,0-1,.49,3.25,3.25,0,0,0-.63,1.23,5.33,5.33,0,0,0-.21,1.47,2.68,2.68,0,0,0,.17,1,1.31,1.31,0,0,0,.72.66,4.31,4.31,0,0,0,1.63.28,19.64,19.64,0,0,0,2.9-.17H355a2.18,2.18,0,0,1,1.7.63,2.21,2.21,0,0,1,.58,1.57,2.27,2.27,0,0,1-.67,1.75,2.68,2.68,0,0,1-1.92.63h-7.56a11.39,11.39,0,0,1-4-.63,4.88,4.88,0,0,1-3.38-4.9,9.68,9.68,0,0,1,.49-3,11.61,11.61,0,0,1,1.36-2.84,7.14,7.14,0,0,1,2.09-2.08,4.87,4.87,0,0,1,2.67-.77,4.94,4.94,0,0,1,3.43,1.28,8,8,0,0,1,2.21,3.5,15.75,15.75,0,0,1,.8,5,12.17,12.17,0,0,1-1.68,6.53,10.88,10.88,0,0,1-4.55,4A19.9,19.9,0,0,1,339.77,110.46Z\"><\/path><path class=\"cls-1\" d=\"M354.68,102.58,355,98a6.55,6.55,0,0,0,2-.26,2.7,2.7,0,0,0,1.33-1,7,7,0,0,0,.91-2.27c.24-1,.48-2.35.71-4l4.41.74c0,.37-.11.79-.19,1.24s-.15.92-.21,1.4a11.14,11.14,0,0,0-.09,1.38,3,3,0,0,0,.23,1.19,2,2,0,0,0,.74.88,4.11,4.11,0,0,0,1.4.56,9.63,9.63,0,0,0,2.18.21,2.13,2.13,0,0,1,1.7.63,2.28,2.28,0,0,1,.54,1.54,2.38,2.38,0,0,1-.66,1.77,2.66,2.66,0,0,1-1.93.64,14.21,14.21,0,0,1-3-.28,5.6,5.6,0,0,1-2.13-.87,4.08,4.08,0,0,1-1.31-1.54,6.71,6.71,0,0,1-.62-2.31l1.58,0a8.24,8.24,0,0,1-1.47,2.68,5.75,5.75,0,0,1-2,1.49,8.16,8.16,0,0,1-2.22.65A17.39,17.39,0,0,1,354.68,102.58ZM359,86.52a2.26,2.26,0,0,1-1.66-.67,2.15,2.15,0,0,1-.69-1.61,2.39,2.39,0,0,1,.67-1.66,2.18,2.18,0,0,1,1.68-.72,2.11,2.11,0,0,1,1.61.72,2.34,2.34,0,0,1,.66,1.63,2.23,2.23,0,0,1-.66,1.64A2.17,2.17,0,0,1,359,86.52Zm5.81,0a2.29,2.29,0,0,1-2.31-2.27,2.36,2.36,0,0,1,.66-1.68,2.23,2.23,0,0,1,1.68-.7,2.09,2.09,0,0,1,1.58.7,2.31,2.31,0,0,1,.66,1.64,2.2,2.2,0,0,1-.68,1.63A2.14,2.14,0,0,1,364.83,86.55Z\"><\/path><path class=\"cls-1\" d=\"M368.05,102.58l.31-4.58a3.53,3.53,0,0,0,1.89-.37,1.87,1.87,0,0,0,.72-1.38,16.5,16.5,0,0,0,.09-2.91l-.67-16.69h4.76l.7,17.08a19.56,19.56,0,0,1-.12,3.66,6.39,6.39,0,0,1-1,2.78,5.13,5.13,0,0,1-2.4,1.78A11.79,11.79,0,0,1,368.05,102.58Z\"><\/path><path class=\"cls-1\" d=\"M380.65,102.41l-.74-25.76h4.76l.74,25.76Z\"><\/path><path class=\"cls-1\" d=\"M389.26,110.46,388.21,106a29,29,0,0,0,3.9-.73,9.89,9.89,0,0,0,2.94-1.3,5.26,5.26,0,0,0,1.87-2.2,8.31,8.31,0,0,0,.63-3.47,16.76,16.76,0,0,0-.12-2.1,8,8,0,0,0-.37-1.66,2.75,2.75,0,0,0-.63-1.1,1.28,1.28,0,0,0-.94-.39,1.38,1.38,0,0,0-1,.44,3.2,3.2,0,0,0-.7,1.14,4.48,4.48,0,0,0-.26,1.54,2.16,2.16,0,0,0,.26,1.1,1.57,1.57,0,0,0,.74.63,2.85,2.85,0,0,0,1.1.19A6.9,6.9,0,0,0,397,98a6.81,6.81,0,0,0,1.4-.48l.14,3.75a7.53,7.53,0,0,1-1.81.94,6.29,6.29,0,0,1-2.25.39,6.61,6.61,0,0,1-2.16-.35,4.68,4.68,0,0,1-1.71-1,4.93,4.93,0,0,1-1.12-1.73,6.47,6.47,0,0,1-.4-2.37,10.55,10.55,0,0,1,.47-3.15A9.62,9.62,0,0,1,391,91.1a7.45,7.45,0,0,1,2.1-2,4.93,4.93,0,0,1,2.63-.74,4.87,4.87,0,0,1,2.67.77,6.22,6.22,0,0,1,2,2.16,11.67,11.67,0,0,1,1.27,3.16,16.08,16.08,0,0,1,.43,3.82,11.58,11.58,0,0,1-1.63,6.28,11.15,11.15,0,0,1-4.51,4.08A18.46,18.46,0,0,1,389.26,110.46Z\"><\/path><path class=\"cls-1\" d=\"M109.33,58.68h-3.79V54.89a5.67,5.67,0,0,0-5.68-5.68H96.07V45.42a5.67,5.67,0,0,0-5.68-5.68H35.46a5.68,5.68,0,0,0-5.68,5.68V96.56a5.68,5.68,0,0,0,5.68,5.68h3.79V106a5.68,5.68,0,0,0,5.68,5.68h3.79v3.79a5.68,5.68,0,0,0,5.68,5.68h54.93A5.67,5.67,0,0,0,115,115.5V64.36a5.67,5.67,0,0,0-5.68-5.68ZM35.46,98.45a1.89,1.89,0,0,1-1.89-1.89V45.42a1.89,1.89,0,0,1,1.89-1.89H90.39a1.88,1.88,0,0,1,1.89,1.89V96.56a1.88,1.88,0,0,1-1.89,1.89Zm9.47,9.47A1.89,1.89,0,0,1,43,106v-3.79H90.39a5.67,5.67,0,0,0,5.68-5.68V53h3.79a1.88,1.88,0,0,1,1.89,1.89V106a1.88,1.88,0,0,1-1.89,1.89Zm66.29,7.58a1.88,1.88,0,0,1-1.89,1.89H54.4a1.89,1.89,0,0,1-1.89-1.89v-3.79H99.86a5.67,5.67,0,0,0,5.68-5.68V62.47h3.79a1.88,1.88,0,0,1,1.89,1.89Z\"><\/path><path class=\"cls-1\" d=\"M76.51,71.32a1.9,1.9,0,0,0-2.64.49,13.25,13.25,0,0,1-9.05,5.69V73.71a9.5,9.5,0,0,0,7.58-9.35V56.78a9.47,9.47,0,1,0-18.94,0v7.58A9.46,9.46,0,0,0,61,73.64v3.79A13.26,13.26,0,0,1,52,71.75a1.9,1.9,0,0,0-3.14,2.14A17.06,17.06,0,0,0,61,81.29v2H57.24a5.68,5.68,0,1,0,0,11.36H68.61a5.68,5.68,0,1,0,0-11.36H64.82v-2A17,17,0,0,0,77,74a1.87,1.87,0,0,0,.29-1.42,1.89,1.89,0,0,0-.79-1.21Zm-7.9,15.77a1.9,1.9,0,0,1,0,3.79H57.24a1.9,1.9,0,0,1,0-3.79ZM62.93,70a5.65,5.65,0,0,1-5.35-3.79h1.56a1.89,1.89,0,0,0,0-3.78h-1.9V58.68h1.9a1.9,1.9,0,0,0,0-3.79H57.58a5.68,5.68,0,0,1,7.61-3.3,5.7,5.7,0,0,1,3.09,3.3H66.71a1.9,1.9,0,0,0,0,3.79h1.9v3.79h-1.9a1.89,1.89,0,0,0,0,3.78h1.57A5.75,5.75,0,0,1,66.2,69a5.65,5.65,0,0,1-3.27,1Z\"><\/path><rect class=\"cls-2\" x=\"0.5\" y=\"0.5\" width=\"520\" height=\"152\"><\/rect><\/svg>\t\t\t\t\t\t\t\t<\/a>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-wrap\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow-border\"><\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-arrow\"><\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"premium-accordion-tab-content\" id=\"premium-accordion-content-6\">\r\n\t\t\t\t\t\t\t\t\t\t<section id=\"section-iconbox-6-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3584\" class=\"elementor elementor-3584 elementor-2336\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e73fa6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e73fa6c\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-06253fc\" data-id=\"06253fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4de7bb dce_masking-none elementor-widget elementor-widget-image\" data-id=\"c4de7bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1922\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2.png\" class=\"attachment-full size-full wp-image-4442\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2.png 1080w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-575x1024.png 575w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-768x1367.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-863x1536.png 863w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e0397c2\" data-id=\"e0397c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-026a796 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"026a796\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-12c3348\" data-id=\"12c3348\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c40409e elementor-widget elementor-widget-text-editor\" data-id=\"c40409e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0627\u0646\u0634\u0631 \u0627\u0644\u0645\u062d\u062a\u0648\u0649 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0645\u0628\u0627\u0634\u0631\u0629 \u0639\u0644\u0649 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0645\u062b\u0644 Whatsapp \u0648 Twitter. \u064a\u0645\u0643\u0646 \u0625\u0646\u0634\u0627\u0621 \u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0639\u0645\u0644\u064a\u0627\u062a \u0625\u0646\u0634\u0627\u0621 \u0627\u0644\u0645\u062d\u062a\u0648\u0649 \u0627\u0644\u0645\u062e\u0635\u0635 \u0628\u0634\u0643\u0644 \u0645\u0634\u062a\u0631\u0643.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<\/section>\r\n\t\t\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"premium-content-wrap premium-tabs-vertical\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<section id=\"section-iconbox-0-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3532\" class=\"elementor elementor-3532 elementor-1167\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-769878e elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"769878e\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d803fb\" data-id=\"6d803fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3064fa6 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"3064fa6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1082\" height=\"1920\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4.png\" class=\"attachment-full size-full wp-image-4781\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4.png 1082w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-577x1024.png 577w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-768x1363.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-1-Final-4-866x1536.png 866w\" sizes=\"(max-width: 1082px) 100vw, 1082px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11ae159\" data-id=\"11ae159\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f334a27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f334a27\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1c28618\" data-id=\"1c28618\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5318d7 elementor-widget elementor-widget-text-editor\" data-id=\"e5318d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u0646\u0633\u0645\u064a\u0647\u0627 \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0639\u0633\u0644 \u0648\u0647\u064a \u062a\u0623\u062a\u064a \u0645\u0639 \u0628\u0631\u0648\u062a\u0648\u0643\u0648\u0644 \u062f\u0631\u062f\u0634\u0629 \u0648\u0645\u0634\u0641\u0631\u0629 \u0648\u0645\u0624\u062a\u0645\u0631\u0627\u062a \u0635\u0648\u062a\u064a\u0629 \u0648\u0647\u064a\u0643\u0644 \u0645\u062c\u0644\u062f \u0645\u0637\u0627\u0628\u0642 \u0644\u0625\u062f\u0627\u0631\u0629 \u062c\u0645\u064a\u0639 \u0645\u0633\u062a\u0646\u062f\u0627\u062a\u0643 \u0628\u0634\u0643\u0644 \u062c\u0645\u0627\u0639\u064a.\r\n\r\n\u064a\u0645\u0643\u0646 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0639\u0633\u0644 \u0645\u0646 \u0642\u0628\u0644 \u0627\u0644\u0632\u0645\u0644\u0627\u0621 \u0645\u0646 \u0625\u062d\u062f\u0649 \u0627\u0644\u0648\u0633\u0627\u0626\u0637 \u0623\u0648 \u0625\u0639\u062f\u0627\u062f\u0647\u0627 \u0644\u0644\u062a\u0639\u0627\u0648\u0646 \u0627\u0644\u0634\u0628\u0643\u064a \u0628\u064a\u0646 \u0645\u062e\u062a\u0644\u0641 \u0627\u0644\u0634\u0631\u0643\u0627\u0621.\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/section>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<section id=\"section-iconbox-1-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3534\" class=\"elementor elementor-3534 elementor-1309\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3f21d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3f21d4\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5995502\" data-id=\"5995502\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a19ea dce_masking-none elementor-widget elementor-widget-image\" data-id=\"39a19ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"1262\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder.png\" class=\"attachment-full size-full wp-image-4444\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder.png 697w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder-166x300.png 166w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/2-Mobiler-Recorder-566x1024.png 566w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4d7361\" data-id=\"c4d7361\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9d3588f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d3588f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c3761db\" data-id=\"c3761db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ea779b elementor-widget elementor-widget-text-editor\" data-id=\"9ea779b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-1-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p><strong>\u0645\u0647\u0645\u0627 \u0643\u0627\u0646 \u062c\u0647\u0627\u0632\u0643 <\/strong><\/p><p>: \u0625\u0630\u0627 \u0643\u0627\u0646 \u0645\u0632\u0648\u062f\u064b\u0627 \u0628\u0645\u064a\u0643\u0631\u0648\u0641\u0648\u0646 \u0623\u0648 \u062e\u0637 \u0625\u062f\u062e\u0627\u0644 \u060c \u0641\u0625\u0646 Colmena \u062a\u0642\u0648\u0645 \u0628\u062a\u062d\u0648\u064a\u0644\u0647 \u0625\u0644\u0649 \u0645\u0633\u062c\u0644 \u0635\u0648\u062a \u0645\u0639 \u0645\u0642\u064a\u0627\u0633 vu \u0648\u0636\u063a\u0637 \u0627\u0644\u062c\u0648\u062f\u0629.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/section>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<section id=\"section-iconbox-2-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3544\" class=\"elementor elementor-3544 elementor-1313\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7545dd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7545dd5\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7c9cedc\" data-id=\"7c9cedc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-571e5d7 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"571e5d7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1082\" height=\"1922\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4.png\" class=\"attachment-full size-full wp-image-4782\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4.png 1082w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-576x1024.png 576w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-768x1364.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Header-2-Final-4-865x1536.png 865w\" sizes=\"(max-width: 1082px) 100vw, 1082px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c19e27b\" data-id=\"c19e27b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-2891f6e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2891f6e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-42a1fcb\" data-id=\"42a1fcb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a11853c elementor-widget elementor-widget-text-editor\" data-id=\"a11853c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0645\u0633\u0627\u062d\u062a\u0643 \u0644\u0644\u062a\u0641\u0627\u0639\u0644 \u0645\u0639 \u0627\u0644\u0636\u064a\u0648\u0641 \u0648\u0627\u0644\u062e\u0628\u0631\u0627\u0621 \u0641\u064a \u0645\u0646\u0627\u0642\u0634\u0627\u062a \u0627\u0644\u0645\u0627\u0626\u062f\u0629 \u0627\u0644\u0645\u0633\u062a\u062f\u064a\u0631\u0629 \u0627\u0644\u0627\u0641\u062a\u0631\u0627\u0636\u064a\u0629 \u0648\u0627\u0644\u0645\u0642\u0627\u0628\u0644\u0627\u062a \u0627\u0644\u062c\u0645\u0627\u0639\u064a\u0629 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a. \u064a\u0645\u0643\u0646 \u062a\u0633\u062c\u064a\u0644 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u062d\u0627\u062f\u062b\u0627\u062a \u0623\u0648 \u0645\u0634\u0627\u0631\u0643\u062a\u0647\u0627 \u0645\u0628\u0627\u0634\u0631\u0629 \u0643\u062a\u062f\u0641\u0642\u0627\u062a \u0635\u0648\u062a\u064a\u0629.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/section>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<section id=\"section-iconbox-3-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3554\" class=\"elementor elementor-3554 elementor-2324\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-359b942 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"359b942\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c44573\" data-id=\"5c44573\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40375f5 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"40375f5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1236\" height=\"697\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2.png\" class=\"attachment-full size-full wp-image-4439\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2.png 1236w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2-300x169.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2-1024x577.png 1024w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/4-MobileEditing-2-768x433.png 768w\" sizes=\"(max-width: 1236px) 100vw, 1236px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4e1e59\" data-id=\"c4e1e59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-729adfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"729adfe\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-62e38ef\" data-id=\"62e38ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcdb26f elementor-widget elementor-widget-text-editor\" data-id=\"fcdb26f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0642\u0645 \u0628\u0642\u0635 \u0627\u0644\u0645\u0642\u0627\u0628\u0644\u0627\u062a \u0623\u0648 \u062a\u062d\u0631\u064a\u0631 \u062d\u0644\u0642\u0627\u062a \u0627\u0644\u0628\u0648\u062f\u0643\u0627\u0633\u062a \u0627\u0644\u0643\u0627\u0645\u0644\u0629 \u0645\u0646 \u0647\u0627\u062a\u0641\u0643 \u0627\u0644\u0645\u062d\u0645\u0648\u0644 \u0623\u0648 \u062c\u0647\u0627\u0632 \u0633\u0637\u062d \u0627\u0644\u0645\u0643\u062a\u0628. \u064a\u0645\u0643\u0646 \u0625\u062c\u0631\u0627\u0621 \u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u062a\u062d\u0631\u064a\u0631 \u0627\u0644\u0645\u062d\u0644\u064a\u0629 \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0632\u0627\u0645\u0646\u0629 \u0645\u0639 \u0627\u0644\u062a\u062e\u0632\u064a\u0646 \u0627\u0644\u0633\u062d\u0627\u0628\u064a \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u062a\u062d\u0631\u064a\u0631 \u0627\u0644\u062c\u0645\u0627\u0639\u064a.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/section>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<section id=\"section-iconbox-4-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3564\" class=\"elementor elementor-3564 elementor-2328\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a381ffe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a381ffe\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3698989\" data-id=\"3698989\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c3b420 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"1c3b420\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1084\" height=\"1925\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2.png\" class=\"attachment-full size-full wp-image-4440\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2.png 1084w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-577x1024.png 577w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-768x1364.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/5-Collaborative-Text-2-865x1536.png 865w\" sizes=\"(max-width: 1084px) 100vw, 1084px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17f3bbc\" data-id=\"17f3bbc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-053f2f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"053f2f6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-005a5c2\" data-id=\"005a5c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48685cc elementor-widget elementor-widget-text-editor\" data-id=\"48685cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0623\u062f\u0627\u0629 \u064a\u062f\u0648\u064a\u0629 \u0644\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0641\u064a \u062a\u062d\u0631\u064a\u0631 \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639 \u0623\u0648 \u0627\u0644\u0646\u0635\u0648\u0635 \u0623\u0648 \u0627\u0644\u0645\u0642\u0627\u0644\u0627\u062a. \u064a\u0645\u0643\u0646\u0643 \u0623\u064a\u0636\u064b\u0627 \u0625\u062f\u0631\u0627\u062c \u0635\u0648\u0631 \u0645\u0646 \u0635\u0627\u0644\u0627\u062a \u0627\u0644\u0639\u0631\u0636 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u0648\u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0645\u0646\u0634\u0648\u0631\u0627\u062a \u0628\u0634\u0643\u0644 \u062c\u0645\u0627\u0639\u064a\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/section>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<section id=\"section-iconbox-5-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3574\" class=\"elementor elementor-3574 elementor-2332\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-919470c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"919470c\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2921d21\" data-id=\"2921d21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36fb80e dce_masking-none elementor-widget elementor-widget-image\" data-id=\"36fb80e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1087\" height=\"2507\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2.png\" class=\"attachment-full size-full wp-image-4441\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2.png 1087w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-130x300.png 130w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-444x1024.png 444w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-768x1771.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-666x1536.png 666w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/6-Collabs-2-888x2048.png 888w\" sizes=\"(max-width: 1087px) 100vw, 1087px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fc8b18f\" data-id=\"fc8b18f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-4983175 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4983175\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c94c2d5\" data-id=\"c94c2d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab7469a elementor-widget elementor-widget-text-editor\" data-id=\"ab7469a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0627\u0644\u0645\u0633\u0627\u062d\u0627\u062a \u0627\u0644\u0627\u0641\u062a\u0631\u0627\u0636\u064a\u0629 \u060c \u0639\r\n\u0644\u0649 \u063a\u0631\u0627\u0631 \u0623\u0642\u0631\u0627\u0635 \u0627\u0644\u0639\u0633\u0644 \u0627\u0644\u062a\u064a \u062a\u0631\u0643\u0632 \u0639\u0644\u0649 \u0627\u0644\u062a\u0628\u0627\u062f\u0644 \u0648\u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u062c\u0645\u0627\u0639\u064a \u060c \u0645\u062f\u0641\u0648\u0639\u0629 \u0628\u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u0645\u062a\u0639\u0627\u0648\u0646\u0629. \u0642\u0645 \u0628\u0625\u0646\u0634\u0627\u0621 \u0627\u0644\u0645\u0633\u0627\u062d\u0627\u062a \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643 \u0645\u062b\u0644 \u062a\u0648\u0641\u064a\u0631 \u0645\u0633\u0627\u062d\u0627\u062a \u0644\u0644\u0646\u0633\u0627\u0621 \u060c \u0648\u0645\u062c\u0645\u0648\u0639\u0627\u062a \u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0627\u0644\u062d\u0642\u0627\u0626\u0642 \u060c \u0648\u062d\u0648\u0627\u0631\u0627\u062a \u0627\u0644\u062d\u0642\u0648\u0642 \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u060c \u0648\u0645\u0627 \u0625\u0644\u0649 \u0630\u0644\u0643 \u060c \u0633\u062a\u0648\u062c\u0647\u0643 \u0627\u0644\u0643\u062a\u064a\u0628\u0627\u062a \u0627\u0644\u0645\u0635\u063a\u0631\u0629 \u0637\u0631\u064a\u0642\u0643 &#8230;\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/section>\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<section id=\"section-iconbox-6-09e7e9d\" class=\"premium-tabs-content-section\">\r\n\t\t\t\t\t\t\t<div class=\"premium-tab-content\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"3584\" class=\"elementor elementor-3584 elementor-2336\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e73fa6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e73fa6c\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-06253fc\" data-id=\"06253fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4de7bb dce_masking-none elementor-widget elementor-widget-image\" data-id=\"c4de7bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1922\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2.png\" class=\"attachment-full size-full wp-image-4442\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2.png 1080w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-169x300.png 169w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-575x1024.png 575w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-768x1367.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/7-Personalized-outplay-2-863x1536.png 863w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e0397c2\" data-id=\"e0397c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-dce-background-color=\"#4C517FD9\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-026a796 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"026a796\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-12c3348\" data-id=\"12c3348\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c40409e elementor-widget elementor-widget-text-editor\" data-id=\"c40409e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section id=\"section-circle-2-e7c90c4\" class=\"premium-tabs-content-section content-current\"><div class=\"premium-tab-content\"><p>\u0627\u0646\u0634\u0631 \u0627\u0644\u0645\u062d\u062a\u0648\u0649 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0645\u0628\u0627\u0634\u0631\u0629 \u0639\u0644\u0649 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u062a\u0648\u0627\u0635\u0644 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a \u0645\u062b\u0644 Whatsapp \u0648 Twitter. \u064a\u0645\u0643\u0646 \u0625\u0646\u0634\u0627\u0621 \u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0639\u0645\u0644\u064a\u0627\u062a \u0625\u0646\u0634\u0627\u0621 \u0627\u0644\u0645\u062d\u062a\u0648\u0649 \u0627\u0644\u0645\u062e\u0635\u0635 \u0628\u0634\u0643\u0644 \u0645\u0634\u062a\u0631\u0643.\r\n<\/p><\/div><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/section>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b62ce6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b62ce6\" data-element_type=\"section\" id=\"publications\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b6a833\" data-id=\"2b6a833\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41a2d28 elementor-widget elementor-widget-heading\" data-id=\"41a2d28\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0645\u0627 \u0627\u0644\u0627\u062e\u0628\u0627\u0631\u061f<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e40d47 elementor-widget elementor-widget-heading\" data-id=\"2e40d47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u0623\u062e\u0628\u0627\u0631 \u062d\u0648\u0644 \u0623\u0646\u0634\u0637\u0629 \u0648\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u0643\u0648\u0646\u0633\u0648\u0631\u062a\u064a\u0648\u0645 \u0648\u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u062d\u0644\u064a\u0641\u0629 \u0627\u0644\u062a\u064a \u062a\u0633\u062a\u062e\u062f\u0645 \u0643\u0648\u0644\u0645\u064a\u0646\u0627<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4080c72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4080c72\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c53d113\" data-id=\"c53d113\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f96b15f dce-col-1 dce-posts-layout-default dce-col-tablet-3 dce-col-mobile-1 dce-align-right elementor-widget elementor-widget-dce-dynamicposts-v2\" data-id=\"f96b15f\" data-element_type=\"widget\" data-settings=\"{&quot;style_items&quot;:&quot;default&quot;,&quot;grid_grid_type&quot;:&quot;flex&quot;,&quot;rtl&quot;:&quot;yes&quot;}\" data-widget_type=\"dce-dynamicposts-v2.grid\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"dce-rtl dce-fix-background-loop dce-posts-container dce-posts dce-dynamic-posts-collection  dce-skin-grid dce-skin-grid-flex\">\n\t\t\t\t\t\t<div class=\"dce-posts-wrapper dce-wrapper-grid\">\n\t\t\t\n\t\t<article class=\"post-6100 post type-post status-publish format-standard hentry category-news dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"6100\" data-dce-post-index=\"0\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-689727b\"><\/div><div class=\"dce-item dce-item_date elementor-repeater-item-00d48cb\">\t\t<div class=\"dce-post-date\">\u0623\u0628\u0631\u064a\u0644 16, 2025<\/div><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-6913176\"><h4 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/in-alley-traditional-ukrainian-dances-become-acts-of-resistance\/\">In \u201cAlley,\u201d traditional Ukrainian dances become acts of resistance<\/a><\/h4><\/div><div class=\"dce-item dce-item_content elementor-repeater-item-cf23125\"><div class=\"dce-post-content\"><\/div><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-19add9a\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/blog.colmena.media\/ar\/in-alley-traditional-ukrainian-dances-become-acts-of-resistance\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-lg\" role=\"button\" >\n\t\t\tRead More &gt;\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-6064 post type-post status-publish format-standard has-post-thumbnail hentry category-news category-newsletter dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"6064\" data-dce-post-index=\"1\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-689727b\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/colmena-communities-of-practice-engagement-across-the-world\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/11\/Colmena-in-Mombasa.jpg\" class=\"\" alt=\"Colmena: Communities of Practice Engagement Across the World\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/11\/Colmena-in-Mombasa.jpg 1280w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/11\/Colmena-in-Mombasa-300x200.jpg 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/11\/Colmena-in-Mombasa-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_date elementor-repeater-item-00d48cb\">\t\t<div class=\"dce-post-date\">\u0646\u0648\u0641\u0645\u0628\u0631 5, 2024<\/div><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-6913176\"><h4 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/colmena-communities-of-practice-engagement-across-the-world\/\">Colmena: Communities of Practice Engagement Across the World<\/a><\/h4><\/div><div class=\"dce-item dce-item_content elementor-repeater-item-cf23125\"><div class=\"dce-post-content\">Recently, Tanda.net led a comprehensive virtual workshop with community radio partners from various parts of Kenya. This session provided updates on the Colmena app\u2019s development and onboarded the participants to the DW Akademie instance.<\/div><\/div><div class=\"dce-item dce-item_readmore elementor-repeater-item-19add9a\">\t\t<div class=\"dce-post-button\">\n\t\t\t<a href=\"https:\/\/blog.colmena.media\/ar\/colmena-communities-of-practice-engagement-across-the-world\/\" class=\"elementor-button-link elementor-button dce-button elementor-size-lg\" role=\"button\" >\n\t\t\tRead More &gt;\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-94be063 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94be063\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3818071\" data-id=\"3818071\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8126841 sombra dce_masking-none elementor-widget elementor-widget-image\" data-id=\"8126841\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.3,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionAbeja.svg\" class=\"attachment-large size-large wp-image-68\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ba8f232\" data-id=\"ba8f232\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43cbe0e elementor-widget elementor-widget-heading\" data-id=\"43cbe0e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/%d8%a3%d8%ae%d8%a8%d8%a7%d8%b1\/\">Read more news<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-90da0ba\" data-id=\"90da0ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a855102 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a855102\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-db6ccf4\" data-id=\"db6ccf4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ccfe2b dce_masking-none elementor-widget elementor-widget-image\" data-id=\"1ccfe2b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/News_world.svg\" class=\"attachment-large size-large wp-image-296\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-113a1db\" data-id=\"113a1db\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-625420f elementor-widget elementor-widget-heading\" data-id=\"625420f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0623\u0635\u0648\u0627\u062a \u0645\u0646 \u0627\u0644\u0639\u0627\u0644\u0645<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b2b2f0 elementor-widget elementor-widget-heading\" data-id=\"7b2b2f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u0625\u0646\u062a\u0627\u062c\u0627\u062a \u0645\u0646 \u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0633\u062a\u062e\u062f\u0645 \u0643\u0648\u0644\u0645\u064a\u0646\u0627<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1974092 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1974092\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-30ea5eb\" data-id=\"30ea5eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-072bb6e dce-posts-layout-template dce-col-1 dce-col-tablet-3 dce-col-mobile-1 elementor-widget elementor-widget-dce-dynamicposts-v2\" data-id=\"072bb6e\" data-element_type=\"widget\" data-settings=\"{&quot;style_items&quot;:&quot;template&quot;,&quot;grid_grid_type&quot;:&quot;flex&quot;,&quot;rtl&quot;:&quot;yes&quot;}\" data-widget_type=\"dce-dynamicposts-v2.grid\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"dce-rtl dce-fix-background-loop dce-posts-container dce-posts dce-dynamic-posts-collection  dce-skin-grid dce-skin-grid-flex\">\n\t\t\t\t\t\t<div class=\"dce-posts-wrapper dce-wrapper-grid\">\n\t\t\t\n\t\t<article class=\"post-2926 voice type-voice status-publish format-standard has-post-thumbnail hentry dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"2926\" data-dce-post-index=\"0\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2948\" data-post-id=\"2926\" data-obj-id=\"2926\" class=\"elementor elementor-2948 dce-elementor-post-2926\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dcb6bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dcb6bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68241e4\" data-id=\"68241e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f736230 elementor-widget elementor-widget-jet-audio\" data-id=\"f736230\" data-element_type=\"widget\" data-widget_type=\"jet-audio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-audio jet-elements\">\n\t\t<div class=\"jet-audio jet-audio--fa5-compat\" data-audio-settings=\"{&quot;controls&quot;:[&quot;playpause&quot;],&quot;startVolume&quot;:0.8,&quot;hideVolumeOnTouchDevices&quot;:true}\">\n\t\t\t<audio class=\"jet-audio-player\" preload=\"none\" controls=\"\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/MX_BOCA-DE-POLEN_Intranet-Comunitaria.mp3\" width=\"100%\"><\/audio>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-870b79d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"870b79d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/MX_BOCA-DE-POLEN_Intranet-Comunitaria-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-2927\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e127f4c\" data-id=\"e127f4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b3a4e elementor-widget elementor-widget-heading\" data-id=\"41b3a4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/voice\/intranet-comunitaria\/\">Intranet comunitaria<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"dce-fix-background-loop elementor-element elementor-element-6bcacdb elementor-widget elementor-widget-dyncontel-acf-relation\" data-id=\"6bcacdb\" data-element_type=\"widget\" data-widget_type=\"dyncontel-acf-relation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dce-acf-relationship-natural\"><a class=\"dce-acf-relational-post-link\" href=\"https:\/\/blog.colmena.media\/ar\/community\/boca-de-polen\/\"><p class=\"elementor-heading-title\">Boca de P\u00f3len<\/p><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93b75 elementor-widget elementor-widget-text-editor\" data-id=\"9b93b75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tUna experiencia de autonom\u00eda tecnolog\u00eda en Oaxaca. Como un maestro y sus alumnos desarrollaron una intranet local en lengua tseltal.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-3619 voice type-voice status-publish format-standard has-post-thumbnail hentry dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"3619\" data-dce-post-index=\"1\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2948\" data-post-id=\"3619\" data-obj-id=\"3619\" class=\"elementor elementor-2948 dce-elementor-post-3619\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dcb6bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dcb6bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68241e4\" data-id=\"68241e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f736230 elementor-widget elementor-widget-jet-audio\" data-id=\"f736230\" data-element_type=\"widget\" data-widget_type=\"jet-audio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-audio jet-elements\">\n\t\t<div class=\"jet-audio jet-audio--fa5-compat\" data-audio-settings=\"{&quot;controls&quot;:[&quot;playpause&quot;],&quot;startVolume&quot;:0.8,&quot;hideVolumeOnTouchDevices&quot;:true}\">\n\t\t\t<audio class=\"jet-audio-player\" preload=\"none\" controls=\"\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/GUA-Sayaxche-Reportaje-CICAN.mp3\" width=\"100%\"><\/audio>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-870b79d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"870b79d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/GUA-Sayaxche-Reportaje-CICAN-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-3620\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e127f4c\" data-id=\"e127f4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b3a4e elementor-widget elementor-widget-heading\" data-id=\"41b3a4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/voice\/la-experiencia-de-cican-emprendedoras-en-guatemala-durante-la-pandemia\/\">La experiencia de CICAN: emprendedoras en Guatemala durante la pandemia<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"dce-fix-background-loop elementor-element elementor-element-6bcacdb elementor-widget elementor-widget-dyncontel-acf-relation\" data-id=\"6bcacdb\" data-element_type=\"widget\" data-widget_type=\"dyncontel-acf-relation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dce-acf-relationship-natural\"><a class=\"dce-acf-relational-post-link\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-sayaxche\/\"><p class=\"elementor-heading-title\">Radio Sayaxch\u00e9<\/p><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93b75 elementor-widget elementor-widget-text-editor\" data-id=\"9b93b75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tMujeres en Guatemala, lideran organizaciones que empoderan a otras mujeres y hacen frente a la pandemia con proyectos productivos.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5162 voice type-voice status-publish format-standard has-post-thumbnail hentry dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"5162\" data-dce-post-index=\"2\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2948\" data-post-id=\"5162\" data-obj-id=\"5162\" class=\"elementor elementor-2948 dce-elementor-post-5162\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dcb6bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dcb6bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68241e4\" data-id=\"68241e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f736230 elementor-widget elementor-widget-jet-audio\" data-id=\"f736230\" data-element_type=\"widget\" data-widget_type=\"jet-audio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-audio jet-elements\">\n\t\t<div class=\"jet-audio jet-audio--fa5-compat\" data-audio-settings=\"{&quot;controls&quot;:[&quot;playpause&quot;],&quot;startVolume&quot;:0.8,&quot;hideVolumeOnTouchDevices&quot;:true}\">\n\t\t\t<audio class=\"jet-audio-player\" preload=\"none\" controls=\"\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Radio-Venegre-INTERVIEW-CNP-NZ.mp3\" width=\"100%\"><\/audio>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-870b79d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"870b79d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Reunion-de-redaction_2-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-5164\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e127f4c\" data-id=\"e127f4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b3a4e elementor-widget elementor-widget-heading\" data-id=\"41b3a4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/voice\/limpact-des-financements-exterieurs-dans-les-pays-a-regime-exceptionnel\/\">L&#8217;impact des financements ext\u00e9rieurs dans les pays \u00e0 r\u00e9gime exceptionnel<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"dce-fix-background-loop elementor-element elementor-element-6bcacdb elementor-widget elementor-widget-dyncontel-acf-relation\" data-id=\"6bcacdb\" data-element_type=\"widget\" data-widget_type=\"dyncontel-acf-relation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dce-acf-relationship-natural\"><a class=\"dce-acf-relational-post-link\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-venegre\/\"><p class=\"elementor-heading-title\">Radio V\u00e9n\u00e9gr\u00e9<\/p><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93b75 elementor-widget elementor-widget-text-editor\" data-id=\"9b93b75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tInterview  journaliste Alfred Kangambega.  Le changement de r\u00e9gime est une pratique permanente en Afrique de l&#8217;ouest.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5108 voice type-voice status-publish format-standard has-post-thumbnail hentry dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"5108\" data-dce-post-index=\"3\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2948\" data-post-id=\"5108\" data-obj-id=\"5108\" class=\"elementor elementor-2948 dce-elementor-post-5108\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dcb6bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dcb6bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68241e4\" data-id=\"68241e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f736230 elementor-widget elementor-widget-jet-audio\" data-id=\"f736230\" data-element_type=\"widget\" data-widget_type=\"jet-audio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-audio jet-elements\">\n\t\t<div class=\"jet-audio jet-audio--fa5-compat\" data-audio-settings=\"{&quot;controls&quot;:[&quot;playpause&quot;],&quot;startVolume&quot;:0.8,&quot;hideVolumeOnTouchDevices&quot;:true}\">\n\t\t\t<audio class=\"jet-audio-player\" preload=\"none\" controls=\"\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-OCAINA-DESAFIOS-DE-LA-RADIO-EN-PANDEMIA.mp3\" width=\"100%\"><\/audio>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-870b79d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"870b79d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ocaina3-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-5111\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e127f4c\" data-id=\"e127f4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b3a4e elementor-widget elementor-widget-heading\" data-id=\"41b3a4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/voice\/desafios-de-la-comunicacion-en-pandemia\/\">Desaf\u00edos de la comunicaci\u00f3n en pandemia<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"dce-fix-background-loop elementor-element elementor-element-6bcacdb elementor-widget elementor-widget-dyncontel-acf-relation\" data-id=\"6bcacdb\" data-element_type=\"widget\" data-widget_type=\"dyncontel-acf-relation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dce-acf-relationship-natural\"><a class=\"dce-acf-relational-post-link\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-ocaina\/\"><p class=\"elementor-heading-title\">Radio Ocaina<\/p><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93b75 elementor-widget elementor-widget-text-editor\" data-id=\"9b93b75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tReconocer cuales han sido los principales falencias dentro de los procesos de comunicaci\u00f3n radial comunitaria que se han generado a ra\u00edz de la pandemia covid 19 y como se es la actualidad de las radios en el departamento. \t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-4023 voice type-voice status-publish format-standard has-post-thumbnail hentry dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"4023\" data-dce-post-index=\"4\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2948\" data-post-id=\"4023\" data-obj-id=\"4023\" class=\"elementor elementor-2948 dce-elementor-post-4023\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dcb6bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dcb6bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68241e4\" data-id=\"68241e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f736230 elementor-widget elementor-widget-jet-audio\" data-id=\"f736230\" data-element_type=\"widget\" data-widget_type=\"jet-audio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-audio jet-elements\">\n\t\t<div class=\"jet-audio jet-audio--fa5-compat\" data-audio-settings=\"{&quot;controls&quot;:[&quot;playpause&quot;],&quot;startVolume&quot;:0.8,&quot;hideVolumeOnTouchDevices&quot;:true}\">\n\t\t\t<audio class=\"jet-audio-player\" preload=\"none\" controls=\"\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/JUKWAA-LA-VIJANA-THE-POWER-OF-THE-BEAT.ogg\" width=\"100%\"><\/audio>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-870b79d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"870b79d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Jukwaa-la-vijana-the-power-of-the-beat-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-4024\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Jukwaa-la-vijana-the-power-of-the-beat-150x150.jpg 150w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Jukwaa-la-vijana-the-power-of-the-beat-300x300.jpg 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Jukwaa-la-vijana-the-power-of-the-beat.jpg 400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e127f4c\" data-id=\"e127f4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b3a4e elementor-widget elementor-widget-heading\" data-id=\"41b3a4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/voice\/jukwaa-la-vijana-the-power-of-the-beat\/\">Jukwaa la vijana: the power of the beat<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"dce-fix-background-loop elementor-element elementor-element-6bcacdb elementor-widget elementor-widget-dyncontel-acf-relation\" data-id=\"6bcacdb\" data-element_type=\"widget\" data-widget_type=\"dyncontel-acf-relation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dce-acf-relationship-natural\"><a class=\"dce-acf-relational-post-link\" href=\"https:\/\/blog.colmena.media\/ar\/community\/pwani-fm\/\"><p class=\"elementor-heading-title\">Pwani FM<\/p><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93b75 elementor-widget elementor-widget-text-editor\" data-id=\"9b93b75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tA Mombasa hiphop based artist Ohmlaw Montana\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2896 voice type-voice status-publish format-standard has-post-thumbnail hentry dce-post dce-post-item dce-item-grid\" data-dce-post-id=\"2896\" data-dce-post-index=\"5\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"2948\" data-post-id=\"2896\" data-obj-id=\"2896\" class=\"elementor elementor-2948 dce-elementor-post-2896\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dcb6bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dcb6bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68241e4\" data-id=\"68241e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f736230 elementor-widget elementor-widget-jet-audio\" data-id=\"f736230\" data-element_type=\"widget\" data-widget_type=\"jet-audio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-audio jet-elements\">\n\t\t<div class=\"jet-audio jet-audio--fa5-compat\" data-audio-settings=\"{&quot;controls&quot;:[&quot;playpause&quot;],&quot;startVolume&quot;:0.8,&quot;hideVolumeOnTouchDevices&quot;:true}\">\n\t\t\t<audio class=\"jet-audio-player\" preload=\"none\" controls=\"\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/Pandemia-tecnologia-y-entramado-social-en-Venezuela.ogg\" width=\"100%\"><\/audio>\n\t\t<\/div>\n\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-870b79d dce_masking-none elementor-widget elementor-widget-image\" data-id=\"870b79d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/tecnologia-contra-el-covid-portada-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2897\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e127f4c\" data-id=\"e127f4c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41b3a4e elementor-widget elementor-widget-heading\" data-id=\"41b3a4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/voice\/pandemia-tecnologia-y-entramado-social-en-venezuela\/\">Pandemia, tecnolog\u00eda y entramado social en Venezuela<\/a><\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"dce-fix-background-loop elementor-element elementor-element-6bcacdb elementor-widget elementor-widget-dyncontel-acf-relation\" data-id=\"6bcacdb\" data-element_type=\"widget\" data-widget_type=\"dyncontel-acf-relation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"dce-acf-relationship-natural\"><a class=\"dce-acf-relational-post-link\" href=\"https:\/\/blog.colmena.media\/ar\/community\/red-de-radios-comunitarias-y-software-libre\/\"><p class=\"elementor-heading-title\">Red de Radios Comunitarias y Software Libre<\/p><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b93b75 elementor-widget elementor-widget-text-editor\" data-id=\"9b93b75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tRepaso a la experiencia venezolana en el uso de la tecnolog\u00eda y la organizaci\u00f3n social en el combate contra la pandemia por covid 19.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9997fe2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9997fe2\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ef2f473\" data-id=\"ef2f473\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bae4f8 sombra dce_masking-none elementor-widget elementor-widget-image\" data-id=\"2bae4f8\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_effect&quot;:&quot;yes&quot;,&quot;motion_fx_mouseTrack_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1,&quot;sizes&quot;:[]},&quot;motion_fx_mouseTrack_direction&quot;:&quot;negative&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/About_IlustracionAbeja.svg\" class=\"attachment-large size-large wp-image-68\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f1a8c1b\" data-id=\"f1a8c1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0636204 elementor-widget elementor-widget-heading\" data-id=\"0636204\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/%d8%a3%d8%b5%d9%88%d8%a7%d8%aa-%d9%85%d9%86-%d8%a7%d9%84%d8%b9%d8%a7%d9%84%d9%85\/\">\u0627\u0644\u0627\u0633\u062a\u0645\u0627\u0639 \u0625\u0644\u0649 \u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0635\u0648\u0627\u062a<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/\/P4_3-1_no-background.svg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5d0d464 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d0d464\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-126691f\" data-id=\"126691f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d7c990 elementor--v-position-top elementor--h-position-center elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"0d7c990\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay_speed&quot;:4000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper-container\" dir=\"rtl\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-f336d53 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Colmena \u0628\u0627\u062e\u062a\u0635\u0627\u0631<\/div><div class=\"elementor-slide-description\"><p>\u0647\u0648 \u062d\u0644 \u0628\u0631\u0645\u062c\u064a \u0644\u0625\u0646\u0634\u0627\u0621 \u0648\u0645\u0634\u0627\u0631\u0643\u0629 \u0627\u0644\u0645\u062d\u062a\u0648\u0649 \u060c \u062a\u0645 \u062a\u0637\u0648\u064a\u0631\u0647 \u0645\u0639 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u0645\u062d\u0644\u064a\u0629 \u0648\u0627\u0644\u0645\u062c\u062a\u0645\u0639\u064a\u0629 \u0645\u0646 \u0627\u0644\u0639\u0627\u0644\u0645 \u0627\u0644\u062c\u0646\u0648\u0628\u064a. \u0643\u0648\u0644\u0645\u064a\u0646\u0627 \u0645\u062c\u0627\u0646\u064a \u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u060c \u0645\u0645\u0644\u0648\u0643 \u0628\u0634\u0643\u0644 \u0634\u0627\u0626\u0639 \u0648\u0645\u0641\u062a\u0648\u062d \u0627\u0644\u0645\u0635\u062f\u0631 \u0628\u0646\u0633\u0628\u0629 \u066a100<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">\u0627\u0646\u0642\u0631 \u0647\u0646\u0627<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-4c20f13 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u062a\u062d\u0627\u0644\u0641 \u0639\u0627\u0644\u0645\u064a \u0644\u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u0645\u062c\u062a\u0645\u0639\u064a\u0629<\/div><div class=\"elementor-slide-description\"><p>\u062a\u0644\u062a\u0632\u0645 Colmena \u0628\u0625\u0646\u0634\u0627\u0621 \u0628\u0646\u064a\u0629 \u062a\u062d\u062a\u064a\u0629 \u0631\u0642\u0645\u064a\u0629 \u0645\u0634\u062a\u0631\u0643\u0629 \u0648\u0645\u0645\u0644\u0648\u0643\u0629 \u0628\u0634\u0643\u0644 \u062c\u0645\u0627\u0639\u064a. \u064a\u062a\u0643\u0648\u0646 \u0645\u062c\u062a\u0645\u0639\u0646\u0627 \u0645\u0646 \u0645\u062a\u0639\u0627\u0648\u0646\u064a\u0646 \u0646\u0634\u0637\u064a\u0646 \u060c \u0648\u0644\u064a\u0633 \u0645\u0633\u062a\u062e\u062f\u0645\u064a\u0646 \u0641\u0642\u0637.<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">\u0627\u0646\u0642\u0631 \u0647\u0646\u0627<\/div><\/div><\/div><\/div><div class=\"elementor-repeater-item-68a38c4 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">\u0642\u0635\u062a\u0646\u0627<\/div><div class=\"elementor-slide-description\"><p>\u0648\u0644\u062f\u062a \u0627\u0644\u0645\u0628\u0627\u062f\u0631\u0629 \u0643\u0627\u0633\u062a\u062c\u0627\u0628\u0629 \u0644\u0648\u0628\u0627\u0621 \u0628\u0642\u064a\u0627\u062f\u0629<br \/>\n\u0623\u0643\u0627\u062f\u064a\u0645\u064a\u0629 DW<\/p>\n<p>\u0648\u0627\u0644\u0645\u0646\u0638\u0645\u0629 \u063a\u064a\u0631 \u0627\u0644\u062d\u0643\u0648\u0645\u064a\u0629 \u0627\u0644\u0645\u0643\u0633\u064a\u0643\u064a\u0629<br \/>\nREDES<br \/>\n\u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u0645\u062f\u0639\u0648\u0645 \u0645\u0646 \u0642\u0628\u0644 \u0627\u0644\u0648\u0632\u0627\u0631\u0629 \u0627\u0644\u0627\u062a\u062d\u0627\u062f\u064a\u0629 \u0627\u0644\u0623\u0644\u0645\u0627\u0646\u064a\u0629 \u0644\u0644\u062a\u0646\u0645\u064a\u0629 \u0627\u0644\u0627\u0642\u062a\u0635\u0627\u062f\u064a\u0629 \u0648\u0627\u0644\u062a\u0639\u0627\u0648\u0646 (BMZ) \u0645\u0646 \u0645\u0628\u0627\u062f\u0631\u0629 \u0627\u0644\u0623\u0632\u0645\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 (GKI).<\/p>\n<p>&gt;&gt;&gt; \u0627\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u0643\u0648\u0644\u0645\u064a\u0646\u0627<\/p>\n<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">\u0627\u0646\u0642\u0631 \u0647\u0646\u0627<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-fb3f182 e-flex e-con-boxed e-con e-parent\" data-id=\"fb3f182\" data-element_type=\"container\" id=\"consortium\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3314d2a e-con-full e-flex e-con e-child\" data-id=\"3314d2a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc1c67b elementor-widget elementor-widget-heading\" data-id=\"cc1c67b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u062a\u062d\u0627\u0644\u0641<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa46c3b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"aa46c3b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0623\u0631\u0628\u0639\u0629 \u0634\u0631\u0643\u0627\u0621 \u0623\u0642\u0648\u064a\u0627\u0621 \u0641\u064a \u0645\u0647\u0645\u0629 \u0648\u0627\u062d\u062f\u0629<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a8db0e e-con-full e-flex e-con e-child\" data-id=\"4a8db0e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b4c0b5e e-con-full e-flex e-con e-child\" data-id=\"b4c0b5e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db8fdf9 elementor-widget elementor-widget-text-editor\" data-id=\"db8fdf9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u0627\u062a\u062d\u0627\u062f \u0643\u0648\u0644\u0645\u064a\u0646\u0627 \u0647\u0648 \u062a\u062d\u0627\u0644\u0641 \u0645\u0646 \u0627\u0644\u0645\u0624\u0633\u0633\u0627\u062a \u0627\u0644\u0645\u062e\u0635\u0635\u0629 \u0644\u062f\u0639\u0645 \u0648\u062a\u0637\u0648\u064a\u0631 \u0648\u0633\u0627\u0626\u0644 \u0627\u0644\u0625\u0639\u0644\u0627\u0645 \u0627\u0644\u0645\u0633\u062a\u0642\u0644\u0629\u060c \u0648\u0627\u0644\u0627\u062a\u0635\u0627\u0644\u0627\u062a \u0648\u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0627\u0644\u062a\u064a \u062a\u0631\u0643\u0632 \u0639\u0644\u0649 \u0627\u0644\u0645\u062c\u062a\u0645\u0639\u060c \u0648\u062a\u0637\u0648\u064a\u0631 \u0627\u0644\u0628\u0631\u0645\u062c\u064a\u0627\u062a \u0648\u062a\u0648\u0641\u064a\u0631 \u0627\u0644\u0628\u0646\u064a\u0629 \u0627\u0644\u062a\u062d\u062a\u064a\u0629. \u0645\u0639\u064b\u0627 \u0646\u062d\u0627\u0641\u0638 \u0639\u0644\u0649 \u062a\u0637\u0648\u064a\u0631 \u0648\u0635\u064a\u0627\u0646\u0629 \u0628\u0631\u0646\u0627\u0645\u062c Colmena \u0645\u0641\u062a\u0648\u062d \u0627\u0644\u0645\u0635\u062f\u0631 \u0644\u0644\u0645\u062c\u062a\u0645\u0639 \u0627\u0644\u0639\u0627\u0644\u0645\u064a<\/p>\n<p>\u0648\u0639\u0644\u0649 \u0646\u062d\u0648 \u062a\u0643\u0645\u064a\u0644\u064a\u060c \u064a\u0633\u0627\u0647\u0645 \u0647\u0630\u0627 \u0627\u0644\u062a\u062d\u0627\u0644\u0641 \u0645\u0646 \u0627\u0644\u0634\u0631\u0643\u0627\u0621 \u0628\u0627\u0644\u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u0648\u0627\u0644\u062a\u0642\u0646\u064a\u0629 \u0648\u0627\u0644\u0645\u0627\u0644\u064a\u0629 \u0644\u0636\u0645\u0627\u0646 \u062a\u0637\u0648\u064a\u0631 \u0648\u0635\u064a\u0627\u0646\u0629 \u0648\u062e\u062f\u0645\u0629 \u0643\u0648\u0644\u0645\u064a\u0646\u0627. 4 \u0645\u0646\u0638\u0645\u0627\u062a \u0641\u064a 3 \u0642\u0627\u0631\u0627\u062a \u0647\u064a \u0623\u0633\u0627\u0633 \u0627\u0644\u0643\u0648\u0646\u0633\u0648\u0631\u062a\u064a\u0648\u0645 \u0627\u0644\u0630\u064a \u064a\u062c\u0639\u0644 \u0643\u0648\u0644\u0645\u064a\u0646\u0627 \u0645\u0645\u0643\u0646\u0629.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33636cb elementor-widget elementor-widget-button\" data-id=\"33636cb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/blog.colmena.media\/colmena-consortium\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0627\u0639\u0631\u0641 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u0627\u0644\u0643\u0648\u0646\u0633\u0648\u0631\u062a\u064a\u0648\u0645<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8065300 e-con-full e-flex e-con e-child\" data-id=\"8065300\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7498d6 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"e7498d6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/08\/Consortium-Colmena-diagram-EN.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Consortium Colmena diagram EN\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTg4MiwidXJsIjoiaHR0cHM6XC9cL2Jsb2cuY29sbWVuYS5tZWRpYVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDhcL0NvbnNvcnRpdW0tQ29sbWVuYS1kaWFncmFtLUVOLnBuZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"1000\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/08\/Consortium-Colmena-diagram-EN.png\" class=\"attachment-large size-large wp-image-5882\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/08\/Consortium-Colmena-diagram-EN.png 705w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/08\/Consortium-Colmena-diagram-EN-212x300.png 212w\" sizes=\"(max-width: 705px) 100vw, 705px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/\/Community_TextureBackground-2.svg\" class=\"elementor-element elementor-element-ea8193b e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"ea8193b\" data-element_type=\"container\" id=\"community\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-727d260 e-con-full e-flex e-con e-child\" data-id=\"727d260\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-868767e e-con-full e-flex e-con e-child\" data-id=\"868767e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c63823 elementor-widget elementor-widget-text-editor\" data-id=\"1c63823\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8bc24e elementor-widget elementor-widget-premium-addon-image-hotspots\" data-id=\"c8bc24e\" data-element_type=\"widget\" data-widget_type=\"premium-addon-image-hotspots.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t<div id=\"premium-image-hotspots-c8bc24e\" class=\"premium-image-hotspots-container\" data-settings=\"{&quot;anim&quot;:&quot;fade&quot;,&quot;animDur&quot;:350,&quot;delay&quot;:10,&quot;arrow&quot;:false,&quot;distance&quot;:6,&quot;minWidth&quot;:0,&quot;maxWidth&quot;:&quot;null&quot;,&quot;side&quot;:[&quot;top&quot;,&quot;bottom&quot;],&quot;hideMobiles&quot;:false,&quot;active&quot;:true,&quot;trigger&quot;:&quot;hover&quot;,&quot;id&quot;:&quot;c8bc24e&quot;,&quot;iconHover&quot;:&quot;grow&quot;}\">\n\t\t<div class=\"premium-image-hotspots-img-wrap\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/mapa-morado.svg\" title=\"mapa-morado\" alt=\"mapa-morado\" loading=\"lazy\" \/>\t\t\t\t\t\t\t<div class=\"premium-image-hotspots-main-icons tooltip-wrapper   elementor-repeater-item-f3257f8 premium-image-hotspots-main-icons-f3257f8\" data-tooltip-content=\"#tooltip_content\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-hotspots-tooltips-link\" href=\"https:\/\/akademie.dw.com\/en\/home\/s-9519\" title=\"DW Akademie\" target=\"_blank\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-hotsot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementor-animation-grow premium-image-hotspots-image-icon\" alt=\"dw-akademie\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/dw-akademie.png\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-image-hotspots-tooltips-wrapper\">\n\t\t\t\t\t\t<div id=\"tooltip_content\" class=\"premium-image-hotspots-tooltips-text\">\n\t\t\t\t\t\t\t<p>DW Akademie<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"premium-image-hotspots-main-icons tooltip-wrapper   elementor-repeater-item-10978a8 premium-image-hotspots-main-icons-10978a8\" data-tooltip-content=\"#tooltip_content\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-hotspots-tooltips-link\" href=\"https:\/\/camba.coop\/\" title=\"\" target=\"_blank\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-hotsot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementor-animation-grow premium-image-hotspots-image-icon\" alt=\"camba\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/camba.png\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-image-hotspots-tooltips-wrapper\">\n\t\t\t\t\t\t<div id=\"tooltip_content\" class=\"premium-image-hotspots-tooltips-text\">\n\t\t\t\t\t\t\t<p>Camb\u00e1<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"premium-image-hotspots-main-icons tooltip-wrapper   elementor-repeater-item-cc55231 premium-image-hotspots-main-icons-cc55231\" data-tooltip-content=\"#tooltip_content\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-hotspots-tooltips-link\" href=\"https:\/\/www.redesac.org.mx\/\" title=\"\" target=\"_blank\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-hotsot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementor-animation-grow premium-image-hotspots-image-icon\" alt=\"redes-ac-2023\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/12\/redes-ac-2023.png\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-image-hotspots-tooltips-wrapper\">\n\t\t\t\t\t\t<div id=\"tooltip_content\" class=\"premium-image-hotspots-tooltips-text\">\n\t\t\t\t\t\t\t<p>Redes por la Diversidad, Equidad y Sustentabilidad A.C.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"premium-image-hotspots-main-icons tooltip-wrapper   elementor-repeater-item-857fc4a premium-image-hotspots-main-icons-857fc4a\" data-tooltip-content=\"#tooltip_content\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"premium-image-hotspots-tooltips-link\" href=\"https:\/\/www.tnetcn.net\/\" title=\"\" target=\"_blank\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-hotsot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementor-animation-grow premium-image-hotspots-image-icon\" alt=\"tanda\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/tanda.png\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"premium-image-hotspots-tooltips-wrapper\">\n\t\t\t\t\t\t<div id=\"tooltip_content\" class=\"premium-image-hotspots-tooltips-text\">\n\t\t\t\t\t\t\t<p>Tanda Community Network<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/\/Community_TextureBackground-2.svg\" class=\"elementor-element elementor-element-1da4af5 e-con-full elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"1da4af5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-82b9924 e-con-full e-flex e-con e-child\" data-id=\"82b9924\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b8aa9e2 e-flex e-con-boxed e-con e-child\" data-id=\"b8aa9e2\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-123f933 elementor-widget elementor-widget-heading\" data-id=\"123f933\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0645\u062c\u062a\u0645\u0639<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b09911 e-con-full e-flex e-con e-child\" data-id=\"6b09911\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f02f611 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"f02f611\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/mapa-morado-movil.png\" class=\"attachment-large size-large wp-image-5895\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/mapa-morado-movil.png 1372w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/mapa-morado-movil-300x219.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2023\/09\/mapa-morado-movil-768x560.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-dce-background-image-url=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/\/Community_TextureBackground-2.svg\" class=\"elementor-element elementor-element-541a26a e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"541a26a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;content_width&quot;:&quot;full&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-60b0550 e-con-full e-flex e-con e-child\" data-id=\"60b0550\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3d1a0e9 e-flex e-con-boxed e-con e-child\" data-id=\"3d1a0e9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06fbd5d elementor-widget elementor-widget-heading\" data-id=\"06fbd5d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u0639\u0627\u0645\u0644\u0629 \u0645\u0639 \u0643\u0648\u0644\u0645\u064a\u0646\u0627<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d868892 elementor-widget elementor-widget-heading\" data-id=\"d868892\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0634\u0627\u0631\u0643 \u0641\u064a \u0625\u0646\u0634\u0627\u0621 \u0643\u0648\u0644\u0645\u064a\u0646\u0627 \u0648\u062a\u062c\u0639\u0644 \u0645\u0646\u0647\u0627 \u062c\u0632\u0621\u064b\u0627 \u0645\u0646 \u0627\u0644\u0645\u062c\u062a\u0645\u0639.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e803ee e-con-full e-flex e-con e-child\" data-id=\"0e803ee\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fd1374 dce-col-8 dce-posts-layout-default dce-col-tablet-3 dce-col-mobile-1 dce-align-right elementor-widget elementor-widget-dce-dynamicposts-v2\" data-id=\"1fd1374\" data-element_type=\"widget\" data-settings=\"{&quot;style_items&quot;:&quot;default&quot;,&quot;grid_filters_all_filter&quot;:&quot;yes&quot;,&quot;grid_filters_all_default&quot;:&quot;yes&quot;,&quot;grid_filters_grid_type&quot;:&quot;flex&quot;,&quot;rtl&quot;:&quot;yes&quot;}\" data-widget_type=\"dce-dynamicposts-v2.grid-filters\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"dce-rtl dce-fix-background-loop dce-posts-container dce-posts dce-dynamic-posts-collection  dce-grid-filters-container dce-skin-grid-filters dce-skin-grid dce-skin-grid-flex\">\n\t\t\t<div class=\"dce-filters align-right\" dir=\"rtl\"><span class=\"filters-item filter-active\"><a href=\"#\" data-filter=\"*\">All<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-america-latina\">Am\u00e9rica Latina<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-bolivia\">Bolivia<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-brasil\">Brasil<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-burkina-faso\">Burkina Faso<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-colombia\">Colombia<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-ecuador\">Ecuador<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-ghana\">Ghana<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-guatemala\">Guatemala<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-ivory-coast-cote-divoire\">Ivory Coast - C\u00f4te d'Ivoire<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-kenya\">Kenya<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-mexico\">M\u00e9xico<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-morocco\">Morocco \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0645\u063a\u0631\u0628\u064a\u0629<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-peru\">Per\u00fa<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-tanzania\">Tanzania<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-tunisie\">Tunisie \u0627\u0644\u062c\u0645\u0647\u0648\u0631\u064a\u0629 \u0627\u0644\u062a\u0648\u0646\u0633\u064a\u0629<\/a><\/span><span class=\"filters-separator\"> \u00b7 <\/span><span class=\"filters-item\"><a href=\"#\" data-e-disable-page-transition=\"false\" data-filter=\".country-ukraine\">Ukraine<\/a><\/span><\/select><\/div>\t\t\t<div class=\"dce-posts-wrapper dce-grid-filters-wrapper dce-wrapper-grid-filters dce-wrapper-grid\">\n\t\t\t\n\t\t<article class=\"post-5836 community type-community status-publish has-post-thumbnail hentry language-francais country-ivory-coast-cote-divoire dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5836\" data-dce-post-index=\"0\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/observateur-citoyen\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Observateur-Citoyen.png\" class=\"\" alt=\"Observateur Citoyen\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Observateur-Citoyen.png 225w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Observateur-Citoyen-150x150.png 150w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/observateur-citoyen\/\">Observateur Citoyen<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-97\" data-dce-order=\"\">Ivory Coast - C\u00f4te d'Ivoire<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5835 community type-community status-publish has-post-thumbnail hentry language-ukrainian- country-ukraine dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5835\" data-dce-post-index=\"1\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/volyn-online\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"325\" height=\"50\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Volyn-Online.png\" class=\"\" alt=\"Volyn Online\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Volyn-Online.png 325w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Volyn-Online-300x46.png 300w\" sizes=\"(max-width: 325px) 100vw, 325px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/volyn-online\/\">Volyn Online<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-95\" data-dce-order=\"\">Ukraine<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5834 community type-community status-publish has-post-thumbnail hentry language-ukrainian- country-ukraine dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5834\" data-dce-post-index=\"2\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/urban-space-radio\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/urban.jpg\" class=\"\" alt=\"Urban Space Radio\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/urban.jpg 225w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/urban-150x150.jpg 150w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/urban-space-radio\/\">Urban Space Radio<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-95\" data-dce-order=\"\">Ukraine<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5831 community type-community status-publish has-post-thumbnail hentry language-ukrainian- country-ukraine dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5831\" data-dce-post-index=\"3\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/ua-broadcasting\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"365\" height=\"138\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/UA-Broadcasating.jpg\" class=\"\" alt=\"UA Broadcasting\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/UA-Broadcasating.jpg 365w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/UA-Broadcasating-300x113.jpg 300w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/ua-broadcasting\/\">UA Broadcasting<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-95\" data-dce-order=\"\">Ukraine<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5830 community type-community status-publish has-post-thumbnail hentry language-ukrainian- country-ukraine dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5830\" data-dce-post-index=\"4\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-culture\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"249\" height=\"203\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Radio-Culture.png\" class=\"\" alt=\"Radio Culture\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-culture\/\">Radio Culture<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-95\" data-dce-order=\"\">Ukraine<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5829 community type-community status-publish has-post-thumbnail hentry language-english country-tanzania dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5829\" data-dce-post-index=\"5\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/media-convergency\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Media-Convergency.jpg\" class=\"\" alt=\"Media Convergency\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/media-convergency\/\">Media Convergency<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-94\" data-dce-order=\"\">Tanzania<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5823 community type-community status-publish has-post-thumbnail hentry language-english country-tanzania dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5823\" data-dce-post-index=\"6\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/omuka-hub\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Omuka-Hub.jpg\" class=\"\" alt=\"Omuka Hub\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Omuka-Hub.jpg 400w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Omuka-Hub-300x300.jpg 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Omuka-Hub-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/omuka-hub\/\">Omuka Hub<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-94\" data-dce-order=\"\">Tanzania<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-5821 community type-community status-publish has-post-thumbnail hentry language-english country-tanzania dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"5821\" data-dce-post-index=\"7\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/tanzania-media-foundation\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"216\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Tanzania-Media-Foundation.jpg\" class=\"\" alt=\"Tanzania Media Foundation\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Tanzania-Media-Foundation.jpg 216w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2024\/02\/Tanzania-Media-Foundation-150x150.jpg 150w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/tanzania-media-foundation\/\">Tanzania Media Foundation<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-94\" data-dce-order=\"\">Tanzania<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-649 community type-community status-publish has-post-thumbnail hentry language-espanol country-bolivia dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"649\" data-dce-post-index=\"8\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/muy-waso\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/MUY-WASO.png\" class=\"\" alt=\"Muy Waso\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/MUY-WASO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/MUY-WASO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/MUY-WASO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/muy-waso\/\">Muy Waso<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-29\" data-dce-order=\"\">Bolivia<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2777 community type-community status-publish has-post-thumbnail hentry language-arabic- country-morocco dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2777\" data-dce-post-index=\"9\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/100-mamans\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/100-MAMANS.png\" class=\"\" alt=\"100% Mamans \/ \u0627\u0644\u0623\u0645\u0647\u0627\u062a \u0639\u0644\u0649 \u0627\u0644\u0623\u062b\u064a\u0631 \u0647\u0648 \u0645\u0634\u0631\u0648\u0639 \u0644\u062c\u0645\u0639\u064a\u0629 \u0645\u0627\u0626\u0629 \u0628\u0627\u0644\u0645\u0627\u0626\u0629 \u0623\u0645\u0647\u0627\u062a\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/100-MAMANS.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/100-MAMANS-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/100-MAMANS-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/100-mamans\/\">100% Mamans \/ \u0627\u0644\u0623\u0645\u0647\u0627\u062a \u0639\u0644\u0649 \u0627\u0644\u0623\u062b\u064a\u0631 \u0647\u0648 \u0645\u0634\u0631\u0648\u0639 \u0644\u062c\u0645\u0639\u064a\u0629 \u0645\u0627\u0626\u0629 \u0628\u0627\u0644\u0645\u0627\u0626\u0629 \u0623\u0645\u0647\u0627\u062a<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-67\" data-dce-order=\"\">Morocco \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0645\u063a\u0631\u0628\u064a\u0629<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2763 community type-community status-publish has-post-thumbnail hentry language-english country-ghana dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2763\" data-dce-post-index=\"10\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-ada\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-ADA-LOGO.png\" class=\"\" alt=\"Radio Ada\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-ADA-LOGO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-ADA-LOGO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-ADA-LOGO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-ada\/\">Radio Ada<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-59\" data-dce-order=\"\">Ghana<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2704 community type-community status-publish has-post-thumbnail hentry language-francais country-burkina-faso dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2704\" data-dce-post-index=\"11\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-venegre\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-RADIOVENEGRE-LOGO.png\" class=\"\" alt=\"Radio V\u00e9n\u00e9gr\u00e9\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-RADIOVENEGRE-LOGO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-RADIOVENEGRE-LOGO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-RADIOVENEGRE-LOGO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-venegre\/\">Radio V\u00e9n\u00e9gr\u00e9<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-57\" data-dce-order=\"\">Burkina Faso<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2678 community type-community status-publish has-post-thumbnail hentry language-portuguese country-brasil dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2678\" data-dce-post-index=\"12\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-comunitaria-aconchego\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ACOCHEGO.png\" class=\"\" alt=\"R\u00e1dio Comunit\u00e1ria Aconchego\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ACOCHEGO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ACOCHEGO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ACOCHEGO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-comunitaria-aconchego\/\">R\u00e1dio Comunit\u00e1ria Aconchego<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-56\" data-dce-order=\"\">Brasil<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2776 community type-community status-publish has-post-thumbnail hentry language-arabic- country-tunisie dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2776\" data-dce-post-index=\"13\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-nefzawa-%d8%a7%d8%b0%d8%a7%d8%b9%d8%a9-%d9%86%d9%81%d8%b2%d8%a7%d9%88%d8%a9\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/NEFZAWA.png\" class=\"\" alt=\"Radio Nefzawa \/ \u0627\u0644\u0627\u0630\u0627\u0639\u0629 \u0627\u0644\u0627\u0643\u062b\u0631 \u0642\u0631\u0628\u0627 \u0641\u064a \u062a\u0648\u0646\u0633\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/NEFZAWA.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/NEFZAWA-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/NEFZAWA-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-nefzawa-%d8%a7%d8%b0%d8%a7%d8%b9%d8%a9-%d9%86%d9%81%d8%b2%d8%a7%d9%88%d8%a9\/\">Radio Nefzawa \/ \u0627\u0644\u0627\u0630\u0627\u0639\u0629 \u0627\u0644\u0627\u0643\u062b\u0631 \u0642\u0631\u0628\u0627 \u0641\u064a \u062a\u0648\u0646\u0633<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-65\" data-dce-order=\"\">Tunisie \u0627\u0644\u062c\u0645\u0647\u0648\u0631\u064a\u0629 \u0627\u0644\u062a\u0648\u0646\u0633\u064a\u0629<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2599 community type-community status-publish has-post-thumbnail hentry language-espanol country-guatemala dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2599\" data-dce-post-index=\"14\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-sayaxche\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-SAYAXCHE.png\" class=\"\" alt=\"Radio Sayaxch\u00e9\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-SAYAXCHE.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-SAYAXCHE-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-SAYAXCHE-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-sayaxche\/\">Radio Sayaxch\u00e9<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-60\" data-dce-order=\"\">Guatemala<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-4077 community type-community status-publish has-post-thumbnail hentry language-kiswahili country-kenya dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"4077\" data-dce-post-index=\"15\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-rahma\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RAHMA-1.png\" class=\"\" alt=\"Radio Rahma\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RAHMA-1.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RAHMA-1-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RAHMA-1-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-rahma\/\">Radio Rahma<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-61\" data-dce-order=\"\">Kenya<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2665 community type-community status-publish has-post-thumbnail hentry language-portuguese country-brasil dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2665\" data-dce-post-index=\"16\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/copio-parente\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COPIO-PARENTE.png\" class=\"\" alt=\"Copi\u00f4, Parente!\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COPIO-PARENTE.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COPIO-PARENTE-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COPIO-PARENTE-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/copio-parente\/\">Copi\u00f4, Parente!<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-56\" data-dce-order=\"\">Brasil<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-4076 community type-community status-publish has-post-thumbnail hentry language-kiswahili country-kenya dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"4076\" data-dce-post-index=\"17\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/pwani-fm\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-PWANI.png\" class=\"\" alt=\"Pwani FM\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-PWANI.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-PWANI-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-PWANI-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/pwani-fm\/\">Pwani FM<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-61\" data-dce-order=\"\">Kenya<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-1689 community type-community status-publish has-post-thumbnail hentry language-espanol country-ecuador dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"1689\" data-dce-post-index=\"18\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/remando\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/REMANDO.png\" class=\"\" alt=\"Remando\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/REMANDO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/REMANDO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/REMANDO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/remando\/\">Remando<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-30\" data-dce-order=\"\">Ecuador<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-1997 community type-community status-publish has-post-thumbnail hentry language-espanol country-mexico dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"1997\" data-dce-post-index=\"19\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/boca-de-polen\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BOCA-DE-POLEN.png\" class=\"\" alt=\"Boca de P\u00f3len\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BOCA-DE-POLEN.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BOCA-DE-POLEN-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BOCA-DE-POLEN-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/boca-de-polen\/\">Boca de P\u00f3len<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-48\" data-dce-order=\"\">M\u00e9xico<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2626 community type-community status-publish has-post-thumbnail hentry language-espanol country-peru dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2626\" data-dce-post-index=\"20\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/union-de-mujeres-aymaras-del-abya-yala-uma\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/UMA.png\" class=\"\" alt=\"Uni\u00f3n de Mujeres Aymaras del Abya Yala (UMA)\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/UMA.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/UMA-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/UMA-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/union-de-mujeres-aymaras-del-abya-yala-uma\/\">Uni\u00f3n de Mujeres Aymaras del Abya Yala (UMA)<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-62\" data-dce-order=\"\">Per\u00fa<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-1984 community type-community status-publish has-post-thumbnail hentry language-espanol country-mexico dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"1984\" data-dce-post-index=\"21\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/redes-ac-mexico\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"439\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/REDES-ICON.png\" class=\"\" alt=\"Redes AC, M\u00e9xico\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/REDES-ICON.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/REDES-ICON-300x263.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/redes-ac-mexico\/\">Redes AC, M\u00e9xico<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-48\" data-dce-order=\"\">M\u00e9xico<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2778 community type-community status-publish has-post-thumbnail hentry language-arabic- country-morocco dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2778\" data-dce-post-index=\"22\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/e-joussour\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/EJOUSSOUR.png\" class=\"\" alt=\"E-joussour\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/EJOUSSOUR.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/EJOUSSOUR-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/EJOUSSOUR-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/e-joussour\/\">E-joussour<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-67\" data-dce-order=\"\">Morocco \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0645\u063a\u0631\u0628\u064a\u0629<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2750 community type-community status-publish has-post-thumbnail hentry language-english country-ghana dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2750\" data-dce-post-index=\"23\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/breezy-community-radio-fm\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-BREEZY.png\" class=\"\" alt=\"Breezy Community Radio FM\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-BREEZY.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-BREEZY-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RADIO-BREEZY-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/breezy-community-radio-fm\/\">Breezy Community Radio FM<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-59\" data-dce-order=\"\">Ghana<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2724 community type-community status-publish has-post-thumbnail hentry language-english country-kenya dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2724\" data-dce-post-index=\"24\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-gulf\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/GULF-RADIO.png\" class=\"\" alt=\"Radio Gulf\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/GULF-RADIO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/GULF-RADIO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/GULF-RADIO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-gulf\/\">Radio Gulf<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-61\" data-dce-order=\"\">Kenya<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2652 community type-community status-publish has-post-thumbnail hentry language-portuguese country-brasil dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2652\" data-dce-post-index=\"25\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/podcast-podpreta\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODPRETA.png\" class=\"\" alt=\"Podcast Podpreta\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODPRETA.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODPRETA-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODPRETA-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/podcast-podpreta\/\">Podcast Podpreta<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-56\" data-dce-order=\"\">Brasil<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2639 community type-community status-publish has-post-thumbnail hentry language-espanol country-america-latina dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2639\" data-dce-post-index=\"26\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/red-de-radios-comunitarias-y-software-libre\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RRCySL.png\" class=\"\" alt=\"Red de Radios Comunitarias y Software Libre\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RRCySL.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RRCySL-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/RRCySL-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/red-de-radios-comunitarias-y-software-libre\/\">Red de Radios Comunitarias y Software Libre<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-63\" data-dce-order=\"\">Am\u00e9rica Latina<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2613 community type-community status-publish has-post-thumbnail hentry language-espanol country-colombia dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2613\" data-dce-post-index=\"27\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-ocaina\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COLOMBIA-OCAINA-LOGO.png\" class=\"\" alt=\"Radio Ocaina\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COLOMBIA-OCAINA-LOGO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COLOMBIA-OCAINA-LOGO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/COLOMBIA-OCAINA-LOGO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-ocaina\/\">Radio Ocaina<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-58\" data-dce-order=\"\">Colombia<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2737 community type-community status-publish has-post-thumbnail hentry language-english country-kenya dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2737\" data-dce-post-index=\"28\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-amani\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/AMANI-LOGO.png\" class=\"\" alt=\"Radio Amani\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/AMANI-LOGO.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/AMANI-LOGO-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/AMANI-LOGO-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/radio-amani\/\">Radio Amani<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-61\" data-dce-order=\"\">Kenya<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2711 community type-community status-publish has-post-thumbnail hentry language-francais country-burkina-faso dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2711\" data-dce-post-index=\"29\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/la-voix-du-paisant\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-LA-VOIX-DU-PAYSANGOLO-LOGO-1.png\" class=\"\" alt=\"La Voix du Paysan\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-LA-VOIX-DU-PAYSANGOLO-LOGO-1.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-LA-VOIX-DU-PAYSANGOLO-LOGO-1-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/BURKINA-LA-VOIX-DU-PAYSANGOLO-LOGO-1-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/la-voix-du-paisant\/\">La Voix du Paysan<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-57\" data-dce-order=\"\">Burkina Faso<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\n\t\t<article class=\"post-2691 community type-community status-publish has-post-thumbnail hentry language-portuguese country-brasil dce-post dce-post-item dce-grid-filters-item dce-item-grid-filters dce-item-grid\" data-dce-post-id=\"2691\" data-dce-post-index=\"30\">\n\t\t\t<div class=\"dce-post-block\">\n\t\t<div class=\"dce-item dce-item_image elementor-repeater-item-124632c\"><a class=\"dce-post-image\" href=\"https:\/\/blog.colmena.media\/ar\/community\/podcast-pod-da-lhe\/\"><figure  class=\"dce-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODDALHE.png\" class=\"\" alt=\"Podcast Pod-Da-lhe\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODDALHE.png 500w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODDALHE-300x300.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/PODDALHE-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><\/a><\/div><div class=\"dce-item dce-item_title elementor-repeater-item-9b11b86\"><h5 class=\"dce-post-title\"><a href=\"https:\/\/blog.colmena.media\/ar\/community\/podcast-pod-da-lhe\/\">Podcast Pod-Da-lhe<\/a><\/h5><\/div><div class=\"dce-item dce-item_termstaxonomy elementor-repeater-item-4acb991\"><div class=\"dce-post-terms\"><ul class=\"dce-terms-list dce-taxonomy-country\"><li class=\"dce-term-item\"><span class=\"dce-term dce-term-56\" data-dce-order=\"\">Brasil<\/span><\/li><\/ul><\/div><\/div>\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<!-- dce invisible element 20f49b7 -->\t\t<section data-dce-background-color=\"#2D2E2F\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3150698 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3150698\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dab6d32\" data-id=\"dab6d32\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1174e04 elementor-widget elementor-widget-heading\" data-id=\"1174e04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Alliances<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485de5d elementor-widget elementor-widget-text-editor\" data-id=\"485de5d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u062a\u0624\u0645\u0646 \u0643\u0648\u0644\u0645\u064a\u0646\u0627 \u0628\u0639\u0627\u0644\u0645 \u0645\u062a\u0635\u0644 \u062d\u064a\u062b \u062a\u0633\u0645\u062d \u0644\u0646\u0627 \u0627\u0644\u062a\u062d\u0627\u0644\u0641\u0627\u062a \u0628\u0627\u0644\u0646\u0645\u0648 \u0628\u0634\u0643\u0644 \u062c\u0645\u0627\u0639\u064a. \u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u062a\u062d\u0627\u0644\u0641\u0627\u062a\u0646\u0627 \u0627\u0644\u062a\u064a \u062a\u0645\u062a \u062d\u062a\u0649 \u0627\u0644\u0622\u0646.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dba2991\" data-id=\"dba2991\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a146a59 elementor-position-left dce_masking-none elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"a146a59\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/about.gitlab.com\/solutions\/open-source\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"150\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/11\/GitLab_logo_blanco.svg\" class=\"attachment-full size-full wp-image-5881\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/about.gitlab.com\/solutions\/open-source\/\">GitLab \u0644\u0628\u0631\u0646\u0627\u0645\u062c \u0645\u0641\u062a\u0648\u062d \u0627\u0644\u0645\u0635\u062f\u0631<\/a><\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15e5b2c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"15e5b2c\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c1396d\" data-id=\"5c1396d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a64396c elementor-widget elementor-widget-template\" data-id=\"a64396c\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"footer\" data-elementor-id=\"4404\" class=\"elementor elementor-4404 elementor-1598\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section data-dce-background-color=\"#343A40\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0dae66a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0dae66a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1962917\" data-id=\"1962917\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a14b500 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"a14b500\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/LogoColmena_grayscale.svg\" class=\"attachment-large size-large wp-image-290\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48ea207 elementor-widget elementor-widget-heading\" data-id=\"48ea207\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0641\u062a\u062d \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u062a\u0639\u0627\u0648\u0646\u064a\u0629 \u0644\u0644\u0625\u0646\u0634\u0627\u0621 \u0648\u0627\u0644\u0645\u0634\u0627\u0631\u0643\u0629<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a67f8ae\" data-id=\"a67f8ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96e5bb1 elementor-widget elementor-widget-heading\" data-id=\"96e5bb1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/blog.colmena.media\/ar\/contact\">\u0627\u062a\u0635\u0627\u0644<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bae4bc elementor-widget elementor-widget-text-editor\" data-id=\"6bae4bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"https:\/\/blog.colmena.media\/help\/\">\u0633\u0627\u0639\u062f \u0644\u062f\u0639\u0645<\/a><\/p><p><a href=\"https:\/\/blog.colmena.media\/terms\">\u0627\u0644\u0628\u0646\u0648\u062f \u0648 \u0627\u0644\u0638\u0631\u0648\u0641<\/a><\/p><p><a href=\"https:\/\/git.colmena.network\/maia\/frontend\/-\/blob\/develop\/README.md\">\u0645\u0635\u062f\u0631 \u0627\u0644\u0631\u0645\u0632<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6717e02\" data-id=\"6717e02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f01d32d elementor-widget elementor-widget-heading\" data-id=\"f01d32d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0627\u0634\u062a\u0631\u0643 \u0641\u064a \u0627\u0644\u0646\u0634\u0631\u0629 \u0627\u0644\u0625\u062e\u0628\u0627\u0631\u064a\u0629<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c607eb6 elementor-widget elementor-widget-text-editor\" data-id=\"c607eb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p id=\"newsletter-form\" class=\"wp-block-heading\"><div class=\"tnp tnp-subscription \">\n<form method=\"post\" action=\"https:\/\/blog.colmena.media\/ar\/?na=s\">\n<input type=\"hidden\" name=\"nlang\" value=\"ar\">\n<div class=\"tnp-field tnp-field-firstname\"><label for=\"tnp-1\">First name<\/label>\n<input class=\"tnp-name\" type=\"text\" name=\"nn\" id=\"tnp-1\" value=\"\" placeholder=\"name\"><\/div>\n<div class=\"tnp-field tnp-field-email\"><label for=\"tnp-2\">Email<\/label>\n<input class=\"tnp-email\" type=\"email\" name=\"ne\" id=\"tnp-2\" value=\"\" placeholder=\"email\" required><\/div>\n<div class=\"tnp-field tnp-field-profile\"><label for=\"tnp-3\">Language<\/label>\n<select class=\"tnp-profile tnp-profile-1\" id=\"tnp-profile_1\" name=\"np1\" required><option>English<\/option><option>Espa\u00f1ol<\/option><option>Portugu\u00eas<\/option><option>Fran\u00e7ais<\/option><option>\u0627\u0644\u0639\u0631\u0628\u064a\u0629<\/option><option>Kiswahili<\/option><\/select>\n<\/div>\n<div class=\"tnp-field tnp-field-button\" style=\"text-align: right\"><input class=\"tnp-submit\" type=\"submit\" value=\"Subscribe\" style=\"\">\n<\/div>\n<\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b68c2e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b68c2e1\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-69ccc57\" data-id=\"69ccc57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45e53b7 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"45e53b7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"745\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ELdZ_ml_rgb_arab-1024x745.jpg\" class=\"attachment-large size-large wp-image-4409\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ELdZ_ml_rgb_arab-1024x745.jpg 1024w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ELdZ_ml_rgb_arab-300x218.jpg 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ELdZ_ml_rgb_arab-768x559.jpg 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/ELdZ_ml_rgb_arab.jpg 1039w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7cd1e58\" data-id=\"7cd1e58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7a8f84 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"e7a8f84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"343\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/redes-ac-1024x343.png\" class=\"attachment-large size-large wp-image-3659\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/redes-ac-1024x343.png 1024w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/redes-ac-300x101.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/redes-ac-768x257.png 768w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/redes-ac-1536x515.png 1536w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/redes-ac.png 1584w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fdf6c1f\" data-id=\"fdf6c1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b35de7 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"8b35de7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"211\" src=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/DW-Akademie-logo.png\" class=\"attachment-large size-large wp-image-3665\" alt=\"\" srcset=\"https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/DW-Akademie-logo.png 850w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/DW-Akademie-logo-300x74.png 300w, https:\/\/blog.colmena.media\/wp-content\/uploads\/2022\/04\/DW-Akademie-logo-768x191.png 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7880a89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7880a89\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35f8ba3\" data-id=\"35f8ba3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e952090 elementor-widget elementor-widget-heading\" data-id=\"e952090\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><i>\u0647\u0630\u0627 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u062c\u0632\u0621 \u0645\u0646 \u0645\u0628\u0627\u062f\u0631\u0629 \u0639\u0627\u0644\u0645\u064a\u0629\n\"\u0627\u0644\u0634\u0641\u0627\u0641\u064a\u0629 \u0648\u062d\u0631\u064a\u0629 \u0627\u0644\u0627\u0639\u0644\u0627\u0645 - \u0627\u0644\u0635\u0645\u0648\u062f \u0641\u064a \u0645\u0648\u0627\u062c\u0647\u0629 \u0627\u0644\u0648\u0628\u0627\u0621 \u0627\u0644\u0639\u0627\u0644\u0645\u064a<\/i><\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u062a\u0633\u062c\u064a\u0644 \u062f\u062e\u0648\u0644 Kiswahili English Espa\u00f1ol Portugu\u00eas Fran\u00e7ais \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u062a\u0633\u062c\u064a\u0644 \u062f\u062e\u0648\u0644 Kiswahili English Espa\u00f1ol Portugu\u00eas Fran\u00e7ais \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0643\u0646 \u062c\u0632\u0621\u064b\u0627 \u0645\u0646 \u062e\u0644\u064a\u0629 \u0627\u0644\u0646\u062d\u0644 Colmena \u0647\u0648 \u0635\u0646\u062f\u0648\u0642 \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u0631\u0642\u0645\u064a\u0629 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u0644\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0625\u0639\u0644\u0627\u0645\u064a \u0627\u0644\u0645\u062d\u0644\u064a \u0648\u0627\u0644\u0645\u062c\u062a\u0645\u0639\u064a. \u0625\u0646\u0647 \u062d\u0644 \u0645\u062c\u0627\u0646\u064a \u0648\u0622\u0645\u0646 \u0648\u0645\u0641\u062a\u0648\u062d \u0627\u0644\u0645\u0635\u062f\u0631 \u0628\u0646\u0633\u0628\u0629 100% \u0644\u0628\u064a\u0626\u0627\u062a \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u0645\u062d\u0645\u0648\u0644\u0629 \u0648\u0633\u0637\u062d \u0627\u0644\u0645\u0643\u062a\u0628. \u062a\u062a\u0645 \u0635\u064a\u0627\u0646\u0629 \u0648\u062a\u0637\u0648\u064a\u0631 \u0643\u0648\u0644\u0645\u064a\u0646\u0627 \u0645\u0646 \u0642\u0628\u0644 \u0627\u062a\u062d\u0627\u062f \u063a\u064a\u0631 \u0631\u0628\u062d\u064a \u0645\u0646 &#8230; <a title=\"Home\" class=\"read-more\" href=\"https:\/\/blog.colmena.media\/ar\/\" aria-label=\"\u0627\u0644\u0645\u0632\u064a\u062f Home\">\u0627\u0642\u0631\u0623 \u0627\u0644\u0645\u0632\u064a\u062f<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2409","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/pages\/2409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/comments?post=2409"}],"version-history":[{"count":74,"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/pages\/2409\/revisions"}],"predecessor-version":[{"id":5976,"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/pages\/2409\/revisions\/5976"}],"wp:attachment":[{"href":"https:\/\/blog.colmena.media\/ar\/wp-json\/wp\/v2\/media?parent=2409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}